{"id":91079,"date":"2012-10-16T15:14:03","date_gmt":"2012-10-16T14:14:03","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/16\/10\/2012\/pasti-al-centro-diurno-anche-a-tavola-e-in-cucina-si-fa-riabilitazioneil-progetto-e-ripartito-grazie-alla-collaborazione-tra-asl-comune-pazienti-e-volontari"},"modified":"2012-10-16T15:14:03","modified_gmt":"2012-10-16T14:14:03","slug":"pasti-al-centro-diurno-anche-a-tavola-e-in-cucina-si-fa-riabilitazioneil-progetto-e-ripartito-grazie-alla-collaborazione-tra-asl-comune-pazienti-e-volontari","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2012\/10\/16\/pasti-al-centro-diurno-anche-a-tavola-e-in-cucina-si-fa-riabilitazioneil-progetto-e-ripartito-grazie-alla-collaborazione-tra-asl-comune-pazienti-e-volontari\/","title":{"rendered":"Pasti al Centro diurno: anche a tavola e in cucina si fa riabilitazioneIl progetto \u00e8 ripartito grazie alla collaborazione tra Asl, Comune, pazienti e volontari"},"content":{"rendered":"<p>Con la sinergia tra Azienda Sanitaria, Amministrazione comunale, operatori, volontari, pazienti e familiari e\u2019 ripreso in questi giorni il progetto \u201cPasti al Centro Diurno\u201d. \u201cUn risultato che siamo riusciti ad ottenere solo grazie al contributo e alla collaborazione di tutti i soggetti coinvolti\u201d, spiega Giovanni Antonio Fadda , il manager della Asl di Olbia che si era impegnato in prima persona per garantire ai pazienti l\u2019ampliamento dell\u2019offerta riabilitativa del centro di via Baronia.<\/p>\n<p>Pasta al sugo, riso coi funghi, ma anche Trota al forno, pollo con patate, verdure di ogni tipo: saranno gli stessi ospiti del Centro, giorno per giorno, a preparare il pranzo, allestire le tavolate, servire il cibo. \u201cUn\u2019attivit\u00e0 riabilitativa che vede la partecipazione diretta degli utenti\u201d, spiega Amadeus Ehrhardt, direttore del Servizio di Salute Mentale della Asl di Olbia. \u201cUn percorso in grado di migliorare le capacit\u00e0 cognitive, relazionali e di gestione della vita quotidiana dei nostri ospiti\u201d.&nbsp;<\/p>\n<p>Da ieri nella sala ricreativa del Centro Diurno del Csm di Olbia \u00e8 ripreso il \u201cProgetto pasti al Centro Diurno\u201d: agli ospiti, una ventina in tutto, giornalmente verr\u00e0 dato un compito, e saranno loro, con la collaborazione dei volontari dell\u2019Associazione Insieme oltre il Muro e con il personale della Asl, a preparare il pasto, apparecchiare, pulire i locali.<\/p>\n<p>&nbsp;\u201cIn seguito agli accordi intercossi tra la Asl di Olbia e i volontari, la nostra Amministrazione, nonostante ci troviamo in un periodo di grande crisi economica, ha comunque deciso di destinare una quota dei fondi destinati ai finanziamenti per le associazioni al progetto terapeutico \u201cPasti al centro diurno\u201d\u201d, spiega l\u2019assessore ai servizi sociali del Comune di Olbia, Rino Piccinnu. <\/p>\n<p>In data 20\/07\/2012, la giunta del Comune di Olbia ha approvato la delibera n. 261, \u201cContributi per attivit\u00e0 di interesse sociale a supporto delle funzioni istituzionali dell\u2019Ente. Erogazione a favore dell\u2019Associazione Insieme oltre il muro\u201d<\/p>\n<p>\u201cUn progetto riabilitativo-educativo che punta sullo stare insieme, ma anche il\u201critorno\u201d alla quotidianit\u00e0, come la preparazione dei pasti, o le basi di una corretta educazione alimentare\u201d, ha detto Antonietta Demurtas, presidente dell\u2019Associazione Insieme oltre il Muro. \u201cCome Associazione riconosciamo lo sforzo che l\u2019Azienda Sanitaria e l\u2019Amministrazione comunale hanno fatto per attivare il progetto e siamo molto soddisfatti perch\u00e9 con la sinergia e la partecipazione di tutti abbiamo dimostrato che, insieme, si possono raggiungere importanti risultati, speriamo nel futuro che questa collaborazione ci porti ad ampliare ulteriormente l\u2019offerta riabilitativa del Csm\u201d.<\/p>\n<p>\u201cConsapevoli dell\u2019importanza di alcuni progetti del Centro di Salute Mentale, abbiamo cercato, anche attraverso la compartecipazione dell\u2019Amministrazione comunale di Olbia, di garantire alcun percorsi che, per la loro particolare valenza riabilitativa, meritavano di esser rifinanziati nonostante non potessero pi\u00f9 usufruire di finanziamenti appositi\u201d, spiega dalla Direzione Aziendale della Asl di Olbia. \u201cCon non poche difficolt\u00e0 siamo riusciti a mantenere la parola data e da questa settimana si riparte anche con questa attivit\u00e0\u201d. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la sinergia tra Azienda Sanitaria, Amministrazione comunale, operatori, volontari, pazienti e familiari e\u2019 ripreso in questi giorni il progetto \u201cPasti al Centro Diurno\u201d. \u201cUn&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/91079"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=91079"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/91079\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=91079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=91079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=91079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}