{"id":85008,"date":"2011-10-10T15:13:57","date_gmt":"2011-10-10T14:13:57","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/10\/10\/2011\/fluorite-di-silius---costituito-gruppo-di-lavoro-per-definizione-nuovo-accordo-lavoratori"},"modified":"2011-10-10T15:13:57","modified_gmt":"2011-10-10T14:13:57","slug":"fluorite-di-silius-costituito-gruppo-di-lavoro-per-definizione-nuovo-accordo-lavoratori","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/10\/fluorite-di-silius-costituito-gruppo-di-lavoro-per-definizione-nuovo-accordo-lavoratori\/","title":{"rendered":"Fluorite di Silius &#8211; Costituito gruppo di lavoro per definizione nuovo accordo lavoratori."},"content":{"rendered":"<p>Questa mattina, a Cagliari, presso la sede dell'assessorato all'Industra, l\u2019assessore Alessandra Zedda e l\u2019assessore del Lavoro, Antonello Liori, nel corso dell'incontro volto a discutere le problematiche relative al futuro della Fluorite di Silius S.p.a., hanno assicurato che \u00e8 stato costituito un gruppo di lavoro tra l\u2019Assessorato dell\u2019Industria, quello del Lavoro, i liquidatori della Fluorite di Silius e le rappresentanze sindacali per esaminare le singole posizioni lavorative e procedere alla definizione di un piano di ricollocamento e prepensionamento per i 105 lavoratori della miniera. <\/p>\n<p>\"Il bando pubblico e il piano di reinserimento dei lavoratori sono due strade separate ma parallele che seguiamo con lo stesso impegno - hanno precisato Zedda e Liori - I nostri uffici stanno studiando tutte le soluzioni percorribili per venire incontro alle esigenze dei lavoratori: il ricorso agli ammortizzatori sociali, i corsi di alta formazione ed eventualmente l\u2019impiego in altre amministrazioni.\" <\/p>\n<p>Il gruppo di lavoro si riunir\u00e0 il prossimo 19 ottobre, mentre per il giorno 21 \u00e8 prevista la convocazione del tavolo tra la Regione, l\u2019azienda, le rappresentanze sindacali e le amministrazioni locali. Red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa mattina, a Cagliari, presso la sede dell&#8217;assessorato all&#8217;Industra, l\u2019assessore Alessandra Zedda e l\u2019assessore del Lavoro, Antonello Liori, nel corso dell&#8217;incontro volto a discutere le&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/85008"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=85008"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/85008\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=85008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=85008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=85008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}