{"id":84872,"date":"2011-09-21T15:13:57","date_gmt":"2011-09-21T14:13:57","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/21\/09\/2011\/attentato-incendiario-contro-auto-della-moglie-del-maresciallo-dei-carabinieri-di-sinnai-la-solidarieta-del-presidente-cappellacci"},"modified":"2011-09-21T15:13:57","modified_gmt":"2011-09-21T14:13:57","slug":"attentato-incendiario-contro-auto-della-moglie-del-maresciallo-dei-carabinieri-di-sinnai-la-solidarieta-del-presidente-cappellacci","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/09\/21\/attentato-incendiario-contro-auto-della-moglie-del-maresciallo-dei-carabinieri-di-sinnai-la-solidarieta-del-presidente-cappellacci\/","title":{"rendered":"Attentato incendiario contro auto della moglie del Maresciallo dei carabinieri di Sinnai, la solidariet\u00e0 del presidente Cappellacci"},"content":{"rendered":"<p><SPAN class=apple-style-span><SPAN style=\"FONT-FAMILY: 'Arial', 'sans-serif'; BACKGROUND: white; COLOR: black\">\"Esprimo il mio sentimento di vicinanza e solidariet\u00e0 al maresciallo Locci e alla sua consorte.\" Lo ha dichiarato il prescindente Cappellacci, dopo aver appreso la notizia dell'atto intimidatorio avvenuto a Sinnai la notte scorsa. <\/SPAN><\/SPAN><\/p>\n<p><SPAN class=apple-style-span><SPAN style=\"FONT-FAMILY: 'Arial', 'sans-serif'; BACKGROUND: white; COLOR: black\">\"Quello compiuto la notte scorsa - ha aggiunto il presidente -&nbsp;\u00e8 un atto stupido e vile, che merita il disprezzo di tutta la nostra comunit\u00e0. In momenti come questo - aggiunge Cappellacci - occorre ribadire che la nostra societ\u00e0 sta dalla parte di chi&nbsp;\u00e8 impegnato quotidianamente nel territorio a presidio della legalit\u00e0\"<\/SPAN><\/SPAN><\/SPAN><\/p>\n<p><SPAN class=apple-style-span><SPAN style=\"FONT-FAMILY: 'Arial', 'sans-serif'; BACKGROUND: white; COLOR: black\">&nbsp;<\/SPAN><\/SPAN><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Esprimo il mio sentimento di vicinanza e solidariet\u00e0 al maresciallo Locci e alla sua consorte.&#8221; Lo ha dichiarato il prescindente Cappellacci, dopo aver appreso la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/84872"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=84872"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/84872\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=84872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=84872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=84872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}