{"id":72169,"date":"2011-10-10T00:00:00","date_gmt":"2011-10-09T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/10\/arrestato-giovane-per-detenzione-ai-fini-di-spaccio-di-stupefacenti\/"},"modified":"2011-10-10T00:00:00","modified_gmt":"2011-10-09T22:00:00","slug":"arrestato-giovane-per-detenzione-ai-fini-di-spaccio-di-stupefacenti-3","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/10\/arrestato-giovane-per-detenzione-ai-fini-di-spaccio-di-stupefacenti-3\/","title":{"rendered":"Arrestato giovane per detenzione ai fini di spaccio di stupefacenti."},"content":{"rendered":"<p>Lo scorso 8 ottobre, a Villa San Pietro (Ca), i Carabinieri delle stazioni di Pula e Santa Margherita, in collaborazione con i colleghi del Nucleo Cinofili di Cagliari, hanno arrestato Massimiliano Scano, di 28 anni, del paese, per detenzione ai fini di spaccio di stupefacenti.<\/p>\n<p>Tutto ha avuto inizio quando il ragazzo, a bordo del suo scooter, notati i militari fermi ad un posto di blocco in localit\u00e0 \"Is Fossus\", ignorando l'alt impostogli, ha invertito il senso di marcia dandosi alla fuga a gran velocit\u00e0. Presto raggiunto, per\u00f2, \u00e8 stato perquisito: addosso 16 spinelli di marijuana, per un peso di 13 grammi circa. In casa invece il 28enne nascondeva dell'altra marijuana, semi di canapa indiana, per un totale di 27 grammi, quattro coltelli ed il materiale per il confezionamento.<\/p>\n<p>Il tutto \u00e8 stato sequestrato, mentre il giovane, trattenuto presso le camere di sicurezza della stazione di Cagliari-Villanova, \u00e8 stato giudicato questa mattina con rito direttissimo: il Giudice monocratico, dopo aver convalidato l'arresto, lo ha condannato con patteggiamento ad un anno di reclusione e 3mila euro di multa, pena sospesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo scorso 8 ottobre, a Villa San Pietro (Ca), i Carabinieri delle stazioni di Pula e Santa Margherita, in collaborazione con i colleghi del Nucleo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/72169"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=72169"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/72169\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=72169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=72169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=72169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}