{"id":72154,"date":"2011-10-09T00:00:00","date_gmt":"2011-10-08T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/09\/alfano-accantonare-berlusconi-e-impraticabile\/"},"modified":"2011-10-09T00:00:00","modified_gmt":"2011-10-08T22:00:00","slug":"alfano-accantonare-berlusconi-e-impraticabile","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/09\/alfano-accantonare-berlusconi-e-impraticabile\/","title":{"rendered":"Alfano: &#8220;Accantonare Berlusconi \u00e8 impraticabile&#8221;"},"content":{"rendered":"<p>\"La condizione che ci pongono coloro che ci dicono 'accantonate Berlusconi e siamo pronti',&nbsp;\u00e8 una condizione che ritengo impraticabile e ingiusta\". \"Io lavoro per un percorso di allargamento dell'area moderata - ha affermato Alfano&nbsp;- senza condizioni capestro\".<\/p>\n<p>Se non ci si pu\u00f2 alleare con l'Udc, non vanno meglio le cose con a sinistra, che Alfano quasi irride: \"Il centrosinistra non&nbsp;\u00e8 unito su nulla. Abbiamo perso le ultime amministrative e abbiamo scoperto che in Italia esiste l'unica opposizione che riesce a perdere anche quando perdiamo noi. Sono riusciti a non vincere facendo vincere Di Pietro, De Magistris e Pisapia. I cittadini non vedono una vera alternativa nella sinistra italiana\". E non solo i cittadini, ma secondo Alfano anche il mondo finanziario non darebbe fiducia al centrosinistra: \"Il provincialismo italiano&nbsp;\u00e8 quello di chi pensa che se domani al posto di Berlusconi arriva Bersani a capo del Governo si emoziona Wall Street. Ma perch\u00e9? Perch\u00e9&nbsp;\u00e8 arrivato Bersani? Questo&nbsp;\u00e8 il provincialismo di chi non sa guardare ad un orizzonte pi\u00f9 grande che&nbsp;\u00e8 quello del tempo che stiamo vivendo\".<SPAN class=Apple-converted-space>&nbsp;<\/SPAN><\/p>\n<p><SPAN class=Apple-converted-space><\/SPAN>\"Sono ottimista e non riesco a perdere l'ottimismo di chi pensa che possa vincere le prossime elezioni di fronte a questa sinistra, perche' gli italiani sceglieranno chi ha messo al centro la libert\u00e0\".<\/p>\n<p>\"Noi -ha aggiunto- abbiamo sempre messo al centro della nostra politica i cittadini e non si pu\u00f2 negare quello che&nbsp;\u00e8 sotto gli occhi di tutti\". Di fronte, ha proseguito il segretario del Pdl \"abbiamo una sinistra che non e' stata capace neppure di vincere quando noi abbiamo perso, come alle ultime elezioni amministrative. Le prossime elezioni vedranno noi contro di loro - ha sottolineato - e loro sono Bersani-Di Pietro-Vendola. Questa&nbsp;\u00e8 la alleanza con la quale dovremo confrontarci\".<\/p>\n<p>\"Non intendiamo tornare indietro sul bipolarismo, una condizione di democrazia trasparente in cui chi vince governa e chi perde va all'opposizione\". E sulla legge elettorale bisogna \"restituire ai cittadini il diritto di scelta del parlamentare, ma anche del premier\".<\/p>\n<p>\"Il nostro programma di governo per la prossima legislatura sar\u00e0 tutto coniugato al futuro\".&nbsp; \"Dobbiamo fare uno sforzo - ha detto - per alleggerire lo zaino di piombo che grava sulle spalle dei nostri figli e che e' rappresentato dal nostro debito\". \"Per uscire dalla crisi - ha aggiunto - dobbiamo lavorare sia sul deficit sia sul pil, ma mentre il primo non&nbsp;\u00e8 un problema, il debito lo \u00e8\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La condizione che ci pongono coloro che ci dicono &#8216;accantonate Berlusconi e siamo pronti&#8217;,&nbsp;\u00e8 una condizione che ritengo impraticabile e ingiusta&#8221;. &#8220;Io lavoro per un&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/72154"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=72154"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/72154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=72154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=72154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=72154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}