{"id":72010,"date":"2011-10-10T00:00:00","date_gmt":"2011-10-09T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/10\/nel-fine-settimana-i-carabinieri-di-quartu-santelena-denunciano-sei-persone-per-reati-vari\/"},"modified":"2011-10-10T00:00:00","modified_gmt":"2011-10-09T22:00:00","slug":"nel-fine-settimana-i-carabinieri-di-quartu-santelena-denunciano-sei-persone-per-reati-vari","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/10\/nel-fine-settimana-i-carabinieri-di-quartu-santelena-denunciano-sei-persone-per-reati-vari\/","title":{"rendered":"Nel fine settimana i Carabinieri di Quartu Sant&#8217;Elena denunciano sei persone per reati vari."},"content":{"rendered":"<p>I Carabinieri del Nucleo Operativo e Radiomobile della Compagnia di Quartu Sant'Elena, nel corso del fine settimana, durante un servizio alla circolazione stradale e dei servizi finalizzati alla prevenzione dei reati predatori, hanno denunciato sei persone.<\/p>\n<p>&#12288;<\/p>\n<p>Tra questi due ragazzi di 20 anni sorpresi alla guida delle proprie autovetture in stato di ebbrezza alcolica, con tasso alcolemico tre volte superiore quello consentito dalla legge. Ai due \u00e8 stata ritirata la patente di guida. <\/p>\n<p>Due pregiudicati di 30 anni sono invece stati denunciati per furto e ricettazione di ciclomotore nel litorale. Sono accusati ugualmente di furto e ricettazione, ma di prodotti alimentari, due giovanissimi di 18 anni uno e di 17 l'altro, che avrebbero rubato nei supermercati della citt\u00e0 di Quartu Sant\u2019Elena. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri del Nucleo Operativo e Radiomobile della Compagnia di Quartu Sant&#8217;Elena, nel corso del fine settimana, durante un servizio alla circolazione stradale e dei&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/72010"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=72010"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/72010\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=72010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=72010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=72010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}