{"id":71987,"date":"2011-10-26T00:00:00","date_gmt":"2011-10-25T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/26\/artizzu-fli-nomina-corrado-sanna-coordinatore-di-fli-per-alghero\/"},"modified":"2011-10-26T00:00:00","modified_gmt":"2011-10-25T22:00:00","slug":"artizzu-fli-nomina-corrado-sanna-coordinatore-di-fli-per-alghero","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/26\/artizzu-fli-nomina-corrado-sanna-coordinatore-di-fli-per-alghero\/","title":{"rendered":"Artizzu (Fli) nomina Corrado Sanna Coordinatore di Fli per Alghero."},"content":{"rendered":"<p>Il Coordinatore Regionale Ignazio Artizzu, di concerto con il Coordinatore Provinciale di Sassari, ha nominato l\u2019Ing. Corrado Sanna Coordinatore di Futuro e Libert\u00e0 per la citt\u00e0 di Alghero.<\/p>\n<p>\"La nomina di Corrado Sanna \u2013 ha dichiarato Artizzu \u2013 \u00e8 un passaggio fondamentale per la realizzazione del progetto Terzo Polo ad Alghero, in vista delle imminenti elezioni amministrative per le quali la citt\u00e0 catalana rappresenta uno degli appuntamenti pi\u00f9 importanti in Sardegna\". <\/p>\n<p>\"Ogni iniziativa relativa ad alleanze elettorali \u2013 ha aggiunto il coordinatore finiano - \u00e8 dunque demandata al Coordinatore Cittadino e agli organi statutariamente preposti\". Red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Coordinatore Regionale Ignazio Artizzu, di concerto con il Coordinatore Provinciale di Sassari, ha nominato l\u2019Ing. Corrado Sanna Coordinatore di Futuro e Libert\u00e0 per la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71987"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71987"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71987\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}