{"id":71984,"date":"2011-10-12T00:00:00","date_gmt":"2011-10-11T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/12\/i-lavori-del-consiglio-regionale-prosegue-il-dibattito-sulla-riduzione-dei-consiglieri\/"},"modified":"2011-10-12T00:00:00","modified_gmt":"2011-10-11T22:00:00","slug":"i-lavori-del-consiglio-regionale-prosegue-il-dibattito-sulla-riduzione-dei-consiglieri","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/12\/i-lavori-del-consiglio-regionale-prosegue-il-dibattito-sulla-riduzione-dei-consiglieri\/","title":{"rendered":"I lavori del Consiglio regionale &#8211; Prosegue il dibattito sulla riduzione dei consiglieri."},"content":{"rendered":"<p>Prosegue il dibattito consiliare sul taglio del numero dei consiglieri regionali, avviato questo pomeriggio.<\/p>\n<p>A prendere la parola \u00e8 stato Antonio Solinas (Pd) il quale ha spiegato di ritenerlo opportuno e, in merito alle polemiche nate nel precedente dibattito sull'argomento, ha chiesto che si intervenga sul Regolamento consiliare abolendo il ricorso al voto segreto, ad eccezione delle questioni di tipo personale. <\/p>\n<p>Franco Cuccureddu (Misto) intervenendo sull'ordine dei lavori, ha sollecitato chiarimenti sulle procedure di trasmissione a Roma della proposta di legge di modifica costituzionale gi\u00e0 approvata dall'Assemblea. A tal proposito, la presidente del Consiglio regionale, Claudia Lombardo, ha spiegato che la legge non \u00e8 stata ancora inviata al Parlamento perch\u00e9 non \u00e8 pronta la relazione.<\/p>\n<p>Attilio Dedoni (Riformatori) ha ricordato come si debba essere pi\u00f9 incisivi in difesa degli interessi della Sardegna, a cominciare dalla rivendicazione delle accise sui prodotti petroliferi prodotti in Sardegna, quantificate in sei miliardi annui. Mentre per Radhouan Ben Amara (Misto) sarebbe pi\u00f9 razionale abbattere i costi della politica, intervenendo sulle indennit\u00e0 e sui privilegi, perch\u00e9 ridurre il numero dei consiglieri crea un danno alla democrazia. Red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue il dibattito consiliare sul taglio del numero dei consiglieri regionali, avviato questo pomeriggio. A prendere la parola \u00e8 stato Antonio Solinas (Pd) il quale&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71984"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71984"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71984\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}