{"id":71928,"date":"2011-10-10T00:00:00","date_gmt":"2011-10-09T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/10\/provincia-di-nuoro-allincontro-convocato-durgenza-questa-mattina-la-societa-ildocat-non-si-e-presentata\/"},"modified":"2011-10-10T00:00:00","modified_gmt":"2011-10-09T22:00:00","slug":"provincia-di-nuoro-allincontro-convocato-durgenza-questa-mattina-la-societa-ildocat-non-si-e-presentata","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/10\/provincia-di-nuoro-allincontro-convocato-durgenza-questa-mattina-la-societa-ildocat-non-si-e-presentata\/","title":{"rendered":"Provincia di Nuoro &#8211; All&#8217;incontro convocato d&#8217;urgenza questa mattina la societ\u00e0 Ildocat non si \u00e8 presentata."},"content":{"rendered":"<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; mso-fareast-language: IT; mso-bidi-font-weight: bold\">La Ildocat, societ\u00e0 inserita nel primo Protocollo aggiuntivo del Contratto d'Area di Ottana, questa mattina &nbsp;non si \u00e8 presentata all'incontro convocato d'urgenza presso il Comitato Promotore, per discutere delle gravi problematiche che riguardano la ditta.<\/SPAN><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; mso-fareast-language: IT\"><\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; mso-fareast-language: IT; mso-bidi-font-weight: bold\">L'assenza ingiustificata di&nbsp;<A href=\"javascript:mails_addtocal(1,%22oggi%22);\"><SPAN style=\"COLOR: #ff8000\">oggi<\/SPAN><\/A>&nbsp;e l'intollerabilit\u00e0 dell'attuale situazione di incertezza dei lavoratori, ha indotto il Presidente della Provincia di Nuoro, Roberto Deriu, Responsabile Unico del Contratto d'Area,&nbsp;a sollectare pertanto una nuova convocazione della ditta, questa volta da parte del Ministero dello Sviluppo Economico e della Presidenza del Consiglio dei Ministri, cos\u00ec come era stato deciso nel corso della riunione del Comitato Promotore tenutasi la settimana scorsa nei locali della Provincia di Nuoro.<\/SPAN><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; mso-fareast-language: IT\"><\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; mso-fareast-language: IT; mso-bidi-font-weight: bold\">Da oltre un anno, infatti, la Ildocat, beneficiaria di un'agevolazione di oltre 14 milioni di euro, di cui 8 gi\u00e0 erogati, non paga gli stipendi dei lavoratori, generando tra loro una condizione di assoluta incertezza sulle prospettive aziendali.&nbsp;<\/SPAN><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; mso-fareast-language: IT\"><\/SPAN><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ildocat, societ\u00e0 inserita nel primo Protocollo aggiuntivo del Contratto d&#8217;Area di Ottana, questa mattina &nbsp;non si \u00e8 presentata all&#8217;incontro convocato d&#8217;urgenza presso il Comitato&#8230;<\/p>\n","protected":false},"author":2,"featured_media":10856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71928"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71928"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}