{"id":71922,"date":"2011-10-08T00:00:00","date_gmt":"2011-10-07T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/08\/provincia-di-olbia-tempio-lunedi-la-consegna-dei-lavori-di-ammodernamento-dellistituto-tecnico-panedda\/"},"modified":"2011-10-08T00:00:00","modified_gmt":"2011-10-07T22:00:00","slug":"provincia-di-olbia-tempio-lunedi-la-consegna-dei-lavori-di-ammodernamento-dellistituto-tecnico-panedda","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/08\/provincia-di-olbia-tempio-lunedi-la-consegna-dei-lavori-di-ammodernamento-dellistituto-tecnico-panedda\/","title":{"rendered":"Provincia di Olbia-Tempio &#8211; Luned\u00ec la consegna dei lavori di ammodernamento dell&#8217;Istituto tecnico Panedda."},"content":{"rendered":"<p><FONT face=\"Verdana, sans-serif\"><\/FONT>&nbsp;<\/p>\n<p><FONT face=\"Verdana, sans-serif\">L'impresa che prender\u00e0 possesso del cantiere dovr\u00e0 occuparsi dell'adeguamento dell'impianto antincendio, di quello elettrico e di tutta una serie di adempimenti tecnici necessari per rendere pi\u00f9 efficiente e sicura l'impiantistica del palazzo. L'importo totale del finanziamento erogato dalla Provincia Olbia Tempio \u00e8 pari a circa 403mila euro, la conclusione dei lavori \u00e8 stata indicata nel mese di marzo del 2012.<\/FONT><\/p>\n<p><FONT face=\"Verdana, sans-serif\"><BR>All'appuntamento saranno presenti il presidente della Provincia Olbia Tempio, Fedele Sanciu, e l'Assessore alla Pubblica Istruzione, Giovanni Pileri. Com.<\/FONT><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L&#8217;impresa che prender\u00e0 possesso del cantiere dovr\u00e0 occuparsi dell&#8217;adeguamento dell&#8217;impianto antincendio, di quello elettrico e di tutta una serie di adempimenti tecnici necessari per&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71922"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71922"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71922\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}