{"id":71861,"date":"2011-10-10T00:00:00","date_gmt":"2011-10-09T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/10\/prevenzione-cercasi-volontari-per-lo-sportello-informa-cancro\/"},"modified":"2011-10-10T00:00:00","modified_gmt":"2011-10-09T22:00:00","slug":"prevenzione-cercasi-volontari-per-lo-sportello-informa-cancro","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/10\/prevenzione-cercasi-volontari-per-lo-sportello-informa-cancro\/","title":{"rendered":"Prevenzione, cercasi volontari per lo sportello \u201cInforma cancro\u201d."},"content":{"rendered":"<p><FONT face=Calibri>Il progetto \u201c<I style=\"mso-bidi-font-style: normal\">Informa cancro<\/I>\u201d punta a migliorare la conoscenza e la consapevolezza della dimensione familiare, sociale e sanitaria delle patologie tumorali, per superare l\u2019isolamento e la penalizzazione dei malati oncologici in ambiente sociale e lavorativo. Promosso dall\u2019Azienda ospedaliero-universitaria di Cagliari, in collaborazione con la Federazione delle Associazioni di Volontariato in Oncologia (FAVO), il progetto \u00e8 coordinato dall\u2019oncologa Maria Teresa Ionta e fa capo all\u2019Oncologia Medica dell\u2019ateneo di Cagliari, diretta da Bruno Massidda. \u201c<I style=\"mso-bidi-font-style: normal\">Informa cancro<\/I>\u201d \u00e8 alla seconda edizione, si giova del supporto del<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>servizio civile del ministero dell\u2019Interno e prevede l\u2019assegnazione all\u2019Azienda mista (unica sede nell\u2019isola) di due volontari da utilizzare per lo sportello informativo e di accoglienza.&nbsp;<\/FONT><\/p>\n<p><FONT face=Calibri>&nbsp;Gli interessati, di et\u00e0 compresa tra 18 e 29 anni, possono scaricare il bando dal sito <\/FONT><a href=\"http:\/\/www.aoucagliari.it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><FONT color=#0000ff face=Calibri>www.aoucagliari.it<\/FONT><\/A><FONT face=Calibri>, nella sezione \u201cprimo piano e notizie\u201d. Il bando scade alle 14 di venerd\u00ec 21 Ottobre. Il compito dei volontari del servizio civile sar\u00e0 quello di ascolto e di accoglienza dei malati oncologici e di chi sta loro vicino, fornendo un\u2019informazione che sia il pi\u00f9 possibile mirata e personalizzata sulla malattia, i trattamenti e i loro effetti collaterali. Ma anche, sull\u2019accesso ai benefici previsti dalle leggi in ambito lavorativo, previdenziale e assistenziale.&nbsp;<\/FONT><\/p>\n<p><FONT face=Calibri><SPAN style=\"LINE-HEIGHT: 115%; FONT-SIZE: 14pt\">&nbsp;<\/SPAN>I volontari saranno affiancati da una equipe interdisciplinare composta da oncologi, psicologi e assistenti sociali dell\u2019Aou di Cagliari e offriranno alle persone malate, ai loro familiari e amici l\u2019opportunit\u00e0 di essere ascoltati e di esprimere eventuali bisogni di sostegno e di assistenza.&nbsp;<\/FONT><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Times New Roman', 'serif'; FONT-SIZE: 12pt; mso-bidi-font-family: 'Times New Roman'; mso-bidi-theme-font: minor-bidi\"><\/SPAN>&nbsp;<\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Times New Roman', 'serif'; FONT-SIZE: 12pt; mso-bidi-font-family: 'Times New Roman'; mso-bidi-theme-font: minor-bidi\">Inoltre, l\u2019Azienda ospedaliera-universitaria intende realizzare, un progetto di<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>pi\u00f9 ampio respiro, da affiancare allo sportello <I style=\"mso-bidi-font-style: normal\">\u201cInforma cancro<\/I>\u201d,<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>comprendente un servizio di biblioteca di svago e un punto internet, servizi gratuiti estesi a tutti i pazienti dell\u2019Azienda. Il progetto sar\u00e0 operativo grazie alla fattiva collaborazione delle associazioni di volontariato oncologico Aspao, Asama e Aimac.<\/SPAN><\/p>\n<p><FONT face=Calibri>&nbsp;<\/FONT><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il progetto \u201cInforma cancro\u201d punta a migliorare la conoscenza e la consapevolezza della dimensione familiare, sociale e sanitaria delle patologie tumorali, per superare l\u2019isolamento e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71861"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71861"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71861\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}