{"id":71827,"date":"2011-10-08T00:00:00","date_gmt":"2011-10-07T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/08\/il-made-in-sardinia-a-expo-2012-in-corea-del-sud-ieri-lincontro-tra-il-presidente-deidda-e-lambasciatore-coreano\/"},"modified":"2011-10-08T00:00:00","modified_gmt":"2011-10-07T22:00:00","slug":"il-made-in-sardinia-a-expo-2012-in-corea-del-sud-ieri-lincontro-tra-il-presidente-deidda-e-lambasciatore-coreano","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/08\/il-made-in-sardinia-a-expo-2012-in-corea-del-sud-ieri-lincontro-tra-il-presidente-deidda-e-lambasciatore-coreano\/","title":{"rendered":"Il Made In Sardinia a Expo 2012 in corea del sud: Ieri l\u2019incontro tra il presidente Deidda  e l\u2019ambasciatore coreano"},"content":{"rendered":"<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'\">La Sardegna si proietta verso Expo <st1:metricconverter w:st=\"on\" ProductID=\"2012 IN\">2012 in<\/st1:metricconverter> programma dal 12 maggio al 12 agosto a Yeosu, in Corea del Sud. Ieri il presidente della Camera di Commercio di Cagliari, Giancarlo Deidda, ha ricevuto la visita dell\u2019ambasciatore della Repubblica di Corea in Italia, Kim Young-Seok. Al centro del colloquio soprattutto i settori alimentare e turistico, indicati per rinsaldare i rapporti economici fra le imprese sarde e il Paese asiatico. L\u2019ente camerale cagliaritano, quale responsabile del Centro estero regionale, in collaborazione con <st1:PersonName w:st=\"on\" ProductID=\"la Regione\">la Regione<\/st1:PersonName> individuer\u00e0 le aziende isolane che rappresenteranno il made in Sardinia all\u2019Expo coreano.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'\"><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>\u201c<I style=\"mso-bidi-font-style: normal\">Con l\u2019ambasciatore abbiamo parlato del grande successo che ha il food italiano in Corea<\/I>\u201d, sottolinea Deidda, aggiungendo che \u201c<I style=\"mso-bidi-font-style: normal\">sono gi\u00e0 state individuate alcune linee di produzione, in particolare nel settore vitivinicolo e in quello della produzione delle paste<\/I>\u201d. Durante l\u2019incontro sono stati analizzati anche i flussi turistici. <I>\u201cFra Corea del Sud e Sardegna nel periodo estivo esistono gi\u00e0 delle rotte con destinazione Costa Smeralda\u201d.<\/I> Deidda e Kim Young-Seok hanno parlato anche di scambi commerciali. \u201c<I>In questa prospettiva <\/I>-&nbsp;sottolinea il presidente della Camera di commercio -<I> grande sviluppo di interesse potrebbe avere il porto industriale di Cagliari\u201d. <\/I><\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'\">Negli ultimi anni l'interscambio commerciale tra l'Italia e <st1:PersonName w:st=\"on\" ProductID=\"la Corea\">la Corea<\/st1:PersonName> del Sud \u00e8 aumentato costantemente. Le principali importazioni italiane riguardano gli autoveicoli, mentre l'export dei prodotti della siderurgia e gli apparecchi trasmittenti radiotelevisivi \u00e8 raddoppiato. Per quanto riguarda le nostre esportazioni, attualmente i settori trainanti sono medicinali e preparati farmaceutici, parti e accessori per autoveicoli e motori, indumenti esterni e articoli da viaggio.<I><\/I><\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'\">Sempre ieri, il presidente Deidda ha ricevuto il questore di Cagliari, Luigi Savina. Tema trattato quello della sicurezza. <I>\u201c\u00c8 indispensabile per lo sviluppo turistico del territorio e per la crescita di qualit\u00e0 dei servizi\u201d,<\/I> precisa Deidda. La situazione emersa \u00e8 tranquillizzante anche se la percezione della sicurezza deve ancora crescere. A breve sono previsti degli incontri con tutti i rappresentanti del settore commercio. Com<\/SPAN><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sardegna si proietta verso Expo 2012 in programma dal 12 maggio al 12 agosto a Yeosu, in Corea del Sud. Ieri il presidente della&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71827"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71827"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71827\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}