{"id":71740,"date":"2011-10-10T00:00:00","date_gmt":"2011-10-09T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/10\/10\/arrestato-dagli-agenti-del-commissariato-ps-di-alghero-uruguaiano-per-evasione-e-il-suo-complice-sardo-per-procurata-inosservanza-di-pena\/"},"modified":"2011-10-10T00:00:00","modified_gmt":"2011-10-09T22:00:00","slug":"arrestato-dagli-agenti-del-commissariato-ps-di-alghero-uruguaiano-per-evasione-e-il-suo-complice-sardo-per-procurata-inosservanza-di-pena","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/10\/10\/arrestato-dagli-agenti-del-commissariato-ps-di-alghero-uruguaiano-per-evasione-e-il-suo-complice-sardo-per-procurata-inosservanza-di-pena\/","title":{"rendered":"Arrestato dagli agenti del Commissariato PS di Alghero uruguaiano per evasione e il suo complice sardo per   \u201cprocurata inosservanza di pena\u201d"},"content":{"rendered":"<p><FONT face=Calibri>Nel tardo pomeriggio di luned\u00ec 3 ottobre scorso, un detenuto uruguaiano 30 enne Carbonell Silveira Christian,<\/FONT><SPAN style=\"FONT-FAMILY: 'Comic Sans MS'\"> <\/SPAN><FONT face=Calibri>rinchiuso presso la Casa Circondariale di Alghero, si \u00e8 reso responsabile del reato di evasione. Lo straniero, in carcere per detenzione ai fini di spaccio di circa <st1:metricconverter w:st=\"on\" ProductID=\"3,5 Kg\">3,5 Kg<\/st1:metricconverter> di cocaina, era stato recentemente ammesso al beneficio del lavoro esterno ed il 3 ottobre, non ha fatto rientro nella struttura penitenziaria dopo aver svolto il suo turno lavorativo.<\/FONT><\/p>\n<p><FONT face=Calibri>A seguito dell\u2019immediata segnalazione effettuata dalla Polizia Penitenziaria, la Squadra di Polizia Giudiziaria del Commissariato di Alghero, ha avviato l\u2019attivit\u00e0 investigativa che si dimostrata complessa ed articolata. Si \u00e8 pensato subito che l\u2019uomo dopo la fuga abbia trovato qualcuno che lo ha aiutato e si cerca tra gli ex detenuti nello stesso carcere con l\u2019evaso. Quindi \u00e8 stata avviata subito l\u2019attivit\u00e0 di indagine ed hanno messo in atto il controllo stretto di appostamento e pedinamento.<\/FONT><\/p>\n<p><FONT face=Calibri>Nella serata di sabato scorso, personale del Commissariato di Alghero, ha quindi rintracciato e nuovamente arrestato Carbonell, <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>rintracciato a bordo di un pullman di linea nell\u2019abitato di Oschiri lungo la strada che da Sassari conduce ad Olbia. L\u2019uomo \u00e8 stato trovato in possesso di un falso passaporto italiano che lo ritraeva con generalit\u00e0 diverse.<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN><\/FONT><\/p>\n<p><FONT face=Calibri>Nello stesso mezzo di trasporto pubblico, l\u2019evaso, \u00e8 stato arrestato assieme ad un cittadino algherese, Giancarlo Masala, di 61 anni, di Sassari, con numerosi precedenti penali, scarcerato lo scorso anno dalla medesima struttura carceraria dove era rimasto anche durante la permanenza dell\u2019evaso. L\u2019algherese \u00e8 stato perci\u00f2 ritenuto responsabile del reato di \u201cprocurata inosservanza di pena\u201d, per aver aiutato<\/FONT><SPAN style=\"FONT-FAMILY: 'Comic Sans MS'\"> lo straniero a<\/SPAN><FONT face=Calibri> sottrarsi all\u2019esecuzione della sanzione penale. <\/FONT><\/p>\n<p><FONT face=Calibri>I due in seguito sono stati portati negli uffici del commissariato dove su disposizione del Sost. Procuratore della Repubblica presso il Tribunale di Sassari, <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>Pischedda, gli arrestati sono stati condotti presso la Casa Circondariale di San Sebastiano in attesa dell\u2019udienza di convalida prevista per oggi.<\/FONT><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel tardo pomeriggio di luned\u00ec 3 ottobre scorso, un detenuto uruguaiano 30 enne Carbonell Silveira Christian, rinchiuso presso la Casa Circondariale di Alghero, si \u00e8&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71740"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71740"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71740\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}