{"id":71108,"date":"2011-09-05T00:00:00","date_gmt":"2011-09-04T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/09\/05\/continuita-territoriale-bruno-pd-il-presidente-cappellacci-si-e-svegliato-tardissimo\/"},"modified":"2011-09-05T00:00:00","modified_gmt":"2011-09-04T22:00:00","slug":"continuita-territoriale-bruno-pd-il-presidente-cappellacci-si-e-svegliato-tardissimo","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/09\/05\/continuita-territoriale-bruno-pd-il-presidente-cappellacci-si-e-svegliato-tardissimo\/","title":{"rendered":"Continuit\u00e0 territoriale &#8211; Bruno (Pd): &#8220;Il Presidente Cappellacci si \u00e8 svegliato tardissimo&#8221;."},"content":{"rendered":"<p>Mario Bruno, capogruppo del Pd in Consiglio regionale, in relazione alla questione sulla continuit\u00e0 territoriale, ha dichiarato: \"Il Presidente Cappellacci si \u00e8 svegliato tardissimo. Non basta che ci dica, oggi, che di tariffa unica ne parla da anni. La verit\u00e0 \u00e8 che ne parla soltanto!\".<\/p>\n<\/p>\n<p>\"Lo testimoniano - ha poi aggiutno Bruno - il caos nei cieli sardi e la proroga della proroga del vecchio regime, nonostante proclami, protocolli con il Governo e decreti pubblicati e ritirati. Il Presidente riferisca in Consiglio Regionale sul modello di intervento che presenter\u00e0 nella Conferenza dei Servizi. Temo che anche per le rotte aggiuntive ( oltre Roma e Milano ) si andr\u00e0, per la migliore delle ipotesi, ad una nuova proroga. La Regione \u00e8 in forte ritardo! E\u2019 vero che bisogna recuperare le risorse per le compensazioni, soprattutto dopo lo scippo dei 2 miliardi di euro annui della vertenza entrate da parte del Governo Berlusconi\".<\/p>\n<\/p>\n<p>\"Il Pd - ha concluso il capogruppo del Pd - continua a sostenere una soluzione stabile e strutturale, sostenibile economicamente che garantisca indistintamente condizioni di mobilit\u00e0 eque e che sottragga il servizio allo strapotere dei vettori con attenti meccanismi di vigilanza e controllo da parte della Regione. Non basta affidarsi solo a segnalazioni volontarie di disservizi per quanto opportune, ma mettere a regime un vero a regime un vero e proprio sistema di monitoraggio costante\". Red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mario Bruno, capogruppo del Pd in Consiglio regionale, in relazione alla questione sulla continuit\u00e0 territoriale, ha dichiarato: &#8220;Il Presidente Cappellacci si \u00e8 svegliato tardissimo. Non&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71108"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=71108"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/71108\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=71108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=71108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=71108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}