{"id":70695,"date":"2011-09-01T00:00:00","date_gmt":"2011-08-31T22:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/09\/01\/a-stintino-ricercatori-ed-esperti-da-tutto-il-mondo\/"},"modified":"2011-09-01T00:00:00","modified_gmt":"2011-08-31T22:00:00","slug":"a-stintino-ricercatori-ed-esperti-da-tutto-il-mondo","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/09\/01\/a-stintino-ricercatori-ed-esperti-da-tutto-il-mondo\/","title":{"rendered":"A Stintino ricercatori ed esperti da tutto il mondo"},"content":{"rendered":"<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">Dal 7 al 9 settembre Stintino ospiter\u00e0 per la seconda volta&nbsp;il meeting del comitato di redazione della rivista internazionale&nbsp;on line e open access \"Journal of&nbsp;Infection of developing countries\" (<a href=\"http:\/\/www.jidc.org%29.\/\" target=\"_blank\" rel=\"noopener noreferrer\"><FONT color=#0000ff>http:\/\/www.jidc.org).<\/FONT><\/A><\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">La riunione del comitato scientifico, che&nbsp;si terr\u00e0 nella sala consiliare al primo piano della Casa comunale, in via Torre Falcone, ha il patrocinio del Comune.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">Il&nbsp; giornale, al suo quarto anno di attivit\u00e0, \u00e8 nato per iniziativa di ricercatori ed esperti sia di Paesi in via di sviluppo che di altri&nbsp;impegnati negli interventi di Cooperazione Internazionale. E' diretto dal Salvatore Rubino, docente ordinario di Microbiologia&nbsp;all\u2019Universit\u00e0 di Sassari, e ha lo scopo di sviluppare competenze e infrastrutture in grado di far crescere tecnicamente e scientificamente i ricercatori dei Paesi in via di sviluppo e di elevare, nel contempo, la loro capacit\u00e0 di conoscere e affrontare in modo efficace i problemi sanitari legati alle malattie trasmissibili.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">&nbsp;<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">L\u2019 interdisciplinarit\u00e0 \u00e8 il carattere distintivo del Jidc che sostiene la collaborazione tra ricercatori di vari ambiti: sanit\u00e0 animale, umana, ambientale, alimentare, per contribuire alla soluzione dei tanti problemi medico-sanitari creati dalle malattie trasmissibili che attentano alla salute e alla vita delle popolazioni dei Paesi in via di sviluppo. Ma, capaci, nell\u2019era della globalizzazione, di mettere a rischio la salute globale.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">&nbsp;<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">Alla riunione di Stintino parteciperanno delegati provenienti dalla Turchia, Cina, Bosnia-Erzegovina, Grecia, Canada, Gran Bretagna, Spagna, Svizzera.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">&nbsp;<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">La sede redazionale \u00e8 localizzata in Sardegna,&nbsp;all\u2019Universit\u00e0 di Sassari e ha una sede stagionale a Stintino, oltre che sedi regionalei a Valladolid (Spagna), Toronto (Canada), Shantou (Cina), Istanbul (Turchia). Londra (Gran Bretagna).<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">&nbsp;<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">Nello scenario internazionale il Mediterraneo \u00e8 divenuto l\u2019area di contatto e di convergenza tra l\u2019Europa nel suo complesso, il Medio Oriente e l\u2019Africa, un\u2019area privilegiata e preferenziale per i rapporti di cooperazione scientifica internazionale.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">&nbsp;<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">In questo contesto la Sardegna, grazie alla sua collocazione geografica posta proprio al centro del Mediterraneo occidentale e alla sua equidistanza tra Europa e Maghreb ha le potenzialit\u00e0 per diventare un importantissimo interlocutore, la cerniera di raccordo, il fulcro di una serie di scambi tra i paesi industrializzati del Nord Europa e i paesi del cosiddetto terzo mondo, soprattutto quelli emergenti del Nord Africa, che attualmente stanno attraversando una crisi politica.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">&nbsp;<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; BACKGROUND: white; FONT-SIZE: 11pt\">La Sardegna e Stintino in particolare, si candida a&nbsp;diventare la sede ideale di importanti iniziative di rilievo internazionale, soprattutto in quei settori che pi\u00f9 accomunano i paesi del Mediterraneo dal punto di vista delle discipline emergenti della scienza (biomedicina, biotecnologie, ambiente) e della tecnologia (soprattutto informatica), e che possono contribuire in larga misura al progresso non solo della nostra isola, ma anche dei Paesi in via di sviluppo che si affacciano nel Mediterraneo (Nord Africa e Medio Oriente). Com<\/SPAN><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 7 al 9 settembre Stintino ospiter\u00e0 per la seconda volta&nbsp;il meeting del comitato di redazione della rivista internazionale&nbsp;on line e open access &#8220;Journal of&nbsp;Infection&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/70695"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=70695"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/70695\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=70695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=70695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=70695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}