{"id":65738,"date":"2011-03-18T00:00:00","date_gmt":"2011-03-17T23:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/03\/18\/esplosioni-a-bengasi-gheddafi-non-avremo-pieta\/"},"modified":"2011-03-18T00:00:00","modified_gmt":"2011-03-17T23:00:00","slug":"esplosioni-a-bengasi-gheddafi-non-avremo-pieta","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/03\/18\/esplosioni-a-bengasi-gheddafi-non-avremo-pieta\/","title":{"rendered":"Esplosioni a Bengasi, Gheddafi: &#8220;Non avremo piet\u00e0&#8221;"},"content":{"rendered":"<p><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">Durante la notte forti esplosioni sono state udite nella citt\u00e0 libica di Bangasi, seguiti dai tiri della contraerea.<\/SPAN><\/B><SPAN class=apple-converted-space><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/B><\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">Le esplosioni a Bengasi, hanno constatato fonti giornalistiche sul posto, sono state tre, poco dopo la mezzanotte locale (le 23 italiane). La loro causa, dicono le fonti, non sono ancora note. I tiri della contraerea dei ribelli sono partiti dallo stesso settore della citta, sulla quale Muammar Gheddafi ha annunciato un'imminente offensiva per questa notte.<\/SPAN><SPAN class=apple-converted-space><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">In un messaggio alla tv, il rais infatti ha minacciato: \"Bengasi, arriviamo questa sera e non avremo piet\u00e0\".<\/SPAN><SPAN class=apple-converted-space><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">Rivolgendosi direttamente agli abitanti della roccaforte della 'Rivoluzione del 17 febbraio' (che oggi ha celebrato in sordina la ricorrenza di un mese), il colonnello ha assicurato che \"le persone disarmate non hanno niente da temere ma ogni casa sar\u00e0 perquisita\", chiedendo ai suoi di non inseguire i ribelli che depongono le armi e fuggono.<\/SPAN><SPAN class=apple-converted-space><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">Gi\u00e0 stamattina la tv di Stato libica aveva annunciato che le forze 'lealiste' erano alle porte di Bengasi. Notizia smentita dal Consiglio transitorio libico, l'organo politico dei ribelli, nell'ormai consueta altalena di annunci e repliche. E' stato cos\u00ec una settimana fa per Ras Lanuf, poi Brega e Ajdabyia, lo \u00e8 ancora a Misurata, ultima roccaforte degli insorti nell'ovest della Libia, dove anche oggi ci sono stati scontri. E ora tocca a Bengasi, dove a mettere un punto fermo sono stati gli Stati Uniti: \"Le truppe di Gheddafi sono a 160 km dalla citt\u00e0 \", ha detto il sottosegretario di Stato William Burns.<\/SPAN><SPAN class=apple-converted-space><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">La notte scorsa i raid aerei dell'aviazione libica si sono avvicinati molto e sono stati uditi chiaramente dal centro della citt\u00e0, cos\u00ec come i colpi della contraerea rivoluzionaria. L'obiettivo era l'aeroporto di Benina, a soli 14 chilometri da Bengasi, che - secondo fonti dell'esercito rivoluzionario - non avrebbe subito gravi danni, mentre sarebbero stati abbattuti due aerei del regime. Ancora attacchi delle forze governative anche su Ajdabyia dove, secondo una fonte locale, i colpi delle mitragliatrici aeree sono caduti sulla strada per Bengasi e vicino ad alcune case abitate. I ribelli hanno riferito di 30 morti nell'ospedale della citt\u00e0.<\/SPAN><SPAN class=apple-converted-space><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">L'esercito libico ha offerto oggi una tregua ai ribelli, annunciando la sospensione delle operazioni militari a partire da domenica prossima per consentire ai \"terroristi\" di deporre le armi e di beneficiare della grazia. Un'offerta arrivata prima delle ultime minacce di Gheddafi.<\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">Il Consiglio di Sicurezza dell'Onu ha approvato la risoluzione con la quale si autorizza la fascia area di non sorvolo. Il s\u00ec \u00e8 arrivato con 10 voti a favore e 5 astenuti (Russia, Cina, Brasile, India e Germania). La Francia decisa a lanciare raid mirati contro le posizione dell'esercito di Gheddafi anche stanotte stessa.<\/SPAN><SPAN class=apple-converted-space><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; COLOR: black; FONT-SIZE: 12pt; mso-bidi-font-family: Arial\">&nbsp;<\/SPAN><\/SPAN><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\"><BR>\"Ogni ora \u00e8 preziosa per salvare i civili in Libia\", ha detto il ministro degli esteri francese, Alain Juppe.<\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">La Lega Araba ha ribadito che alcuni Paesi arabi parteciperanno militarmente per imporre una no fly zone sulla Libia.<\/SPAN><\/p>\n<p><SPAN style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Verdana', 'sans-serif'; FONT-SIZE: 12pt\">La minaccia di un intervento militare straniero ha fatto alzare il tono delle minacce del regime di Gheddafi contro l'Occidente: in caso di attacco la Libia potrebbe mettere a rischio il traffico aereo e marittimo nel Mediterraneo, ha fatto sapere il suo ministro della Difesa.<\/SPAN><\/p>\n<p><\/SPAN><\/FONT><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la notte forti esplosioni sono state udite nella citt\u00e0 libica di Bangasi, seguiti dai tiri della contraerea.&nbsp; Le esplosioni a Bengasi, hanno constatato fonti&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/65738"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=65738"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/65738\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=65738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=65738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=65738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}