{"id":65570,"date":"2011-03-19T00:00:00","date_gmt":"2011-03-18T23:00:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/2011\/03\/19\/calcio-anticipo-di-serie-a-30ma-giornata\/"},"modified":"2011-03-19T00:00:00","modified_gmt":"2011-03-18T23:00:00","slug":"calcio-anticipo-di-serie-a-30ma-giornata","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2011\/03\/19\/calcio-anticipo-di-serie-a-30ma-giornata\/","title":{"rendered":"Calcio \u2013 Anticipo di serie A, 30ma giornata"},"content":{"rendered":"<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; mso-ansi-language: IT\">Lazio (54) \u2013 Cesena (29) 1 \u2013 0 - Grazie ad un gol dopo 89 secondi di gioco di Mauro Zarate la Lazio trova la vittoria e si rilancia in campionato dopo la sconfitta nel derby di domenica scorsa contro la Roma.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; mso-ansi-language: IT\">La squadra di Reja controlla bene nel primo tempo e la gara va avanti a ritmi molto bassi. Nella ripresa il Cesena prova a cercare il pari ma sono i padroni di casa a sfiorare pi\u00f9 volte il raddoppio, giocando in contropiede.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; mso-ansi-language: IT\">Lo stesso Zarate in alcune occasioni si divora il gol della sicurezza e cos\u00ec la partita rimane in bilico fino al fischio finale. Lazio torna quarta in classifica. Ruggero R.<\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Verdana', 'sans-serif'; mso-ansi-language: IT\"><\/SPAN>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lazio (54) \u2013 Cesena (29) 1 \u2013 0 &#8211; Grazie ad un gol dopo 89 secondi di gioco di Mauro Zarate la Lazio trova la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":8828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/65570"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=65570"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/65570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=65570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=65570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=65570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}