{"id":275684,"date":"2026-09-02T05:47:20","date_gmt":"2026-09-02T03:47:20","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=275684"},"modified":"2026-09-02T05:47:23","modified_gmt":"2026-09-02T03:47:23","slug":"nuovi-attacchi-usa-sulliran-teheran-bersaglia-le-basi-americane-il-petrolio-balza-a-95-dollari","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/09\/02\/nuovi-attacchi-usa-sulliran-teheran-bersaglia-le-basi-americane-il-petrolio-balza-a-95-dollari\/","title":{"rendered":"Nuovi attacchi Usa sull&#8217;Iran, Teheran bersaglia le basi americane. Il petrolio balza a 95 dollari."},"content":{"rendered":"\n<p>Teheran, 2 Sett 2026 - \"Stiamo colpendo obiettivi iraniani vicino allo Stretto di Hormuz\" e \"se l'Iran dovesse reagire a questo attacco pi\u00f9 che giustificato, subirebbe una nuova offensiva di ben altra portata e intensit\u00e0\". Lo ha detto Donald Trump sul suo social Truth, sottolineando che il nuovo raid che potrebbe scattare se Teheran rispondesse non sarebbe comunque \"l'attacco decisivo: quello \u00e8 gi\u00e0 pronto e, una volta concluso, dell'Iran rimarrebbe ben poco\".\u00a0<\/p>\n\n\n\n<p>Trump ha definito gli attacchi in corso nei confronti di obiettivi iraniani vicino allo Stretto di Hormuz \"massicci e potenti\" e ha spiegato che sono \"in risposta al fallito tentativo iraniano di piazzare mine navali nello Stretto, attualmente privo di mine (sono state tutte rimosse o fatte brillare), e al lancio di otto missili (tutti abbattuti con successo) contro la nostra base militare in Giordania\", ha scritto Trump. \"Se l'Iran, Paese ormai fallito, dovesse reagire a questo attacco pi\u00f9 che giustificato, subirebbe una nuova offensiva di ben altra portata e intensit\u00e0. Tuttavia, non si tratterebbe dell'attacco decisivo: quello \u00e8 gi\u00e0 pronto a scattare e, una volta concluso, dell'Iran resterebbe ben poco\", ha messo in evidenza.<\/p>\n\n\n\n<p>Gli Stati Uniti hanno completato una serie di raid contro obiettivi militari iraniani, ha riferito in un comunicato il comando centrale Usa (Centcom), spiegando che sono stati presi di mira sistemi radar, installazioni di difesa aerea, asset marittimi e centri di comunicazione.<\/p>\n\n\n\n<p>L\u2019attacco missilistico iraniano contro una caserma militare statunitense presso Camp Titin, in Giordania, non ha causato feriti n\u00e9 danni ingenti. Lo ha dichiarato una fonte statunitense ad Al Jazeera, spiegando che le forze Usa hanno intercettato l\u2019attacco e che la risposta di Teheran all\u2019ultimo ciclo di raid statunitensi \u00e8 stata \"inefficace\".&nbsp;<\/p>\n\n\n\n<p>Il Corpo delle Guardie della Rivoluzione Islamica iraniana ha rivendicato l'attacco con missili balistici contro la base sostenendo di aver ucciso numerosi militari statunitensi e di aver distrutto \"diverse installazioni ed elicotteri d'attacco nemici\" presenti nella base.<\/p>\n\n\n\n<p>Un funzionario iraniano ha dichiarato in serata che due persone sono rimaste uccise e diverse altre ferite in un attacco statunitense mentre partecipavano a un matrimonio nel sud del Paese. \"Un'abitazione \u00e8 stata colpita mentre era in corso una cerimonia nuziale\", ha riferito alla televisione di Stato Ahmad Nafisi, vicegovernatore della provincia di Hormozgan, aggiungendo che \"due persone sono morte e altre sono rimaste ferite\".<\/p>\n\n\n\n<p>Le forze armate giordane affermano che 13 missili balistici lanciati dal territorio iraniano sono entrati nello spazio aereo del regno, mentre i sistemi di difesa aerea ne hanno intercettati e distrutti 10. \"I restanti tre missili sono caduti in aree remote, lontano dai centri abitati\", ha dichiarato il portavoce delle Forze armate giordane in un comunicato citato da Al Jazeera.&nbsp;<\/p>\n\n\n\n<p>\"Non sono stati registrati feriti n\u00e9 vittime\", ha aggiunto, precisando che squadre specializzate sono state inviate per mettere in sicurezza i luoghi dell'impatto e occuparsi dei detriti.<\/p>\n\n\n\n<p>L'Iran ha attaccato una base americana in Bahrein prendendo di mira impianti radar: lo ha reso noto l'esercito iraniano. \"L'esercito iraniano ha condotto un massiccio attacco con droni contro impianti radar e centri di addestramento delle truppe statunitensi presso la base aerea Sheikh Isa, in Bahrein\", ha riferito l'agenzia di stampa Fars citando l'esercito.&nbsp;<\/p>\n\n\n\n<p>Gli allarmi aerei sono risuonati nella notte in Bahrein, confermano fonti giornalistiche dal piccolo regno insulare del Golfo Persico. Il ministero dell'Interno ha invitato la popolazione alla calma e a raggiungere rifugi e altri luoghi sicuri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teheran, 2 Sett 2026 &#8211; &#8220;Stiamo colpendo obiettivi iraniani vicino allo Stretto di Hormuz&#8221; e &#8220;se l&#8217;Iran dovesse reagire a questo attacco pi\u00f9 che giustificato,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":275685,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/275684"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=275684"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/275684\/revisions"}],"predecessor-version":[{"id":275686,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/275684\/revisions\/275686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/275685"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=275684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=275684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=275684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}