{"id":274550,"date":"2026-07-15T18:40:45","date_gmt":"2026-07-15T16:40:45","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=274550"},"modified":"2026-07-15T18:40:47","modified_gmt":"2026-07-15T16:40:47","slug":"chimica-verde-dichiarazione-dellon-silvio-lai-pd-interrogazione-al-governo-dopo-quanto-accaduto-oggi-a-porto-torres","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/07\/15\/chimica-verde-dichiarazione-dellon-silvio-lai-pd-interrogazione-al-governo-dopo-quanto-accaduto-oggi-a-porto-torres\/","title":{"rendered":"Chimica Verde, dichiarazione dell\u2019on. Silvio Lai (Pd): interrogazione al governo dopo quanto accaduto oggi a Porto Torres."},"content":{"rendered":"\n<p>Roma, 15 Lug 2026 - \u00abOggi, nello stabilimento Eni di Porto Torres, ai lavoratori delle imprese in appalto \u00e8 stato impedito l\u2019accesso alla sala aziendale nella quale era stata convocata un\u2019assemblea sindacale promossa dalla Cgil sulla vertenza della chimica verde. Per questo motivo l\u2019assemblea, alla quale hanno partecipato il sindaco di Sassari Giuseppe Mascia e il sindaco di Porto Torres Massimo Mulas, il segretario nazionale Cgil Gino Giove, il segretario regionale Fausto Durante e il segretario territoriale Massimiliano Muretti, si \u00e8 svolta all\u2019esterno, sotto il sole cocente, con evidenti disagi e pericoli per lavoratrici e lavoratori.\u00bb Lo dichiara Silvio Lai, deputato del Partito Democratico e segretario regionale del PD Sardegna.<br>\u00abQuanto accaduto \u00e8 un fatto molto grave e pone un serio problema di rispetto delle garanzie previste dallo Statuto dei lavoratori a tutela dell\u2019attivit\u00e0 sindacale e del diritto di assemblea. Se un\u2019azienda decide di impedire ai lavoratori delle imprese in appalto di partecipare a un\u2019assemblea sindacale negli stessi spazi concessi ai dipendenti diretti, introduce una distinzione inaccettabile tra lavoratori di serie A e lavoratori di serie B. Ancora pi\u00f9 grave \u00e8 che questa decisione abbia costretto decine di persone a riunirsi all\u2019aperto, sotto il sole cocente di queste giornate, con evidenti disagi e con un\u2019esposizione evitabile a condizioni che possono comportare rischi anche per la salute. I lavoratori delle imprese in appalto sono parte integrante del sistema produttivo di Porto Torres: svolgono attivit\u00e0 essenziali per il funzionamento degli impianti, condividono responsabilit\u00e0, competenze e rischi con i dipendenti diretti e contribuiscono ogni giorno alla sicurezza e alla continuit\u00e0 produttiva del sito. Non possono essere trattati come lavoratori di seconda categoria quando si tratta dell\u2019esercizio di un diritto fondamentale come quello di assemblea e di partecipazione sindacale\u00bb.<br>\u00abParliamo di uno dei principali poli industriali della Sardegna, nel quale si sta discutendo il futuro della chimica verde e il destino di centinaia di posti di lavoro. In una fase tanto delicata ci si aspetterebbe un clima di dialogo, di confronto e di rispetto delle relazioni industriali, non comportamenti che rischiano di compromettere il rapporto di fiducia tra azienda, lavoratori e territorio. Una societ\u00e0 a controllo pubblico come ENI deve rappresentare un modello nelle relazioni industriali e nella tutela dei diritti dei lavoratori, non un esempio contrario. Per queste ragioni presenter\u00f2 un\u2019interrogazione ai Ministri del Lavoro Calderone e delle Imprese Urso affinch\u00e9 chiariscano quanto accaduto, chi abbia assunto questa decisione, se essa sia conforme alla normativa che tutela il diritto di assemblea e alle corrette relazioni industriali e se ritengano compatibile, per una societ\u00e0 a controllo pubblico come Eni, impedire ai lavoratori delle imprese in appalto di partecipare, nelle stesse condizioni degli altri dipendenti, a un\u2019assemblea sindacale regolarmente convocata\u00bb. Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 15 Lug 2026 &#8211; \u00abOggi, nello stabilimento Eni di Porto Torres, ai lavoratori delle imprese in appalto \u00e8 stato impedito l\u2019accesso alla sala aziendale&#8230;<\/p>\n","protected":false},"author":2,"featured_media":241381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274550"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=274550"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274550\/revisions"}],"predecessor-version":[{"id":274551,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274550\/revisions\/274551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/241381"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=274550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=274550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=274550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}