{"id":274529,"date":"2026-07-15T14:42:13","date_gmt":"2026-07-15T12:42:13","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=274529"},"modified":"2026-07-15T14:42:14","modified_gmt":"2026-07-15T12:42:14","slug":"le-delibere-adottate-oggi-15-luglio-26-dalla-giunta-regionale-della-sardegna","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/07\/15\/le-delibere-adottate-oggi-15-luglio-26-dalla-giunta-regionale-della-sardegna\/","title":{"rendered":"Le delibere adottate oggi 15 luglio \u201926 dalla Giunta regionale della Sardegna."},"content":{"rendered":"\n<p>Cagliari, 15 Lug 2026 - Di seguito le principali delibere adottate dalla Giunta Todde nella riunione odierna.\u00a0<\/p>\n\n\n\n<p>Agricoltura - Su proposta dell\u2019assessore dell\u2019Agricoltura, Francesco Agus, la Giunta ha approvato il Programma Operativo Regionale di attuazione del \u201cPiano generale per l\u2019attivit\u00e0 di vigilanza sull\u2019emissione deliberata nell\u2019ambiente di Organismi Geneticamente Modificati\u201d per l\u2019anno 2026, predisposto dall\u2019Assessorato dell\u2019Agricoltura in collaborazione con l\u2019Agenzia Agris.&nbsp;<\/p>\n\n\n\n<p>Turismo - La Giunta regionale, su proposta dell\u2019assessore del Turismo, Artigianato e Commercio, Franco Cuccureddu, ha approvato la concessione del contributo per la riqualificazione di un\u2019ala del monastero finalizzata alla realizzazione di nuove stanze per l\u2019accoglienza di pellegrini e ha individuato quale beneficiario il \u201cMonastero Benedettino di San Pietro di Sorres\u201d. Il contributo \u00e8 concesso fino a un massimo di 300 mila euro.&nbsp;<\/p>\n\n\n\n<p>Sanit\u00e0 - La Regione ha aggiornato le regole per l\u2019assegnazione dei contributi agli enti che accompagnano le famiglie nei percorsi di adozione internazionale. Le nuove linee guida renderanno pi\u00f9 chiari e uniformi requisiti, spese ammissibili, rendicontazione e controlli. Per il triennio 2026-2028 sono disponibili 210 mila euro all\u2019anno.&nbsp;<\/p>\n\n\n\n<p>La Giunta ha aggiornato il Piano operativo degli investimenti Pnrr per la sanit\u00e0, rimodulando le risorse tra gli interventi senza modificare il quadro finanziario complessivo. L\u2019aggiornamento riguarda in particolare Case della Comunit\u00e0, Ospedali di Comunit\u00e0 e grandi apparecchiature sanitarie. Il nuovo Piano sar\u00e0 trasmesso al Ministero della Salute.&nbsp;<\/p>\n\n\n\n<p>Trasporti - Su proposta dell\u2019assessora regionale dei Trasporti, Barbara Manca, la Giunta ha approvato l\u2019aggiornamento dei criteri per gli aiuti sociali destinati al trasporto aereo dei residenti in Sardegna.&nbsp;<\/p>\n\n\n\n<p>Ambiente - La Giunta regionale ha approvato lo schema di Protocollo di intesa tra la Regione Autonoma della Sardegna e il Comando Generale del Corpo delle Capitanerie di Porto \u2013 Guardia Costiera. Il Protocollo rappresenta lo strumento di cooperazione istituzionale finalizzato a rafforzare le attivit\u00e0 di tutela ambientale e demaniale marittima, sicurezza della navigazione e delle attivit\u00e0 costiere, monitoraggio del territorio marino-costiero, valorizzazione delle risorse del mare e sviluppo sostenibile delle comunit\u00e0 costiere della Sardegna. L\u2019attuazione del Protocollo, che ha durata triennale dalla data della sottoscrizione, avverr\u00e0 attraverso la predisposizione di uno specifico documento operativo concordato tra le parti, elaborato con il coinvolgimento delle Direzioni marittime territorialmente competenti di Cagliari e Olbia e delle rispettive articolazioni territoriali.&nbsp;<\/p>\n\n\n\n<p>L\u2019Esecutivo, su proposta dell\u2019assessora della Difesa dell\u2019Ambiente, Rosanna Laconi, delegata dalla Presidente in materia di protezione civile, ha approvato l\u2019integrazione del \u201cPiano regionale di previsione, prevenzione e lotta attiva contro gli incendi boschivi 2026-2028\u201d, approvato con la deliberazione della Giunta regionale n. 28\/56 del 4 giugno 2026, con la \u201cpianificazione ripartimentale\u201d, i \u201cPiani speditivi AIB dei Parchi regionali\u201d e i \u201cPiani speditivi AIB dei Sistemi forestali litoranei\u201d. Inoltre, sono state integrate le \u201cPrescrizioni regionali antincendio\u201d con le \u201czone di previsione di pericolo incendi\u201d. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 15 Lug 2026 &#8211; Di seguito le principali delibere adottate dalla Giunta Todde nella riunione odierna.\u00a0 Agricoltura &#8211; Su proposta dell\u2019assessore dell\u2019Agricoltura, Francesco Agus,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":265880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274529"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=274529"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274529\/revisions"}],"predecessor-version":[{"id":274530,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274529\/revisions\/274530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/265880"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=274529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=274529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=274529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}