{"id":274520,"date":"2026-07-15T14:33:18","date_gmt":"2026-07-15T12:33:18","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=274520"},"modified":"2026-07-15T14:33:21","modified_gmt":"2026-07-15T12:33:21","slug":"football-americano-i-crusaders-campioni-ditalia-ricevuti-dal-presidente-comandini","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/07\/15\/football-americano-i-crusaders-campioni-ditalia-ricevuti-dal-presidente-comandini\/","title":{"rendered":"Football americano. I Crusaders, campioni d\u2019Italia ricevuti dal Presidente Comandini."},"content":{"rendered":"\n<p>\u00a0Cagliari, 15 luglio 2026 \u2013 \u201cSacrificio, devozione, passione ma soprattutto rispetto dell\u2019avversario. I Crusaders Cagliari, squadra campione d\u2019Italia di Football americano sono un orgoglio per la Sardegna e rappresentano un esempio per tutti di perseveranza e di abnegazione sportiva\u201d.<\/p>\n\n\n\n<p>Lo ha affermato il Presidente del Consiglio regionale Piero Comandini che, questa mattina, ha ricevuto in Presidenza, i dirigenti e gli atleti della societ\u00e0 cagliaritana.<\/p>\n\n\n\n<p>\u201cQuesta coppa, vinta qualche settimana fa a Ferrara, dopo sedici anni riporta la Sardegna sul podio pi\u00f9 alto in Italia del Football americano. Vi siamo grati \u2013 ha detto Comandini - per gli enormi sacrifici che fate. Sappiamo bene quanto sia difficile per gli atleti sardi riuscire ad emergere in qualunque disciplina sportiva. Ma la qualit\u00e0, la professionalit\u00e0 e la caparbiet\u00e0 dei nostri atleti e dei dirigenti delle societ\u00e0 isolane fanno superare gli ostacoli e in ogni disciplina riusciamo a raggiungere ottimi livelli\u201d.<\/p>\n\n\n\n<p>Lo stesso nome scelto dalla societ\u00e0 \u201cCrusaders\u201d letteralmente \u201cI crociati\u201d \u2013 \u00e8 stato detto stamattina dai dirigenti della squadra \u2013 rappresenta bene il percorso, le difficolt\u00e0, i sacrifici affrontati dal 1990 da questa squadra ora campione d\u2019Italia. Una strada che in futuro sar\u00e0 ancora pi\u00f9 tortuosa perch\u00e9 i Crusaders hanno obiettivi ambiziosi e gi\u00e0 si organizzano per il prossimo anno con l\u2019iscrizione alla Seconda divisione di football a 11.<\/p>\n\n\n\n<p>Erano presenti all\u2019incontro il Presidente della squadra Emanuele Garzia, il vicepresidente Sergio Andrea Meloni, il general manager Giuseppe Marongiu, la dirigente Giulia Congia, il dirigente e coach Antonio Nicolli, il coach Andrea Antonino e gli atleti Edoardo Stara, Gianfranco Farris, Davide Anedda, Fabio Matta, Riccardo Pili, Massimiliano Mandas, Michele Meloni, Mike Scano.<\/p>\n\n\n\n<p>Il Presidente Comandini ha consegnato agli atleti e ai dirigenti la bandiera dei Quattro Mori. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Cagliari, 15 luglio 2026 \u2013 \u201cSacrificio, devozione, passione ma soprattutto rispetto dell\u2019avversario. I Crusaders Cagliari, squadra campione d\u2019Italia di Football americano sono un orgoglio per&#8230;<\/p>\n","protected":false},"author":2,"featured_media":274521,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274520"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=274520"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274520\/revisions"}],"predecessor-version":[{"id":274522,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274520\/revisions\/274522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/274521"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=274520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=274520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=274520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}