{"id":274516,"date":"2026-07-15T14:26:16","date_gmt":"2026-07-15T12:26:16","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=274516"},"modified":"2026-07-15T14:26:17","modified_gmt":"2026-07-15T12:26:17","slug":"arrestato-dai-carabinieri-della-stazione-di-monserrato-un-27enne-in-esecuzione-di-un-ordine-di-carcerazione-il-giovane-deve-scontare-una-pena-definitiva-di-sei-anni-di-carcere","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/07\/15\/arrestato-dai-carabinieri-della-stazione-di-monserrato-un-27enne-in-esecuzione-di-un-ordine-di-carcerazione-il-giovane-deve-scontare-una-pena-definitiva-di-sei-anni-di-carcere\/","title":{"rendered":"Arrestato dai Carabinieri della Stazione di Monserrato un 27enne in esecuzione di un ordine di carcerazione. Il giovane deve scontare una pena definitiva di sei anni di carcere."},"content":{"rendered":"\n<p>Monserrato (CA). 15 Lug 2026 \u2013 Ieri, i Carabinieri della Stazione di Monserrato, hanno dato esecuzione a un\u2019ordinanza di carcerazione per espiazione di pena detentiva emessa dal Tribunale di Sorveglianza di Cagliari nei confronti di un 27enne domiciliato a Quartu Sant\u2019Elena, disoccupato, gi\u00e0 noto alle forze di polizia.<\/p>\n\n\n\n<p>Il provvedimento scaturisce a seguito della revoca di una precedente misura dell\u2019affidamento in prova. Il giovane, dopo essere stato informato del provvedimento e accompagnato in caserma per le formalit\u00e0 di rito, \u00e8 stato trasferito presso la casa circondariale di Uta come disposto dall\u2019Autorit\u00e0 Giudiziaria competente dove dovr\u00e0 scontare la pena di 6 anni di reclusione per un pregresso grave reato contro la persona commesso nell\u2019hinterland cagliaritano nel 2023.<\/p>\n\n\n\n<p>L\u2019intervento s\u2019inserisce nel pi\u00f9 ampio e costante impegno dei Carabinieri nel garantire l\u2019effettivit\u00e0 dei provvedimenti dell\u2019Autorit\u00e0 Giudiziaria e nel rafforzare le attivit\u00e0 di prevenzione e controllo del territorio, a tutela della sicurezza della collettivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monserrato (CA). 15 Lug 2026 \u2013 Ieri, i Carabinieri della Stazione di Monserrato, hanno dato esecuzione a un\u2019ordinanza di carcerazione per espiazione di pena detentiva&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200465,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274516"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=274516"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274516\/revisions"}],"predecessor-version":[{"id":274517,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274516\/revisions\/274517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/200465"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=274516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=274516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=274516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}