{"id":274511,"date":"2026-07-15T12:06:24","date_gmt":"2026-07-15T10:06:24","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=274511"},"modified":"2026-07-15T12:06:26","modified_gmt":"2026-07-15T10:06:26","slug":"blitz-dei-carabinieri-di-santa-teresa-gallura-e-dellispettorato-del-lavoro-nellazienda-di-raccolta-rifiuti-scattano-denunce-e-sanzioni-per-la-sicurezza","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/07\/15\/blitz-dei-carabinieri-di-santa-teresa-gallura-e-dellispettorato-del-lavoro-nellazienda-di-raccolta-rifiuti-scattano-denunce-e-sanzioni-per-la-sicurezza\/","title":{"rendered":"Blitz dei Carabinieri di Santa Teresa Gallura e dell\u2019Ispettorato del Lavoro nell&#8217;azienda di raccolta rifiuti: scattano denunce e sanzioni per la sicurezza."},"content":{"rendered":"\n<p>Santa Teresa di Gallura (SS), 15 Lug 2026 - Prosegue l\u2019attivit\u00e0 di vigilanza sul rispetto delle norme di sicurezza e salute nei luoghi di lavoro in tutta la Gallura. Infatti, nei giorni scorsi, un\u2019operazione congiunta ha visto protagonisti i militari del Nucleo Carabinieri Ispettorato del Lavoro (Nil) e il personale dell\u2019ispettorato territoriale del lavoro che, con il fondamentale supporto operativo dei colleghi della Stazione di Santa Teresa Gallura, hanno effettuato un controllo approfondito presso la sede di un\u2019azienda locale attiva nel settore della raccolta dei rifiuti.<\/p>\n\n\n\n<p>L\u2019attenzione degli ispettori e dei militari dell'arma si \u00e8 concentrata non solo sui locali aziendali in cui operano quotidianamente i dipendenti, ma anche sull\u2019intero parco veicoli utilizzato per il servizio sul territorio. Nel corso delle verifiche sono emerse diverse e significative inadempienze rispetto agli obblighi che la normativa sulla sicurezza nei luoghi di lavoro. &nbsp;<\/p>\n\n\n\n<p>Nello specifico, secondo quanto accertato nel corso dei controlli, l'azienda non avrebbe adottato tutte le misure necessarie per assicurare che le attrezzature di lavoro e i mezzi fossero utilizzati in conformit\u00e0 alle istruzioni d'uso e sottoposti a quella regolare manutenzione indispensabile a garantire nel tempo gli standard di sicurezza. Inoltre le carenze hanno riguardato da vicino anche la logistica e la struttura stessa del sito aziendale.<\/p>\n\n\n\n<p>A seguito degli accertamenti, al datore di lavoro sono state impartite precise e dettagliate prescrizioni tecniche per sanare in tempi rapidi tutte le non conformit\u00e0 riscontrate sul campo. Contestualmente, sono state elevate ammende per un importo complessivo di 5.700,00 euro ed \u00e8 scattata la segnalazione formale alla Procura Della Repubblica di Tempio Pausania.<\/p>\n\n\n\n<p>Questa attivit\u00e0 di controllo rientra in una pi\u00f9 vasta e costante azione di tutela del mondo del lavoro portata avanti in tutta la provincia. Un impegno quotidiano che vede i carabinieri del comando provinciale di Sassari e del comando per la tutela del lavoro operare in stretta sinergia con l\u2019ispettorato territoriale, con l'obiettivo prioritario di prevenire gli infortuni e garantire il pieno rispetto dei diritti e della salute dei lavoratori.<\/p>\n\n\n\n<p>\u00c8 opportuno ricordare, nel rispetto del principio di presunzione di innocenza, che gli indagati non possono essere considerati colpevoli fino a quando non sia stata pronunciata una sentenza o un decreto penale di condanna divenuti irrevocabili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Teresa di Gallura (SS), 15 Lug 2026 &#8211; Prosegue l\u2019attivit\u00e0 di vigilanza sul rispetto delle norme di sicurezza e salute nei luoghi di lavoro&#8230;<\/p>\n","protected":false},"author":2,"featured_media":262425,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274511"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=274511"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274511\/revisions"}],"predecessor-version":[{"id":274512,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/274511\/revisions\/274512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/262425"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=274511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=274511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=274511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}