{"id":272511,"date":"2026-05-13T15:15:03","date_gmt":"2026-05-13T13:15:03","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=272511"},"modified":"2026-05-13T15:15:14","modified_gmt":"2026-05-13T13:15:14","slug":"pre-e-post-scuola-gratuiti-dalla-regione-3-milioni-di-euro-per-le-famiglie-sarde","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/05\/13\/pre-e-post-scuola-gratuiti-dalla-regione-3-milioni-di-euro-per-le-famiglie-sarde\/","title":{"rendered":"Pre e post scuola gratuiti: dalla Regione 3 milioni di euro per le famiglie sarde."},"content":{"rendered":"\n<p>Cagliari, 13 Magg 2026\u00a0- \u201cLa Sardegna continua a fare i conti con una delle pi\u00f9 gravi emergenze sociali e demografiche del Paese. I dati pi\u00f9 recenti confermano infatti che l\u2019Isola resta il fanalino di coda d\u2019Italia per natalit\u00e0, con un ulteriore calo delle nascite pari all\u20198,8% tra il 2024 e il 2025. Un dato che si inserisce in un quadro gi\u00e0 fortemente critico dal punto di vista dell\u2019occupazione. Per questo abbiamo pensato a una misura concreta di sostegno alle famiglie\u201d.<\/p>\n\n\n\n<p>Con queste parole l\u2019assessora regionale del Lavoro, Desir\u00e8 Manca, ha presentato questa mattina, nel corso di una conferenza stampa, la misura sperimentale \u201cServizi di accoglienza gratuiti nelle scuole primarie del territorio regionale\u201d, un intervento realizzato in collaborazione con Anci Sardegna.<\/p>\n\n\n\n<p>\u201cGeneralmente l\u2019Assessorato del Lavoro mette in campo azioni orientate alla crescita occupazionale e all\u2019inserimento lavorativo\u201d, ha spiegato l\u2019assessora. \u201cMa questo non pu\u00f2 bastare se non viene accompagnato da misure che consentano alle famiglie, e in particolar modo alle donne, non solo di trovare lavoro, ma anche di mantenerlo quando si hanno figli. Per questo abbiamo ideato un progetto sperimentale per il quale sono stati stanziati tre milioni di euro per il triennio 2026-2028, con un milione di euro per ciascuna annualit\u00e0. Partiamo con una sperimentazione, ma l\u2019obiettivo \u00e8 renderla strutturale nel tempo\u201d.<\/p>\n\n\n\n<p>Nel dettaglio, grazie allo stanziamento regionale, verranno finanziati servizi gratuiti di pre-scuola e post-scuola nelle scuole primarie dell\u2019Isola. L\u2019intervento consentir\u00e0 ai bambini di essere accolti fino a un\u2019ora prima dell\u2019inizio delle lezioni e nell\u2019ora successiva alla fine dell\u2019attivit\u00e0 scolastica, offrendo alle famiglie un supporto concreto nella gestione quotidiana degli orari lavorativi.<\/p>\n\n\n\n<p>\u201cNon abbiamo la presunzione di risolvere da soli il problema dell\u2019occupazione femminile\u201d, ha proseguito l\u2019esponente della Giunta, \u201cma intendiamo intervenire soprattutto nei piccoli comuni della Sardegna, dove il rischio spopolamento \u00e8 sempre pi\u00f9 forte e dove le famiglie incontrano maggiori difficolt\u00e0 negli spostamenti e nell\u2019organizzazione quotidiana. Quando una donna rinuncia a lavorare perch\u00e9 non riesce a conciliare gli orari scolastici con quelli lavorativi, quando un genitore \u00e8 costretto a scegliere tra occupazione e cura dei figli, significa che il sistema pubblico non sta facendo abbastanza\u201d.<\/p>\n\n\n\n<p>Il progetto non si limiter\u00e0 a garantire un semplice servizio di vigilanza, ma costruir\u00e0 veri e propri spazi educativi qualificati, affidati a educatori ed educatrici professionali. \u201cNon stiamo offrendo un servizio-parcheggio\u201d, ha sottolineato l\u2019assessora Manca. \u201cVogliamo garantire qualit\u00e0 educativa, inclusione, socializzazione e ambienti sicuri e accoglienti per i bambini\u201d.<\/p>\n\n\n\n<p>I soggetti attuatori saranno gli Enti locali, che potranno partecipare singolarmente o in forma associata, in collaborazione con le istituzioni scolastiche del territorio. Ogni progetto potr\u00e0 ricevere fino a 19.200 euro per annualit\u00e0 scolastica, finanziamento calcolato per garantire la presenza di due educatori o educatrici per due ore giornaliere, cinque giorni alla settimana, per nove mesi scolastici.<\/p>\n\n\n\n<p>Soddisfazione \u00e8 stata espressa anche dalla presidente di Anci Sardegna, Daniela Falconi, presente alla conferenza stampa in collegamento video.<\/p>\n\n\n\n<p>\u201cSono particolarmente contenta quando vengono presentate misure come questa\u201d, ha dichiarato Falconi. \u201cAnci ha apprezzato moltissimo questa misura per due motivi fondamentali: perch\u00e9 va incontro ai genitori lavoratori, ma anche alle famiglie che hanno bisogno di tempo e strumenti per cercare lavoro o organizzare meglio la propria giornata\u201d.<\/p>\n\n\n\n<p>\u201cPur essendo una misura sperimentale\u201d, ha aggiunto, \u201csi tratta di un vero intervento di welfare territoriale. Inoltre, non si tratta del classico bonus: qui si costruisce una programmazione condivisa tra Regione, Comuni, scuola e famiglie. Agli enti locali viene affidata una grande responsabilit\u00e0 nella costruzione dei progetti, ma \u00e8 proprio questo il ruolo dei Comuni: creare servizi concreti per i cittadini\u201d. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 13 Magg 2026\u00a0&#8211; \u201cLa Sardegna continua a fare i conti con una delle pi\u00f9 gravi emergenze sociali e demografiche del Paese. I dati pi\u00f9&#8230;<\/p>\n","protected":false},"author":2,"featured_media":272512,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272511"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=272511"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272511\/revisions"}],"predecessor-version":[{"id":272513,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272511\/revisions\/272513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/272512"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=272511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=272511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=272511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}