{"id":272497,"date":"2026-05-13T12:01:18","date_gmt":"2026-05-13T10:01:18","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=272497"},"modified":"2026-05-13T12:01:21","modified_gmt":"2026-05-13T10:01:21","slug":"larma-dei-carabinieri-e-lassociazione-insieme-si-puo-insieme-per-i-piccoli-pazienti-liniziativa-colorando-fa-tappa-negli-ospedali-di-cag","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/05\/13\/larma-dei-carabinieri-e-lassociazione-insieme-si-puo-insieme-per-i-piccoli-pazienti-liniziativa-colorando-fa-tappa-negli-ospedali-di-cag\/","title":{"rendered":"L\u2019Arma dei Carabinieri e l\u2019associazione \u201cInsieme si pu\u00f2\u201d insieme per i piccoli pazienti: l\u2019iniziativa \u201cColorando\u201d fa tappa negli ospedali di Cagliari e Iglesias."},"content":{"rendered":"\n<p>Cagliari, 13 Magg 2026 \u2013 Una giornata dedicata al sorriso, alla creativit\u00e0 e alla solidariet\u00e0 ha visto protagonisti i Carabinieri del Comando Provinciale di Cagliari e i rappresentanti dell\u2019associazione no profit \u201cInsieme si pu\u00f2\u201d.<\/p>\n\n\n\n<p>Grazie al progetto nazionale \u201cColorando\u201d, numerosi bambini ricoverati nei reparti pediatrici del territorio hanno ricevuto in dono speciali libricini illustrati, nati per raccontare attraverso il disegno il legame tra l\u2019Arma e le nuove generazioni, promuovendo al contempo i valori del rispetto e della legalit\u00e0.<\/p>\n\n\n\n<p>Il progetto \u201cColorando\u201d trae origine dalla costante attivit\u00e0 di beneficenza promossa dall\u2019associazione \u201cInsieme si pu\u00f2\u201d e accolta dal Comando Generale dell\u2019Arma dei Carabinieri e si pone l\u2019obiettivo di trasformare momenti di difficolt\u00e0 in occasioni di svago e riflessione per i pi\u00f9 piccoli attraverso gli affascinanti disegni realizzati da Antonio Mariella, Appuntato Scelto in quiescenza.<\/p>\n\n\n\n<p>Nei giorni scorsi i militari della Compagnia di Sanluri e della Stazione di Cagliari-Sant\u2019Avendrace, affiancati dal il presidente dell\u2019Associazione, hanno completato un percorso di visite che ha toccato tre eccellenze sanitarie della zona. Il tour della solidariet\u00e0 \u00e8 iniziato presso il reparto di Pediatria del Presidio Ospedaliero C.T.O. di Iglesias, dove la delegazione \u00e8 stata accolta dalla dottoressa Monica Zurru e dai suoi collaboratori. Successivamente, i Carabinieri hanno fatto tappa all\u2019A.R.N.A.S. \u201cG. Brotzu\u201d di Cagliari, incontrando il Direttore Generale, dottor Maurizio Marcias, e il Direttore Sanitario, dottor Giorgio Carboni, per poi concludere la giornata presso l\u2019Ospedale Microcitemico del capoluogo, accolti dalla coordinatrice.<\/p>\n\n\n\n<p>La distribuzione dei libricini ha rappresentato un momento di grande vicinanza, permettendo ai bambini e alle loro famiglie di interagire con i militari in un clima di gioia e prossimit\u00e0. Attraverso le illustrazioni che raffigurano i Carabinieri impegnati a fianco dei cittadini, il progetto mira a trasmettere ai piccoli pazienti un messaggio di fiducia nelle Istituzioni e di speranza, sottolineando come la solidariet\u00e0 rappresenti il pilastro fondamentale di una comunit\u00e0 unita.<\/p>\n\n\n\n<p>L\u2019iniziativa si inserisce nel pi\u00f9 ampio quadro delle attivit\u00e0 di prossimit\u00e0 sociale svolte quotidianamente dall\u2019Arma dei Carabinieri, che oltre ai compiti di prevenzione e controllo del territorio, riafferma la propria vocazione al servizio della collettivit\u00e0 e l\u2019attenzione costante verso le fasce pi\u00f9 vulnerabili della popolazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 13 Magg 2026 \u2013 Una giornata dedicata al sorriso, alla creativit\u00e0 e alla solidariet\u00e0 ha visto protagonisti i Carabinieri del Comando Provinciale di Cagliari&#8230;<\/p>\n","protected":false},"author":2,"featured_media":272498,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272497"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=272497"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272497\/revisions"}],"predecessor-version":[{"id":272499,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272497\/revisions\/272499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/272498"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=272497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=272497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=272497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}