{"id":272489,"date":"2026-05-13T05:26:08","date_gmt":"2026-05-13T03:26:08","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=272489"},"modified":"2026-05-13T05:26:11","modified_gmt":"2026-05-13T03:26:11","slug":"trump-vola-a-pechino-cina-e-nato-non-ci-servono-poi-attacca-i-media-traditori-liran-se-ci-attaccano-lavoreremo-allatomica-il-pentagono-la-guerra-e-costata-finora-29-miliardi","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/05\/13\/trump-vola-a-pechino-cina-e-nato-non-ci-servono-poi-attacca-i-media-traditori-liran-se-ci-attaccano-lavoreremo-allatomica-il-pentagono-la-guerra-e-costata-finora-29-miliardi\/","title":{"rendered":"Trump vola a Pechino: &#8220;Cina e Nato non ci servono&#8221;. Poi attacca i media: &#8220;Traditori&#8221;. L&#8217;Iran: &#8220;Se ci attaccano lavoreremo all&#8217;atomica&#8221;. Il Pentagono: &#8220;La guerra \u00e8 costata finora 29 miliardi&#8221;.\u00a0"},"content":{"rendered":"\n<p>Cagliari, 13 Magg 2026 - Donald Trump \u00e8 tornato ad attaccare i media sulla guerra contro l'Iran. \"Quando le 'fake news' affermano che il nemico iraniano sta avendo la meglio, militarmente, contro di noi, si tratta di un atto di virtuale tradimento\", tuona il tycoon in un post su Truth in cui accusa i media \"di favorire e spalleggiare il nemico!\".<\/p>\n\n\n\n<p>\"Non abbiamo bisogno dell'aiuto della Cina con l'Iran\". Lo ha detto Donald Trump ribadendo di essere contento di andare a Pechino. Stesse parole poco dopo a proposito della Nato: \"Non ne abbiamo bisogno\", ha detto il presidente prima di partire per la Cina.<\/p>\n\n\n\n<p>Finora la guerra contro l'Iran \u00e8 costata agli Stati Uniti 29 miliardi di dollari, riferisce il funzionario del Pentagono, Jules Hurst, in audizione al Congresso.<\/p>\n\n\n\n<p>\"Tutto ci\u00f2 che ottengono \u00e8 infondere nell'Iran una falsa speranza, laddove non dovrebbe essercene alcuna. Si tratta di codardi americani che fanno il tifo contro il nostro Paese\", ha attaccato ancora.<\/p>\n\n\n\n<p>L'Iran ha confermato che non intende tornare al tavolo dei negoziati con gli Stati Uniti finche' non saranno soddisfatte le cinque condizioni gi\u00e0 poste. \"Sono garanzie minime per creare fiducia per l'inizio di qualsiasi trattativa\", ha detto una fonte del regime all'agenzia Fars.<br>Dunque Teheran chiede \"la fine della guerra in tutti i fronti, in particolare in Libano, la rimozione delle sanzioni, lo sblocco dei fondi congelati, il risarcimento dei danni di guerra e il riconoscimento del diritto di sovranit\u00e0 dell'Iran sullo Stretto di Hormuz\", si ribadisce.<\/p>\n\n\n\n<p>L'Iran potrebbe arricchire l'uranio fino al 90%, qualora venisse nuovamente attaccato. Lo ha scritto oggi su X Ebrahim Rezaei, portavoce della Commissione parlamentare per la sicurezza nazionale e la politica estera.<br>\"Una delle opzioni dell'Iran, in caso di un nuovo attacco, potrebbe essere l'arricchimento al 90%. Ne discuteremo in Parlamento\", ha dichiarato Rezaei.<\/p>\n\n\n\n<p>Il presidente del Parlamento iraniano, Mohammad Bagher Ghalibaf, ha scritto su X che \"non c'\u00e8 alternativa\" al piano in 14 punti presentato da Teheran per mettere fine al conflitto.<br>\"Non c'\u00e8 altra alternativa che accettare i diritti del popolo iraniano cos\u00ec come sono esposti nella proposta in 14 punti - ha scritto Ghalibaf - qualsiasi altro approccio non porter\u00e0 a nulla, se non a un fallimento dopo l'altro. Pi\u00f9 tergiversano, pi\u00f9 i contribuenti americani ne pagheranno le conseguenze\".<\/p>\n\n\n\n<p>L'agenzia iraniana Tasnim ha reso noti i dettagli della risposta di Teheran alla proposta americana, che includeva richieste decisive tra cui il pieno controllo iraniano sullo Stretto di Hormuz e la fine della guerra con garanzie di non aggressione. Teheran ha condizionato l'accordo all\u2019immediato sollevamento del blocco navale e al rilascio degli asset congelati al momento della firma di un'intesa preliminare, oltre alla cancellazione delle sanzioni OFAC sul petrolio entro 30 giorni. Fonti della stessa agenzia hanno sottolineato che lo scontento espresso da Trump rappresenta \"una prova della bont\u00e0 della risposta iraniana\", ribadendo che l'Iran non formula le proprie posizioni per compiacere la Casa Bianca, ma per rivendicare i propri diritti sovrani.<\/p>\n\n\n\n<p>Il presidente degli Stati Uniti Donald Trump andr\u00e0 in Cina con un gruppo di 16 tra i maggiori dirigenti di diversi settori, come Elon Musk (Tesla), Tim Cook (Apple) e Larry Fink (BlackRock). Non ci sar\u00e0 invece il Ceo di Nvidia Jensen Huang, come hanno riferito funzionari statunitensi all'agenzia di stampa spagnola&nbsp;Efe. A seguito di Trump ci saranno altri Ceo come Kelly Ortberg (Boeing), David Solomon (Goldman Sachs), Cristiano Amon (Qualcomm), Stephen Schwarzman (Blackstone), Larry Culp (GE Aerospace) o Brian Sikes, del colosso agricolo Cargill. Ad affiancare il presidente americano saranno anche i Ceo di Citi, Coherent, Illumina, Mastercard, Micron e Visa. Le uniche donne sono Jane Fraser, amministratore delegato di Citi, e Dina Powell McCormick, presidente di Meta.<\/p>\n\n\n\n<p>Il presidente degli Stati Uniti,&nbsp;Donald Trump, arriver\u00e0 a Pechino questa sera per la sua visita in Cina. Ad annunciarlo la portavoce della Casa Bianca. La visita di Trump in Cina inizier\u00e0 con una&nbsp;cerimonia di apertura&nbsp;gioved\u00ec mattina e si concluder\u00e0 con un banchetto di Stato in serata, ha aggiunto la portavoce. Trump sembra voglia&nbsp;\"esercitare pressioni\"&nbsp;sul suo omologo cinese Xi Jinping durante il suo viaggio in Cina, mentre gli Stati Uniti cercano un accordo per porre fine alla guerra in Iran, ha riferito un funzionario statunitense. \"Mi aspetto che il presidente eserciti pressioni\", ha detto il funzionario ai giornalisti a condizione di anonimato, sottolineando che il presidente degli Stati Uniti aveva gi\u00e0 fatto pressione sull'Iran durante le sue recenti telefonate con il leader cinese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 13 Magg 2026 &#8211; Donald Trump \u00e8 tornato ad attaccare i media sulla guerra contro l&#8217;Iran. &#8220;Quando le &#8216;fake news&#8217; affermano che il nemico&#8230;<\/p>\n","protected":false},"author":2,"featured_media":271334,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272489"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=272489"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272489\/revisions"}],"predecessor-version":[{"id":272490,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/272489\/revisions\/272490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/271334"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=272489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=272489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=272489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}