{"id":269402,"date":"2026-02-04T08:29:35","date_gmt":"2026-02-04T07:29:35","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=269402"},"modified":"2026-02-04T08:29:37","modified_gmt":"2026-02-04T07:29:37","slug":"piantedosi-duro-a-montecitorio-basta-ambiguita-con-chi-assalta-lo-stato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/02\/04\/piantedosi-duro-a-montecitorio-basta-ambiguita-con-chi-assalta-lo-stato\/","title":{"rendered":"Piantedosi duro a Montecitorio: &#8220;Basta ambiguit\u00e0 con chi assalta lo Stato&#8221;."},"content":{"rendered":"\n<p>Roma, 4 Feb 2026 - Non \u00e8 bastato l\u2019appello all\u2019unit\u00e0 sulla sicurezza lanciato nei giorni scorsi dalla premier\u00a0Giorgia Meloni. L\u2019informativa alla Camera del Ministro dell\u2019Interno,\u00a0Matteo Piantedosi, sui disordini avvenuti sabato scorso a Torino durante il corteo pro-Askatasuna, ha trasformato Montecitorio in un\u2019arena di scontro politico durissimo tra governo e opposizioni.<\/p>\n\n\n\n<p>Il titolare del Viminale ha usato parole nette per descrivere i fatti del capoluogo piemontese, parlando di una \"vile aggressione\" che non rester\u00e0 impunita.&nbsp;\u201cEra un attacco frontale allo stato, era stato presentato cos\u00ec fin dalla presentazione della manifestazione, qualche settimana prima\u201d. Secondo Piantedosi, i disordini hanno mostrato il \"vero volto\" degli antagonisti legati ai centri sociali occupati abusivamente. Comunica la solidariet\u00e0 del governo ai poliziotti feriti poi l\u2019attacco si \u00e8 poi spostato sul piano politico.&nbsp;<\/p>\n\n\n\n<p>Il Ministro ha puntato il dito contro chi, a suo dire, offrirebbe una prospettiva di impunit\u00e0 ai manifestanti violenti.&nbsp;\"Chi sfila a fianco di questi delinquenti finisce per offrire loro copertura\", ha dichiarato Piantedosi, criticando aspramente anche le \"riflessioni sociologiche\" volte a giustificare l'agibilit\u00e0 politica di realt\u00e0 come Askatasuna in virt\u00f9 di una presunta utilit\u00e0 sociale.&nbsp;\"Queste persone dovrebbero tener conto che, cos\u00ec facendo, si offre complicit\u00e0 a questi gruppi organizzati\", ha aggiunto, ricordando come il centro sociale abbia rivendicato le azioni illegali tramite un comunicato ufficiale.<\/p>\n\n\n\n<p>La risposta delle minoranze non si \u00e8 fatta attendere. Per il Partito Democratico, il Movimento 5 Stelle, Alleanza Verdi e Sinistra e Pi\u00f9 Europa, le parole di Piantedosi rappresentano la fine del dialogo sulla sicurezza.<\/p>\n\n\n\n<p>Matteo Mauri (PD)&nbsp;ha definito \"ipocrita\" il richiamo all'unit\u00e0 del governo, accusando il Ministro di criminalizzare i manifestanti pacifici:&nbsp;\"Voi usate ogni occasione per strumentalizzare persone perbene, parlandone come se fossero tutti delinquenti\".&nbsp;<\/p>\n\n\n\n<p>Durissima anche l\u2019ex sindaca di Torino,&nbsp;Chiara Appendino (M5S), chiamata in causa per presunte \"coperture\" passate:&nbsp;\"Io vivo ancora sotto scorta. Usate la violenza anarchica per nascondere il vostro fallimento sulla sicurezza.&nbsp;In quella piazza c'erano famiglie, bambini. Poi c'era la schifezza di quei violenti.&nbsp;Criminalizzare un intero gruppo di persone \u00e8 pericoloso&nbsp;perch\u00e9 allontana le persone dallo stato e le avvicina ai violenti veri\u201d.&nbsp;<\/p>\n\n\n\n<p>Dagli scranni di AVS,&nbsp;Angelo Bonelli&nbsp;ha accusato il Ministro di aver alzato il livello dello scontro nel Paese, rinfacciandogli la mancata gestione dei violenti:&nbsp;\"Voi quei violenti li conoscete e gli avete consentito di agire. Parla di legalit\u00e0? Aspettiamo ancora lo sgombero di CasaPound\". Anche&nbsp;Riccardo Magi&nbsp;(+Europa) si \u00e8 detto \"terrorizzato\" dall'uso politico delle norme speciali annunciate dal Viminale.<\/p>\n\n\n\n<p>Oltre alla condanna ferma degli scontri, l'informativa del Ministro ha lasciato intravedere il perimetro d'azione legislativa che il Governo intende perseguire per blindare la sicurezza urbana. Al centro del pacchetto di misure, ci sarebbe l'inasprimento delle sanzioni per chiunque partecipi a manifestazioni non autorizzate o degenerate in violenza, con un focus particolare sulla responsabilit\u00e0 solidale e sulla limitazione dell'agibilit\u00e0 politica per le realt\u00e0 che occupano immobili pubblici.<\/p>\n\n\n\n<p>Mentre le opposizioni valutano la presentazione di un testo comune per il voto previsto domani, il Ministro Piantedosi, intercettato dai cronisti in Transatlantico, ha provato a smorzare i toni della polemica personale:&nbsp;\"Ho fatto un racconto dei fatti, sono fatti. Non mi sarei permesso alcun attacco\".<\/p>\n\n\n\n<p>La partita si sposta ora a Palazzo Madama. Domani mattina, dopo l'informativa del ministro Musumeci sul maltempo al Sud, Piantedosi torner\u00e0 nell'emiciclo del Senato per nuove comunicazioni sui fatti di Torino. La maggioranza ha forzato la mano in capigruppo per garantire che la seduta si concluda con un voto, segnale di una tensione politica che non accenna a placarsi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 4 Feb 2026 &#8211; Non \u00e8 bastato l\u2019appello all\u2019unit\u00e0 sulla sicurezza lanciato nei giorni scorsi dalla premier\u00a0Giorgia Meloni. L\u2019informativa alla Camera del Ministro dell\u2019Interno,\u00a0Matteo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":269403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/269402"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=269402"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/269402\/revisions"}],"predecessor-version":[{"id":269404,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/269402\/revisions\/269404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/269403"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=269402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=269402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=269402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}