{"id":269096,"date":"2026-01-26T16:05:41","date_gmt":"2026-01-26T15:05:41","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=269096"},"modified":"2026-01-26T16:05:43","modified_gmt":"2026-01-26T15:05:43","slug":"unione-europea-ce-il-via-libera-definitivo-stop-al-gas-russo-dal-2027-ma-non-ce-ancora-una-data-per-ladesione-dellucraina","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/01\/26\/unione-europea-ce-il-via-libera-definitivo-stop-al-gas-russo-dal-2027-ma-non-ce-ancora-una-data-per-ladesione-dellucraina\/","title":{"rendered":"Unione europea, c&#8217;\u00e8 il via libera definitivo: stop al gas russo dal 2027. Ma non c&#8217;\u00e8 ancora una data per l&#8217;adesione dell&#8217;Ucraina."},"content":{"rendered":"\n<p>Bruxelles, 26 Gen 2026 - I 27 Paesi Ue hanno adottato definitivamente il regolamento che imporr\u00e0 lo stop graduale alle importazioni di gas e gnl dalla Russia. La stretta prevede un divieto totale da fine 2026 per il gas naturale liquefatto e dall'autunno 2027 per il gas da gasdotto. L'intesa con l'Eurocamera \u00e8 stata sostenuta da tutti i Paesi membri, fatta eccezione per Ungheria e Slovacchia che hanno votato contro e la Bulgaria che si \u00e8 invece astenuta. Il regolamento sar\u00e0 ora pubblicato nella Gazzetta ufficiale dell'Ue ed entrer\u00e0 in vigore il giorno successivo alla pubblicazione. Bruxelles ha preannunciato inoltre una proposta legislativa per porre fine alle importazioni di petrolio russo - che ad oggi fanno parte del mix energetico solo di Budapest e Bratislava - entro la fine del 2027.<\/p>\n\n\n\n<p>Ora, il ministro degli Esteri tedesco, Johann Wadephul, vuole un intervento pi\u00f9 duro contro la \"flotta ombra\" russa, con la quale Mosca cerca di aggirare le sanzioni contro le vendite di petrolio. Il diritto marittimo internazionale deve essere urgentemente modificato, secondo il ministro del governo Merz, che ne ha parlato a margine di un incontro con l'omologa lettone a Riga, secondo quanto riporta la Dpa. \"Non \u00e8 possibile che ci troviamo permanentemente con le mani legate\", ha affermato il politico della Cdu, sottolineando che sia necessaria \"molta pi\u00f9 efficacia nella lotta contro questa flotta ombra\". Le navi e i loro mandanti sono gi\u00e0 oggetto di sanzioni a livello europeo, ha premesso, tuttavia occorre adesso un approfondito scambio tra i partner del Mar Baltico. Inoltre, deve essere possibile intervenire anche contro le navi il cui status di bandiera non \u00e8 chiaro. \"Dobbiamo ora sfruttare tutte le possibilit\u00e0 offerte dal diritto marittimo per fermare tali navi\", ha detto Wadephul, il quale ha inoltre rimarcato che la flotta ombra minaccia l'ecologia delle coste del Mar Baltico. Le navi sono spesso in condizioni tecniche disastrose e hanno equipaggi poco preparati, ha affermato. Se una di queste grandi petroliere dovesse naufragare, si potrebbe assistere a un \"disastro ecologico\" con un impatto forte anche nel settore turistico della Germania.<\/p>\n\n\n\n<p>Come facilmente prevedile l\u2019uomo e corrotto uomo di Putin in Europa, il presidente dell\u2019Ungheria adir\u00e0 la Corte di giustizia dell'Unione europea \"non appena la decisione su REPowerEU sar\u00e0 ufficialmente pubblicata. Utilizzeremo ogni mezzo legale \u2013 ha affermato - per ottenerne l'annullamento\". Lo ha confermato via X il ministro degli Esteri ungherese, P\u00e9ter Szijj\u00e1rt\u00f3, dopo il via libera da parte dei Paesi Ue alla tabella di marcia REPowerEu per lo stop definitivo al gas russo. \"Il piano REPowerEU si basa su un espediente giuridico, presentando una misura sanzionatoria come una decisione di politica commerciale al fine di evitare l'unanimit\u00e0. Ci\u00f2 \u00e8 in totale contrasto con le norme dell'Ue\", ha motivato. \"I trattati sono chiari: le decisioni sul mix energetico sono di competenza nazionale. &nbsp;Vietare all'Ungheria di acquistare petrolio e gas dalla Russia va contro il nostro interesse nazionale e aumenterebbe in modo significativo i costi energetici per le famiglie ungheresi\", ha ribadito.<\/p>\n\n\n\n<p>\u201cAccogliamo con favore la decisione del Consiglio dell'Ue di introdurre un divieto definitivo graduale sulle importazioni di gas dalla Russia. Il divieto totale sul GNL entrer\u00e0 in vigore all'inizio del 2027, seguito dal divieto sul gas trasportato tramite gasdotti nell'autunno del 2027. Le sanzioni per le violazioni vanno da 2,5 milioni di euro per le persone fisiche a 40 milioni di euro per le societ\u00e0. Il regolamento entrer\u00e0 in vigore all'inizio di febbraio. Grazie Ursula von der Leyen, Dan Joergensen, alla presidenza di turno danese e a quella cipriota per questa importante decisione. L'indipendenza dalle risorse energetiche della Russia \u00e8, prima di tutto, una questione di sicurezza e forza dell'Europa\u201d. &nbsp;Cos\u00ec sui social media il ministro dell'Energia dell'Ucraina, Denys Shmyhal.<\/p>\n\n\n\n<p>\"Kiev e la regione di Kiev, Kharkiv e la sua regione, le regioni di Chernihiv, Sumy, Dnipro e Zaporizhzhia\" sono le regioni che pi\u00f9 stanno soffrendo la crisi energetica dovuta agli attacchi russi, ha affermato il presidente ucraino Volodymyr Zelensky al termine di una riunione speciale tenuta oggi. \"La maggiore attenzione e il maggior tempo della discussione sono stati dedicati a Kiev. Le circostanze sono estremamente difficili: oltre 1.200 edifici residenziali plurifamiliari in citt\u00e0 sono tuttora senza riscaldamento. Abbiamo discusso con i responsabili locali e con i rappresentanti del governo come fornire aiuti nel modo pi\u00f9 rapido possibile. Al momento, tutte le scadenze di cui si \u00e8 parlato non possono essere considerate soddisfacenti: \u00e8 necessario agire pi\u00f9 velocemente\", ha osservato Zelensky.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruxelles, 26 Gen 2026 &#8211; I 27 Paesi Ue hanno adottato definitivamente il regolamento che imporr\u00e0 lo stop graduale alle importazioni di gas e gnl&#8230;<\/p>\n","protected":false},"author":2,"featured_media":224172,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/269096"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=269096"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/269096\/revisions"}],"predecessor-version":[{"id":269097,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/269096\/revisions\/269097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/224172"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=269096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=269096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=269096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}