{"id":268871,"date":"2026-01-19T16:55:59","date_gmt":"2026-01-19T15:55:59","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=268871"},"modified":"2026-01-19T16:56:02","modified_gmt":"2026-01-19T15:56:02","slug":"danimarca-le-esercitazioni-in-groenlandia-dureranno-1-o-2-anni-verranno-anche-le-forze-speciali","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2026\/01\/19\/danimarca-le-esercitazioni-in-groenlandia-dureranno-1-o-2-anni-verranno-anche-le-forze-speciali\/","title":{"rendered":"Danimarca: le esercitazioni in Groenlandia dureranno 1 o 2 anni, verranno anche le forze speciali."},"content":{"rendered":"\n<p>Copenaghen, 19 Gen 2026 \u2013 \"Minacciare dazi non \u00e8 accettabile come mezzo per affrontare le questioni\" relative alla Groenlandia. \"Dobbiamo ricordare che il Partenariato Transatlantico per il Commercio e gli Investimenti \u00e8 il pi\u00f9 grande al mondo, quindi c'\u00e8 molto da perdere economicamente, sia per l'Europa, ma anche per gli Usa, le sue aziende e i suoi lavoratori. Pertanto, dobbiamo lavorare per trovare una soluzione costruttiva per andare avanti, rispettando il diritto internazionale e prendendoci cura delle nostre importanti relazioni economiche e politiche\". Lo afferma il commissario Ue all'Economia, Valdis Dombrovskis, al suo arrivo alla riunione del C a Bruxelles.<\/p>\n\n\n\n<p>Ha inoltre osservato Dombrovskis: \"Dobbiamo ricordare che il Partenariato transatlantico per il commercio e gli investimenti \u00e8 il pi\u00f9 grande al mondo. Quindi c'\u00e8 molto da perdere. Economicamente, per l'Europa, ma anche per gli Usa, le sue aziende e i suoi lavoratori. Pertanto, dobbiamo lavorare per trovare una soluzione costruttiva per andare avanti, nel rispetto del diritto internazionale e anche prendendoci cura delle nostre importanti relazioni economiche e politiche. Ovviamente oggi discuteremo anche degli sviluppi geopolitici\", ha affermato, sottolineando che \"l'Ue rimane solidale con il Regno di Danimarca e la Groenlandia e i loro cittadini e per il principio di rispetto della sovranit\u00e0 e dell'integrit\u00e0 territoriale degli Stati membri dell'Ue. E questo riguarda anche la Groenlandia\".&nbsp;<\/p>\n\n\n\n<p>\"\u00c8 chiaro dalle riunioni tra i leader dell'Unione europea che la priorit\u00e0 \u00e8 non far precipitare la situazione ed evitare i dazi\". Lo ha affermato il portavoce della Commissione europea Olof Gill durante l'incontro quotidiano della Commissione europea con la stampa a Bruxelles, in merito alle recenti tensioni politiche e commerciali legate all'Artico. Negli ultimi mesi, si \u00e8 intensificato il dibattito in merito al ruolo dei partner transatlantici sul futuro dell'Artico, regione chiave per sicurezza e approvvigionamenti strategici. \"In ultima analisi i dazi danneggerebbero i consumatori e le imprese su entrambe le sponde dell'Atlantico- ha continuato il portavoce della Commissione europea-. L'Unione europea ha costantemente sottolineato il suo comune interesse transatlantico per la pace e la sicurezza nell'Artico, anche attraverso la Nato\". Se i dazi dovessero essere imposti: \u201cL'Ue sarebbe pronta a rispondere utilizzando gli strumenti a sua disposizione e far\u00e0 tutto il necessario per proteggere i suoi interessi economici\u201d.<\/p>\n\n\n\n<p>Le esercitazioni militari in cooperazione con gli Stati europei in Groenlandia proseguiranno ''per un anno, forse due'\": lo afferma il responsabile del Comando Artico danese, il generale Soren Andersen, al quotidiano Le Monde. Nell'intervista pubblicata oggi sul giornale francese, il comandante delle forze danesi in Groenlandia annuncia che dopo la fase di ''riconoscimento'', le esercitazioni proseguiranno, probabilmente dal mese di marzo, con ''capacit\u00e0 differenti'', incluso l'arrivo di ''forze speciali\". Andersen rivela che la sua proposta di associare gli Stati Uniti alle esercitazioni non ha avuto ''alcuna risposta''. ''Collaboriamo con l'esercito americano da decenni e continuiamo a farlo oggi - tiene a precisare il militare danese - Parte del mio personale \u00e8 dispiegata sulla base aerea di Pituffik (la base Usa in Groenlandia). Per quanto riguarda gli aspetti militari, non \u00e8 cambiato nulla\".<\/p>\n\n\n\n<p>Andersen non esita tuttavia a smentire il presidente Usa, Donald Trump, secondo cui si vedono \"destroyer e sottomarini russi ovunque'' intorno alla Groenlandia. ''Sono qui a comando da due anni e mezzo e non ho visto nessuna nave da guerra russa o cinese. \u00c8 inoltre essenziale precisare che condividiamo i timori di numerosi Paesi riguardo la Russia e la Cina e la loro collaborazione. Gli osserviamo, non vicino alla Groenlandia, ma nell'Oceano Artico. Vediamo navi da ricerca cinesi attraversare lo stretto di Bering tra Alaska e Russia. Qualcosa di mai visto prima\". E ancora: ''Dal nostro punto di vista, non c'\u00e8 minaccia immediata per la Groenlandia. Studiamo tuttavia una minaccia potenziale: una volta finita la guerra in Ucraina - e speriamo che finisca bene per l'Ucraina- la Russia sposter\u00e0 parte delle sue capacit\u00e0 e risorse verso altre zone, forse nel Mar Baltico, ma ci attendiamo soprattutto che le dispieghi nell'Artico\". Per Andersen, bisogna quindi ''rafforzare i nostri mezzi al fine di difendere a Groenlandia ma anche, ovviamente, in quanto alleati Nato, per proteggere il fianco nord della Nato\".<\/p>\n\n\n\n<p>Il presidente della Camera dei rappresentanti degli Stati Uniti Mike Johnson, in merito alle rivendicazioni del presidente Usa Donald Trump sulla Groenlandia, ha dichiarato che \"secondo il nostro sistema costituzionale, il Congresso deve dichiarare guerra. Non prevedo alcuno scenario in cui dichiariamo guerra alla Groenlandia\". Alla domanda dell'emittente Sky News se Trump avrebbe schierato truppe sul territorio della Groenlandia senza l'approvazione del Congresso, Johnson ha risposto: \"secondo il nostro sistema costituzionale, il Congresso deve dichiarare guerra. Non prevedo alcuno scenario in cui dichiariamo guerra alla Groenlandia\". \"Se si trattasse di un'incursione militare su larga scala, bisognerebbe coinvolgere il Congresso\", ha specificato il leader repubblicano.<\/p>\n\n\n\n<p>La Cina ha preso di mira la minaccia del presidente americano Donald Trump di imporre sanzioni ai Paesi europei che si oppongono ai suoi piani di controllo della Groenlandia, affermando che \"il diritto internazionale sostenuto dagli scopi e dai principi della Carta dell'Onu \u00e8 il fondamento dell'attuale ordine internazionale e deve essere rispettato\". Il portavoce del ministero degli Esteri Guo Jiakun, parlando durante il briefing quotidiano, ha aggiunto che Pechino esorta gli Usa \"a smettere di usare la cosiddetta minaccia cinese come pretesto per cercare i suoi guadagni egoistici\". Trump ha ripetutamente detto che gli Stati Uniti hanno bisogno dell'isola artica ricca di risorse perch\u00e9 Cina e Russia. In un'escalation della sua retorica, il tycoon ha annunciato sabato che imporr\u00e0 dazi del 10% sulle merci provenienti da otto Paesi europei - Danimarca, Norvegia, Svezia, Francia, Germania, Regno Unito, Paesi Bassi e Finlandia - finch\u00e9 non accetteranno di sostenere il suo discorso sull'acquisto della Groenlandia, isola danese autonoma. \"\u00c8 in gioco la pace nel mondo!\", ha scritto Trump in un post sul social Truth. \"La Cina e la Russia vogliono la Groenlandia, e la Danimarca non pu\u00f2 fare nulla al riguardo\".<\/p>\n\n\n\n<p>\"Considerando che il vostro Paese ha deciso di non darmi il Premio Nobel per la Pace per aver fermato 8 guerre in pi\u00f9, non mi sento pi\u00f9 in dovere di pensare esclusivamente alla Pace, anche se sar\u00e0 sempre predominante, ma ora posso pensare a ci\u00f2 che \u00e8 buono e giusto per gli Stati Uniti d'America\".&nbsp;<\/p>\n\n\n\n<p>Lo scrive&nbsp;Donald Trump&nbsp;in una lettera al primo ministro della Norvegia, Jonas Gahr Store, rivelata da&nbsp;Sky News. \"La Danimarca non pu\u00f2 proteggere quella terra dalla Russia o dalla Cina, e perch\u00e9 mai dovrebbero avere un diritto di propriet\u00e0? Non ci sono documenti scritti\", afferma il tycoon riferendosi alla Groenlandia.<\/p>\n\n\n\n<p>\"Sappiamo solo - afferma Trump - che una barca \u00e8 approdata l\u00ec centinaia di anni fa, ma anche noi avevamo barche che approdavano l\u00ec. Ho fatto per la Nato pi\u00f9 di chiunque altro fin dalla sua fondazione, e ora la Nato faccia qualcosa per gli Stati Uniti. Il mondo non sar\u00e0 sicuro se non avremo il controllo totale e completo della Groenlandia. Grazie!\".<\/p>\n\n\n\n<p>\"Il Premio Nobel per la Pace, ho spiegato chiaramente anche al presidente Trump, viene assegnato da un comitato indipendente e non dal governo norvegese\". Lo afferma il primo ministro norvegese Jonas Gahr Store in replica al messaggio del presidente Usa. Lo riporta la Bbc. \"La posizione della Norvegia - ribadisce Store - sulla Groenlandia \u00e8 chiara. La Groenlandia fa parte del Regno di Danimarca e la Norvegia sostiene pienamente il Regno di Danimarca su questa questione\".&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Copenaghen, 19 Gen 2026 \u2013 &#8220;Minacciare dazi non \u00e8 accettabile come mezzo per affrontare le questioni&#8221; relative alla Groenlandia. &#8220;Dobbiamo ricordare che il Partenariato Transatlantico&#8230;<\/p>\n","protected":false},"author":2,"featured_media":268872,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/268871"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=268871"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/268871\/revisions"}],"predecessor-version":[{"id":268873,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/268871\/revisions\/268873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/268872"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=268871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=268871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=268871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}