{"id":249158,"date":"2024-06-27T11:32:38","date_gmt":"2024-06-27T09:32:38","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=249158"},"modified":"2024-06-27T11:32:41","modified_gmt":"2024-06-27T09:32:41","slug":"comune-di-cagliari-per-il-sardegna-pride-temporanee-modifiche-alla-circolazione-il-29-giugno","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2024\/06\/27\/comune-di-cagliari-per-il-sardegna-pride-temporanee-modifiche-alla-circolazione-il-29-giugno\/","title":{"rendered":"Comune di Cagliari &#8211; Per il Sardegna Pride temporanee modifiche alla circolazione il 29 giugno."},"content":{"rendered":"\n<p>Cagliari, 27 Giu 2024 - Nell'ambito della manifestazione denominata \u201cSardegna Pride\u201d, nella giornata di sabato 29 giugno 2024 sono previste temporanee modifiche alla circolazione veicolare nelle vie del centro di Cagliari.<\/p>\n\n\n\n<p>A voce dell'ordinanza dirigenziale n. 1564\/2024 (link pi\u00f9 sotto), le prescrizioni da osservare (comprese le corsie bus e le piste ciclabili) sono di seguito specificate.<\/p>\n\n\n\n<p>Divieto di sosta (con rimozione forzata) dalla mezzanotte di venerd\u00ec 28 e divieto di transito dalle ore 8 di sabato 29 giugno e sino al completo disimpegno della strada da parte dei partecipanti al corteo, nella via Giudice Torbeno (dalla intersezione con via Dei Giudicati alla intersezione con via Cao Di San Marco) e nella via Cao Di San Marco (dalla intersezione con via Giudice Torbeno alla intersezione con via Baccaredda).<\/p>\n\n\n\n<p>Divieto di transito dalle ore 8 di sabato 29 giugno e sino a completo disimpegno della strada da parte dei partecipanti al corteo nella via San Vetrano e nella via Giudicessa Vera.<\/p>\n\n\n\n<p>Divieto di transito dalle ore 14 di sabato 29 giugno e sino a completo disimpegno della strada da parte dei partecipanti al corteo nella via Bacaredda (da via Dei Giudicati a via Cao Di San Marco) e nella via Romagna (bretella di svolta nella via Bacaredda).<\/p>\n\n\n\n<p>Divieto di sosta (con rimozione forzata) dalle ore 8 di sabato 29 giugno e divieto di transito dalle ore 17 e sino al completo disimpegno della strada da parte dei partecipanti al corteo nelle vie:<\/p>\n\n\n\n<p>Bacaredda (da via Cao di San Marco a via Manzoni)<\/p>\n\n\n\n<p>Manzoni (ambo i lati)<\/p>\n\n\n\n<p>Paoli<\/p>\n\n\n\n<p>piazza Garibaldi (compresi parcheggio taxi fronte civico n. 12 e parcheggi fronte civico n. 23 area ex distributore)<\/p>\n\n\n\n<p>Sonnino (da piazza Garibaldi a via Logudoro)<\/p>\n\n\n\n<p>San Gregorio Magno<\/p>\n\n\n\n<p>Logudoro (ambo i lati)<\/p>\n\n\n\n<p>Dante (da via De Gioannis a piazza Giovanni XXIII)<\/p>\n\n\n\n<p>Divieto di sosta (con rimozione forzata), dalla mezzanotte di venerd\u00ec 28 alle ore 24 di sabato 29 giugno nella via Santa Alenixedda (ambo i lati dal civico n. 125 alla intersezione con la via Cao Di San Marco), nella via Cao Di San Marco (ambo i lati dalla via Santa Alenixedda alla via Dante) e nella piazza Giovanni (ambo i lati dalla Via Dante alla via Don Macchioni).<\/p>\n\n\n\n<p>Divieto di transito dalle ore 17 di sabato 29 giugno 2024 e sino a completo disimpegno della strada da parte dei partecipanti al corteo nelle vie:<\/p>\n\n\n\n<p>vico XII San Giovanni;<\/p>\n\n\n\n<p>Sant\u2019Alenixedda<\/p>\n\n\n\n<p>Cocco Ortu<\/p>\n\n\n\n<p>San Rocco<\/p>\n\n\n\n<p>piazza San Rocco<\/p>\n\n\n\n<p>Ozieri (da via Macomer a piazza San Rocco)<\/p>\n\n\n\n<p>Monti<\/p>\n\n\n\n<p>Leopardi (da via Carducci a via Manzoni)<\/p>\n\n\n\n<p>Alfieri (da via Tiziano a via Manzoni)<\/p>\n\n\n\n<p>piazza San Benedetto<\/p>\n\n\n\n<p>San Benedetto (direzione piazza San Benedetto, da via Petrarca\/Pergolesi a piazza San Benedetto)<\/p>\n\n\n\n<p>Tola (da via Satta a via Paoli)<\/p>\n\n\n\n<p>Settembrini<\/p>\n\n\n\n<p>Bacaredda (da via Manzoni a piazza Garibaldi)<\/p>\n\n\n\n<p>Alghero (da via Satta a via Sonnino)<\/p>\n\n\n\n<p>Alghero (da via Einaudi a via Sonnino)<\/p>\n\n\n\n<p>Einaudi (da via Oristano a via Alghero)<\/p>\n\n\n\n<p>Abba<\/p>\n\n\n\n<p>Iglesias\/piazza Gramsci (da via Oristano a via Sonnino)<\/p>\n\n\n\n<p>Deledda (da via Satta a via Sonnino)<\/p>\n\n\n\n<p>San Lucifero (da via Sant\u2019Eusebio a via Sonnino)<\/p>\n\n\n\n<p>Carbonia (da via Lanusei a via Sonnino)<\/p>\n\n\n\n<p>via Olbia<\/p>\n\n\n\n<p>Nuoro (da piazza Ichnusa a via Logudoro)<\/p>\n\n\n\n<p>viale Cimitero (da viale Bonaria a via De Gioannis)<\/p>\n\n\n\n<p>Dante (direzione viale Cimitero da piazza Repubblica a via Logudoro)<\/p>\n\n\n\n<p>De Gioannis (direzione via Dante: da via Gianturco a via Dante)<\/p>\n\n\n\n<p>piazza Repubblica<\/p>\n\n\n\n<p>Deledda (da via Sant\u2019Eusebio\/Lo Frasso a via Dante)<\/p>\n\n\n\n<p>Farina (da via Alagon a via Dante)<\/p>\n\n\n\n<p>Donizetti (direzione via Dante: da via Puccini a via Dante)<\/p>\n\n\n\n<p>San Benedetto (direzione piazza San Benedetto da via Pergolesi)<\/p>\n\n\n\n<p>Cherubini<\/p>\n\n\n\n<p>Cino Da Pistoia (direzione via Dante)<\/p>\n\n\n\n<p>Tiziano (da via Pacinotti a via Dante)<\/p>\n\n\n\n<p>Petrarca (da via Cavalcanti\/Pascoli a via Dante)<\/p>\n\n\n\n<p>Cocco Ortu (dalla via Pacinotti con direzione via Dante)<\/p>\n\n\n\n<p>Ferracciu (da via Foscolo a via Dante)<\/p>\n\n\n\n<p>Salaris (da via Foscolo a via Dante)<\/p>\n\n\n\n<p>Todde (da piazza Michelangelo a via Dante)<\/p>\n\n\n\n<p>Don Macchioni (da via Salvemini\/piazza San Giovanni XXIII a via Cao San Marco)<\/p>\n\n\n\n<p>Direzioni obbligatorie, dalle ore 14 di sabato 29 giugno 2024 e sino a completo disimpegno della strada da parte dei partecipanti al corteo, nella via Romagna (direzione via Bacaredda, obbligo di svolta a sinistra in via Francesco Ciusa).<\/p>\n\n\n\n<p>Direzioni obbligatorie, dalle ore 17 di sabato 29 giugno 2024 e sino a completo disimpegno della strada da parte dei partecipanti al corteo, nella via Marche (obbligo svolta in via San Giovanni), nella via Verdi (obbligo svolta a destra in via San Benedetto), nella via Tola (obbligo svolta a sinistra in via Satta), nella via Carrara (obbligo svolta a sinistra in via De Gioannis), nella via Sant\u2019Eusebio (obbligo direzione diritto in via Lo Frasso), nella via Tuveri (obbligo svolta a sinistra in piazza Repubblica\/Pessina), nella via Cherubini (obbligo svolta a destra in via Donizzetti), nella via Foscolo (obbligo svolta a sinistra in via Cocco Ortu), nella via Cino Da Pistoia (direzione obbligatoria da via Dante a via Petrarca).<\/p>\n\n\n\n<p>A cura degli organizzatori della manifestazione \u00e8 prevista la predisposizione di un servizio di segnalazione, tramite addetti posizionati in corrispondenza delle intersezioni o degli sbocchi delle strade che comunque si immettono su quella percorsa dal corteo del, allo scopo di rendere tempestivamente informati gli utenti che vi circolano, dell\u2019imminente transito dei partecipanti al corteo Sardegna Pride. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 27 Giu 2024 &#8211; Nell&#8217;ambito della manifestazione denominata \u201cSardegna Pride\u201d, nella giornata di sabato 29 giugno 2024 sono previste temporanee modifiche alla circolazione veicolare&#8230;<\/p>\n","protected":false},"author":2,"featured_media":237045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249158"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=249158"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249158\/revisions"}],"predecessor-version":[{"id":249159,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249158\/revisions\/249159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/237045"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=249158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=249158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=249158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}