{"id":249095,"date":"2024-06-25T10:37:26","date_gmt":"2024-06-25T08:37:26","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=249095"},"modified":"2024-06-25T10:37:29","modified_gmt":"2024-06-25T08:37:29","slug":"un-58enne-di-cagliari-tenta-di-rubare-un-motociclo-arrestato-dagli-agenti-della-squadra-volanti-per-tentato-furto-aggravato-e-resistenza-e-minaccia-a-pubblico-ufficiale","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2024\/06\/25\/un-58enne-di-cagliari-tenta-di-rubare-un-motociclo-arrestato-dagli-agenti-della-squadra-volanti-per-tentato-furto-aggravato-e-resistenza-e-minaccia-a-pubblico-ufficiale\/","title":{"rendered":"Un 58enne di Cagliari tenta di rubare un motociclo: arrestato dagli agenti della Squadra Volanti per tentato furto aggravato e resistenza e minaccia a Pubblico Ufficiale."},"content":{"rendered":"\n<p>Cagliari, 25 Giu 2024 \u2013 Sabato scorso, di sera, gli Agenti della Squadra Volanti della Questura di Cagliari, nel rispetto dei diritti della persona indagata e della presunzione di innocenza, per quanto risulta allo stato, salvo ulteriori approfondimenti e in attesa del giudizio, hanno arrestato un 58enne,\u00a0per l\u2019ipotesi di reato di\u00a0tentato furto aggravato e resistenza e minaccia a Pubblico Ufficiale.<\/p>\n\n\n\n<p>L\u2019intervento che ha portato all\u2019arresto dell\u2019uomo \u00e8 stato segnalato intorno alle ore 19.40 quando era stato notato mentre cercava di rubare una bicicletta in Via Is Mirrionis ma non essendoci riuscito si \u00e8 spostato nella vicina Via Anglona dove, sempre con un coltello, ha cercato di forzare il quadro di accensione di uno scooter. Ma proprio in quel frangente \u00e8 stato notato dai poliziotti che percorrevano la via seguendo le indicazioni pervenute al Centro Operativo. E l\u2019uomo, vista la Volante, con l\u2019intento di sottrarsi al controllo, si&nbsp;\u00e8 allontanato velocemente verso la via Ogliastra, buttando a terra il coltello. I poliziotti lo hanno raggiunto e bloccato e nella circostanza ha opposto resistenza, minacciando il personale della Polizia in servizio.<\/p>\n\n\n\n<p>Quindi subito dopo l\u2019arresto, \u00e8 stato recuperato e sequestrato il coltello e dopo aver verificato il danneggiamento del blocco di accensione dello scooter, il 58enne \u00e8 stato accompagnato in Questura e qui dichiarato in arresto.<\/p>\n\n\n\n<p>I fatti accertati dai poliziotti sono stati sottoposti alla valutazione del giudice monocratico, che&nbsp;a seguito dell\u2019udienza con rito direttissima, ha convalidato l\u2019arresto con l\u2019applicazione della misura dell\u2019obbligo di presentazione alla PG.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 25 Giu 2024 \u2013 Sabato scorso, di sera, gli Agenti della Squadra Volanti della Questura di Cagliari, nel rispetto dei diritti della persona indagata&#8230;<\/p>\n","protected":false},"author":2,"featured_media":160391,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249095"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=249095"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249095\/revisions"}],"predecessor-version":[{"id":249096,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249095\/revisions\/249096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/160391"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=249095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=249095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=249095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}