{"id":249071,"date":"2024-06-24T13:16:38","date_gmt":"2024-06-24T11:16:38","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=249071"},"modified":"2024-06-24T13:16:39","modified_gmt":"2024-06-24T11:16:39","slug":"lavvio-della-campagna-estiva-dal-servizio-polizia-stradale-e-state-con-noi-ha-portato-alla-denuncia-di-sette-persone-sorpresi-alla-guida-delle-loro-vettura-sotto-l","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2024\/06\/24\/lavvio-della-campagna-estiva-dal-servizio-polizia-stradale-e-state-con-noi-ha-portato-alla-denuncia-di-sette-persone-sorpresi-alla-guida-delle-loro-vettura-sotto-l\/","title":{"rendered":"L\u2019avvio della campagna estiva dal Servizio Polizia Stradale \u201cE..state con noi\u201d ha portato alla denuncia di sette persone sorpresi alla guida delle loro vettura sotto l\u2019effetto di sostanze stupefacenti o psicotrope."},"content":{"rendered":"\n<p>Sassari, 24 Giu 2024 - Lo scorso fine settimana in Sardegna \u00e8 partita la campagna estiva programmata dal Servizio Polizia Stradale \u201cE..state con noi\u201d che ha visto la presenza del personale della polizia stradale impegnato sia in attivit\u00e0 di prossimit\u00e0 che in servizi di controllo specifici sul territorio gallurese.<\/p>\n\n\n\n<p>Sabato 22 giugno, nella piazza Terranova di Olbia, \u00e8 stato preparato uno spazio dedicato alla Polizia di Stato per accogliere turisti e cittadini. Durante la serata, hanno potuto ammirare l\u2019autovettura Lamborghini Huracan e interagire con gli uomini e le donne della Polizia di Stato.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2024\/06\/Lauto-Lamborghini-della-polizia-di-stato-presente-a-Sassari.jpg\" alt=\"\" class=\"wp-image-249074\" width=\"726\" height=\"484\" srcset=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2024\/06\/Lauto-Lamborghini-della-polizia-di-stato-presente-a-Sassari.jpg 600w, https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2024\/06\/Lauto-Lamborghini-della-polizia-di-stato-presente-a-Sassari-300x200.jpg 300w\" sizes=\"(max-width: 726px) 100vw, 726px\" \/><\/figure>\n\n\n\n<p>Lo scopo della serata \u00e8 stato quello di sensibilizzare le persone ad assumere comportamenti pi\u00f9 responsabili quando si \u00e8 alla guida di qualsiasi veicolo, provando personalmente un percorso attraverso l\u2019utilizzo di occhiali di simulazione per comprendere meglio cosa significa guidare in condizioni psicofisiche alterate da assunzione di droghe e alcol.<\/p>\n\n\n\n<p>A seguire, nel corso della notte del 23 giugno, il personale del Distaccamento di Olbia e di Tempio Pausania, ha effettuato un servizio specifico dedicato ai controlli su strada. E le pattuglie impegnate a Olbia, poich\u00e9 interessata dalla tappa italiana del Campionato Mondiale di Acquabike e che ha richiamato un notevole numero di persone giunti non solo dalla Sardegna ma da ogni parte di Italia, si sono avvalse della collaborazione del personale del Laboratorio Mobile per accertare su strada lo stato di alterazione psicofisica dovuto all\u2019assunzione di stupefacenti attraverso analisi di secondo livello degli utenti della strada fermati e sottoposti a controllo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2024\/06\/Mostra-mezzi-polizia-di-Stato-Sassari.jpg\" alt=\"\" class=\"wp-image-249072\" width=\"730\" height=\"487\" srcset=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2024\/06\/Mostra-mezzi-polizia-di-Stato-Sassari.jpg 600w, https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2024\/06\/Mostra-mezzi-polizia-di-Stato-Sassari-300x200.jpg 300w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>I risultati finali hanno evidenziato che su 78 persone controllate 7 conducenti erano alla guida sotto l\u2019effetto di sostanze stupefacenti o psicotrope. Sono state denunciate a piede libero 8 persone per infrazioni al Codice della Strada e uno sanzionato per illecito amministrativo. Inoltre sono state ritirate 9 patenti, confiscati 3 veicoli, ritirate 3 carte di circolazione e decurtati 100 punti.<\/p>\n\n\n\n<p>Episodio da menzionare un giovane diciottenne sassarese, in possesso di patente di guida da tre mesi, denunciato perch\u00e9 sotto l\u2019effetto di cannabinoidi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sassari, 24 Giu 2024 &#8211; Lo scorso fine settimana in Sardegna \u00e8 partita la campagna estiva programmata dal Servizio Polizia Stradale \u201cE..state con noi\u201d che&#8230;<\/p>\n","protected":false},"author":2,"featured_media":249073,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249071"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=249071"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249071\/revisions"}],"predecessor-version":[{"id":249075,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249071\/revisions\/249075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/249073"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=249071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=249071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=249071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}