{"id":249001,"date":"2024-06-21T10:13:22","date_gmt":"2024-06-21T08:13:22","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=249001"},"modified":"2024-06-21T10:13:25","modified_gmt":"2024-06-21T08:13:25","slug":"arrestato-dai-carabinieri-della-stazione-di-uta-e-cacciatori-di-sardegna-un-pensionato-con-precedenti-di-polizia-un-77enne-per-coltivazione-di-marijuana-nelle-campagne-del-comune-di-uta","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2024\/06\/21\/arrestato-dai-carabinieri-della-stazione-di-uta-e-cacciatori-di-sardegna-un-pensionato-con-precedenti-di-polizia-un-77enne-per-coltivazione-di-marijuana-nelle-campagne-del-comune-di-uta\/","title":{"rendered":"Arrestato dai Carabinieri della Stazione di Uta e Cacciatori di Sardegna, un pensionato con precedenti di polizia, un 77enne per coltivazione di Marijuana nelle campagne del comune di Uta."},"content":{"rendered":"\n<p>Uta (Ca), 21 Giu 2024 \u2013 I Carabinieri della Stazione di Uta, in provincia di Cagliari, avendo ricevuto informazioni su una possibile coltivazione di Marijuana nella zona, hanno avviato le indagini necessarie per verificare la veridicit\u00e0 delle segnalazioni. Le prime informazioni indicavano che la coltivazione fosse situata in una zona impervia, difficilmente accessibile e nascosta alla vista, il che rendeva l'operazione particolarmente complessa. Quindi grazie al meticoloso lavoro d\u2019indagine e alla conoscenza del territorio, i militari sono riusciti a localizzare il sito sospetto.<\/p>\n\n\n\n<p>In seguito, la scorsa notte, con l'ausilio del personale dello Squadrone Eliportato Cacciatori di Sardegna, \u00e8 stata eseguita una perquisizione domiciliare che ha portato, nel rispetto dei diritti delle persone indagate e della presunzione di innocenza, in attesa di ulteriori approfondimenti e del giudizio finale, all'arresto di un uomo di 77 anni per coltivazione di stupefacenti.<\/p>\n\n\n\n<p>Durante l'operazione, eseguita nell'abitazione dell'arrestato, il personale dell\u2019Arma ha trovato 88 piante di Cannabis di varie dimensioni coltivate nel giardino di pertinenza. Le piante, nascoste in una zona impervia, erano ben curate e disposte in modo tale da rendere difficile la loro individuazione. Pertanto le piante sono state immediatamente sottoposte a sequestro e verranno analizzate in laboratorio per determinare il contenuto di principio attivo.<\/p>\n\n\n\n<p>L'arrestato, pensionato e gi\u00e0 noto alle forze dell'ordine, ultimate le formalit\u00e0 di rito in caserma, \u00e8 stato accompagnato nella sua abitazione in attesa del rito direttissimo, che si terr\u00e0 questa mattina presso il Tribunale di Cagliari.<\/p>\n\n\n\n<p>I Carabinieri di Uta continueranno a vigilare attentamente sul territorio, garantendo la sicurezza e la legalit\u00e0 per tutti i cittadini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uta (Ca), 21 Giu 2024 \u2013 I Carabinieri della Stazione di Uta, in provincia di Cagliari, avendo ricevuto informazioni su una possibile coltivazione di Marijuana&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249001"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=249001"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249001\/revisions"}],"predecessor-version":[{"id":249002,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/249001\/revisions\/249002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/201716"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=249001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=249001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=249001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}