{"id":248953,"date":"2024-06-20T09:15:18","date_gmt":"2024-06-20T07:15:18","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=248953"},"modified":"2024-06-20T09:15:21","modified_gmt":"2024-06-20T07:15:21","slug":"il-turismo-spinge-leconomia-regionale-nel-2023-superato-il-livello-pre-pandemico-report-della-cna-sardegna","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2024\/06\/20\/il-turismo-spinge-leconomia-regionale-nel-2023-superato-il-livello-pre-pandemico-report-della-cna-sardegna\/","title":{"rendered":"Il turismo spinge l\u2019economia regionale: nel 2023 superato il livello pre-pandemico: Report della Cna Sardegna."},"content":{"rendered":"\n<p>Cagliari, 20 Giu 2024 - Nel 2023 nelle strutture ricettive alberghiere ed extra-alberghiere della Sardegna si sono registrate\u00a015,7 milioni di presenze: una\u00a0crescita del +6,5% rispetto al 2022, oltre mezzo milione in pi\u00f9 di quanto si registrava nel 2019. Ancora pi\u00f9 rapido \u00e8 stato il recupero in termini di arrivi, i quali hanno fatto registrare una crescita del +7,7% rispetto al 2022, portandosi su un livello superiore del 6,7% rispetto all\u2019anno pre-pandemico.<\/p>\n\n\n\n<p>Nel corso del 2023 il turismo \u00e8 stato uno dei pochi settori in grado di sospingere l\u2019economia della Sardegna&nbsp;grazie al pieno recupero dei livelli pre-pandemici.&nbsp; Lo si evince da un dossier del Centro Studi della Cna Sardegna che analizza le ultime stime dell\u2019Istat per il 2023, ottenute a partire dai dati contenuti nel portale \u201cAlloggiati Web\u201d della Polizia di Stato.<\/p>\n\n\n\n<p>L\u2019analisi si riferisce alle sole strutture ufficiali e non considera il contributo all\u2019economia regionale fornito dal cosiddetto turismo residenziale, ovvero, quello delle seconde case, case vacanze e B&amp;B gestiti in maniera non imprenditoriale. Stime della Cna indicano che questa vera e propria nicchia turistica in forte ascesa, grazie al volano della cosiddetta sharing economy, quasi eguaglia i numeri del turismo ufficiale. Se ci si limita ai flussi internazionali, indicazioni al riguardo arrivano dalle indagini campionarie condotte dalla Banca d\u2019Italia sui viaggiatori internazionali che arrivano sull\u2019Isola dai principali scali aeroportuali e portuali; in base a queste stime,&nbsp;nel corso del 2023, in Sardegna si sono registrate - a prescindere dalla tipologia di alloggio - circa 14,1 milioni di presenze straniere, a fronte delle 7,6 milioni censite dall\u2019Istat.<\/p>\n\n\n\n<p>Tornado ai dati ufficiali, negli ultimi due anni sono stati soprattutto i flussi italiani a sospingere le dinamiche del turismo regionale; gi\u00e0&nbsp;nel 2022, infatti, il numero di connazionali giunti sull\u2019Isola aveva superato il livello del 2019, con circa 1,82 milioni di arrivi e quasi 8 milioni di presenze, numeri, questi, leggermente migliorati nel corso del&nbsp;2023 (+4,2% gli arrivi e +1,3% le presenze). La ripresa dei flussi internazionali \u00e8 stata pi\u00f9 lenta, in parte per via della riduzione del numero di collegamenti aeroportuali con i principali scali europei e dell\u2019aumento dei costi di viaggio sperimentata nell\u2019ultimo biennio \u2013 come indicato dalle simulazioni di booking condotte annualmente dalla CNA. A conti fatti, rispetto al 2019, nel 2022 mancavano all\u2019appello circa 150 mila arrivi stranieri e un milione di presenze.&nbsp;Nel 2023 la crescita della presenza turistica internazionale sull\u2019Isola \u00e8 stata per\u00f2 eccezionale, pari a oltre +13% sia in termini di arrivi sia in termini di presenze, portando cos\u00ec a compimento il pieno recupero dei livelli pre-pandemici.<\/p>\n\n\n\n<p>Per quanto riguarda l\u2019anno in corso, nonostante la difficile situazione nazionale e internazionale, i dati sulle prenotazioni nelle strutture ricettive dell\u2019Isola sono positivi. In base ai numeri forniti dagli operatori,&nbsp;alla fine del primo trimestre dell\u2019anno&nbsp;(si vedano ad esempio i report di AlbergatorePro)&nbsp;la percentuale di camere in strutture alberghiere gi\u00e0 prenotate era superiore a quella registrata nello stesso periodo del 2023, e questo lascia ben sperare in vista della stagione estiva.<\/p>\n\n\n\n<p>Secondo la Cna la ripresa del settore turistico \u00e8 stata sicuramente fondamentale per sostenere la claudicante economia dell\u2019Isola, eppure,&nbsp;il confronto tra le diverse regioni italiane fa pensare che in Sardegna esistano ancora ampi margini di crescita. In primo luogo,&nbsp;l\u2019Isola ha perso due posizioni nella classifica nazionale in termini di numero di presenze annue rispetto al 2019, superata da Liguria e Sicilia; inoltre, nell\u2019ultimo biennio la crescita registrata \u00e8 stata inferiore a quella di alcune regioni simili, come Puglia, Sicilia o Abruzzo.<\/p>\n\n\n\n<p>D\u2019altra parte, se si estende il campo di analisi a un insieme di regioni europee che competono con la Sardegna per attrarre la domanda turistica nell\u2019area Mediterranea (Creta, Algarve, Puglia, Corsica, Croazia, Malta, Sicilia, Baleari, Calabria e Cipro), si trova che&nbsp;i poco pi\u00f9 di 3,4 milioni di arrivi registrati nelle strutture ricettive dell\u2019Isola nel 2022 hanno rappresentato appena il 5,6% degli arrivi totali in queste regioni; il dato della Sardegna, in particolare, impallidisce di fronte agli&nbsp;oltre 12 milioni di turisti che arrivano annualmente nelle Baleari o in Croazia Adriatica, ma risulta modesto anche se paragonato ai quasi 5 milioni di&nbsp; Sicilia o Algarve, o ai 6 milioni di Creta. La distanza \u00e8 evidente anche se si guarda al dato delle presenze:&nbsp;in Sardegna nel 2022 le strutture ufficiali hanno ospitato viaggiatori per circa 14,7 milioni di notti - il 5,1% del totale; in Croazia i pernottamenti sono stati 86 milioni; 65,4 milioni nelle Baleari; 32 milioni a Creta; 21 milioni nell\u2019Algarve.<\/p>\n\n\n\n<p>Se per\u00f2 si guarda all\u2019offerta ricettiva ufficiale \u00e8 evidente che qualcosa non torni;&nbsp;con i suoi 222 mila posti letto ufficiali la Sardegna si pone infatti su un livello simile o superiore a quello di Creta o Algarve, regioni che registrano quasi il doppio del numero di presenze annue. Anche guardando alla capacit\u00e0 ricettiva delle Baleari, circa 462 mila posti letto, la differenza con la Sardegna non \u00e8 nemmeno lontanamente paragonabile a quella che si registra in termini di presenze (65 milioni contro le 15 milioni ufficiali della Sardegna).<\/p>\n\n\n\n<p>\u201cIl turismo in Sardegna ha grandi potenzialit\u00e0 inespresse ed esiste uno spazio di lavoro enorme ancora da colmare\u201d,&nbsp;commentano&nbsp;Luigi Tomasi&nbsp;e&nbsp;Francesco Porcu, rispettivamente presidente e segretario regionale della Cna Sardegna&nbsp; - si tratta di&nbsp;superare l\u2019immagine internazionale fortemente caratterizzata e incentrata sullo stereotipo della vacanza balneare&nbsp;che rappresenta probabilmente uno dei limiti del modello di offerta della Sardegna che, non a caso, concentra i flussi di viaggiatori nei pochi mesi estivi. Sulla base di uno studio effettuato nel 2017 dalla Cna Sardegna (\u201cEconomia e Turismo: modelli a confronto, la Sardegna e i suoi competitor\u201d),&nbsp;benessere e salute sono in assoluto come gli ambiti in cui la Sardegna potrebbe essere pi\u00f9 competitiva, seguiti dal turismo storico-archeologico e dal turismo sportivo\u201d.&nbsp;<\/p>\n\n\n\n<p>Ecco quali sono, secondo i vertici della Cna Sardegna, le azioni intraprendere per rendere l\u2019industria turistica sarda pi\u00f9 dinamica e sostenibile: Dare centralit\u00e0 al tema dell\u2019innovazione, anche per via delle difficolt\u00e0 del tessuto imprenditoriale regionale di rinnovare la propria offerta e sfruttare le opportunit\u00e0 offerte dall\u2019innovazione tecnologica e da una domanda sempre pi\u00f9 diversificata ed esigente; Supportare e promuovere la cultura d\u2019impresa attraverso l\u2019organizzazione di&nbsp;corsi di formazione per gli imprenditori e per il personale; Fornire&nbsp;strumenti utili per i sempre pi\u00f9 numerosi \u201cimprenditori\u201d che alimentano il turismo residenziale, allo scopo di innalzare la qualit\u00e0 generale e contribuire a migliorare l\u2019immagine della Sardegna sui canali della sharing economy (OTA, social network e portali web); Investire sui trasporti, inteso non solo come potenziamento dell\u2019accessibilit\u00e0 dell\u2019Isola dall\u2019esterno ma anche, e soprattutto, in riferimento al trasporto interno, ovvero ai collegamenti da e verso i principali punti di accesso (porti e aeroporti) e al potenziamento del trasporto pubblico locale, visto come elemento fondamentale per favorire la mobilit\u00e0 dei turisti sul territorio; Intervenire sul paesaggio urbano attraverso politiche organiche di riqualificazione; la \u201ccitt\u00e0\u201d come elemento strategico per il turismo, vista non solo come entit\u00e0 di passaggio dove fare acquisti e usufruire dei servizi di base ma parte integrante dell\u2019esperienza di viaggio e promuovere l\u2019organizzazione di&nbsp;eventi culturali e artistici, ma anche sportivi, di intrattenimento e fieristici, non solo per intercettare nuove tipologie di domanda (culturale, sportiva, turismo dell\u2019intrattenimento), ma anche come elemento utile per arricchire l\u2019esperienza di viaggio, favorire il ritorno dei turisti e promuovere i prodotti e le produzioni locali in chiave esportativa. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 20 Giu 2024 &#8211; Nel 2023 nelle strutture ricettive alberghiere ed extra-alberghiere della Sardegna si sono registrate\u00a015,7 milioni di presenze: una\u00a0crescita del +6,5% rispetto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":187727,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/248953"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=248953"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/248953\/revisions"}],"predecessor-version":[{"id":248954,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/248953\/revisions\/248954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/187727"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=248953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=248953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=248953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}