{"id":227074,"date":"2022-09-23T10:03:53","date_gmt":"2022-09-23T08:03:53","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=227074"},"modified":"2022-09-23T10:03:55","modified_gmt":"2022-09-23T08:03:55","slug":"carabinieri-del-nas-di-cagliari-sequestrano-in-una-enoteca-della-citta-circa-130-bottiglie-di-vini-sardi","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2022\/09\/23\/carabinieri-del-nas-di-cagliari-sequestrano-in-una-enoteca-della-citta-circa-130-bottiglie-di-vini-sardi\/","title":{"rendered":"Carabinieri del Nas di Cagliari sequestrano in una enoteca della citt\u00e0 circa 130 bottiglie di vini sardi"},"content":{"rendered":"\n<p>Cagliari, 23 Sett 2022 - Ieri a Cagliari i carabinieri del Nas del capoluogo, operando nell'ambito del settore mensile d\u2019interesse, relativo per settembre all'ambito vitivinicolo, in collaborazione coi colleghi della locale Stazione di Stampace, hanno ispezionato un\u2019enoteca di cui \u00e8 titolare un cagliaritano.<\/p>\n\n\n\n<p>A seguito delle verifiche compiute hanno riscontrato che il proprietario era incorso in irregolarit\u00e0 tali da doversi procedere al blocco di alcuni prodotti, poich\u00e9 posti in vendita senza la necessaria indicazione del lotto di produzione, utile per la rintracciabilit\u00e0 di prodotti che possano manifestare problematiche di qualunque genere.<\/p>\n\n\n\n<p>Quindi sono state fermate 26 bottiglie da 0,75 litri ciascuna di un vino rosso prodotto a Mamoiada, nonch\u00e9 108 bottiglie di Vermentino di Gallura prodotto e confezionato a Monti.<\/p>\n\n\n\n<p>Il valore dei prodotti bloccati ammonta a oltre 1.300 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 23 Sett 2022 &#8211; Ieri a Cagliari i carabinieri del Nas del capoluogo, operando nell&#8217;ambito del settore mensile d\u2019interesse, relativo per settembre all&#8217;ambito vitivinicolo,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":227075,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/227074"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=227074"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/227074\/revisions"}],"predecessor-version":[{"id":227076,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/227074\/revisions\/227076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/227075"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=227074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=227074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=227074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}