{"id":225801,"date":"2022-08-18T09:16:06","date_gmt":"2022-08-18T07:16:06","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=225801"},"modified":"2022-08-18T09:16:08","modified_gmt":"2022-08-18T07:16:08","slug":"vele-stracciate-e-motore-fuori-uso-spavento-nel-tardo-pomeriggio-nel-canale-di-s-pietro-soccorse-otto-persone-dalla-guardia-costiera-di-carloforte","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2022\/08\/18\/vele-stracciate-e-motore-fuori-uso-spavento-nel-tardo-pomeriggio-nel-canale-di-s-pietro-soccorse-otto-persone-dalla-guardia-costiera-di-carloforte\/","title":{"rendered":"Vele stracciate e motore fuori uso: spavento nel tardo pomeriggio nel Canale di S. Pietro. Soccorse otto persone dalla Guardia Costiera di Carloforte."},"content":{"rendered":"\n<p>Carloforte (Su), 18 Ago 2022 - \u201cUna barca a vela con difficolt\u00e0 di manovra, alla deriva, in vicinanza di scogli, nei pressi del tratto di mare antistante la localit\u00e0 Porto Sciusciau del Comune di Sant\u2019Antioco\u201d, dove gli otto occupanti (di origine francese) della barca a vela di circa 12 metri, hanno lanciato sul canale V.H.F. 16 la richiesta di soccorso a seguito di un\u2019avaria al motore e dopo essersi visti privati delle vele, stracciatesi, presumibilmente, a causa delle forti raffiche di vento insistenti in zona.<\/p>\n\n\n\n<p>Quindi per acquisire pi\u00f9 specifiche informazioni per indirizzare al meglio le attivit\u00e0 di ricerca e soccorso e, soprattutto, conoscere lo stato di salute degli occupanti la barca - per eventuali richieste di intervento da parte del 118 -, il personale in servizio presso la sala operativa dell\u2019Ufficio Circondariale Marittimo di Carloforte ha proceduto, senza ritardo, a contattare il conduttore dell\u2019unit\u00e0 da diporto in difficolt\u00e0.<\/p>\n\n\n\n<p>Pertanto accertate le buone condizioni degli otto diportisti e dopo aver individuato la posizione della barca a vela, veniva inviata in zona a motovedetta di \u201cricerca e soccorso\u201d CP869, in uso a Circomare Carloforte che una&nbsp; volta raggiunta l\u2019area d\u2019intervento, la motovedetta della Guardia Costiera ha avviato le operazioni di assistenza all\u2019unit\u00e0 da diporto, protrattesi sin dopo al tramonto, procedendo, successivamente, a scortarla in sicurezza presso il porto di Carloforte per le verifiche e gli accertamenti di rito inerenti all\u2019evento occorso.<\/p>\n\n\n\n<p>Ancora una volta, una situazione di pericolo, fortunatamente sventata e presumibilmente generata dalla non approfondita conoscenza della tratta di navigazione e da una mancata preventiva informazione da parte del conduttore dell\u2019unit\u00e0 sulle vigenti ordinanze e divieti locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carloforte (Su), 18 Ago 2022 &#8211; \u201cUna barca a vela con difficolt\u00e0 di manovra, alla deriva, in vicinanza di scogli, nei pressi del tratto di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":225802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/225801"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=225801"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/225801\/revisions"}],"predecessor-version":[{"id":225803,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/225801\/revisions\/225803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/225802"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=225801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=225801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=225801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}