{"id":206414,"date":"2021-05-12T07:15:29","date_gmt":"2021-05-12T05:15:29","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=206414"},"modified":"2021-05-12T07:15:31","modified_gmt":"2021-05-12T05:15:31","slug":"razzi-raid-e-decine-di-morti-e-guerra-tra-israele-e-hamas","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/05\/12\/razzi-raid-e-decine-di-morti-e-guerra-tra-israele-e-hamas\/","title":{"rendered":"Razzi, raid e decine di morti: \u00e8 guerra tra Israele e Hamas."},"content":{"rendered":"\n<p>Cagliari, 12 Magg 2021 - Divampa la guerra tra Israele e Hamas, con lo Stato ebraico deciso a proseguire \"senza limiti di tempo\" un conflitto \"esteso\". Alla pioggia di razzi arrivati da Gaza - oltre 500, di cui 200 intercettati e 150 esplosi nella Striscia - l'esercito ha risposto con decine e decine di attacchi contro obiettivi di Hamas e della Jihad islamica.\u00a0Due dirigenti militari sono stati uccisi stamani: il comandante della brigata di Hamas a Khan Yunes,\u00a0Hasan\u00a0Salama, e il capo dell'Intelligence Abu\u00a0Muhammad\u00a0al-Hasan al-Yazuri. In un attacco precedente gli obiettivi erano altri dirigenti di Hamas, Hassan Kaoggi e Wail Issa. Netanyahu: continueremo a colpire.<\/p>\n\n\n\n<p>\"Continueremo ad attaccare Gaza con tutta la forza\", ha detto il premier israeliano Benjamin Netanyahu. \"Hamas e la Jihad islamica pagheranno un prezzo molto pesante per la loro belligeranza\".&nbsp;Israele ha nel mirino \"molti altri obiettivi\" da colpire a Gaza, ha detto il ministro della Difesa Benny Gantz, che ha preso la parola dopo Netanyahu.&nbsp;Idf (l'esercito di Israele) avverte i palestinesi di stare al sicuro lontano dai siti di Hamas.<\/p>\n\n\n\n<p>Le forze militari israeliane hanno distrutto un altro edificio a Gaza City. Si tratta dell'al-Jawharah. Lo riporta il Times of Israel. Hamas e la Jihad islamica hanno ripetutamente minacciato nuovi lanci di razzi contro Tel Aviv nel caso di ulteriori attacchi agli edifici della Striscia.<\/p>\n\n\n\n<p>Un razzo sparato da Gaza da Hamas ha centrato una delle infrastrutture strategiche pi\u00f9 importanti di Ashkelon: la pipeline del 'Red-Med Land Bridge' che collega il Mediterraneo al porto di Eilat sul Mar Rosso. Immagini televisive mostrano un furioso incendio ancora in corso.<\/p>\n\n\n\n<p>Violenti incidenti si stanno verificando a Lod e a Ramle, cittadine miste nel centro di Israele, con sinagoghe, negozi e auto date alle fiamme da parte di dimostranti arabi. Lo riferiscono i media israeliani. In particolare, secondo la tv Canale 12, sono 3 le sinagoghe incendiate a Lod e molte le auto. La stessa fonte ha riferito che la polizia sta scortando alcuni \"residenti ebrei terrorizzati\" via dalle loro case.&nbsp;<\/p>\n\n\n\n<p>\"Questa \u00e8 la Notte dei Cristalli a Lod\". Cos\u00ec il sindaco Yair Revivo - evocando i pogrom contro gli ebrei nella Germania nazista del 1938 - ha definito quanto sta accadendo nella cittadina al centro di Israele. Revivo - che ha chiesto al premier Benjamin Netanyhau di dichiarare \"lo stato di emergenza nella citt\u00e0\" - ha detto che \u00e8 necessario l'intervento dell'esercito.&nbsp;\"Qui c'\u00e8 una mancanza del governo - ha aggiunto - E' un fatto gigantesco: una Intifada degli arabi israeliani. Sono bruciate le sinagoghe, come centinaia di auto. Centinaia di teppisti arabi stanno percorrendo le strade. E' scoppiata la guerra civile\".<\/p>\n\n\n\n<p>\"Bisogna porre fine alle deplorevoli morti di civili\": \u00e8 l'appello lanciato a israeliani e palestinesi dall'amministrazione Biden, preoccupata per l'escalation tra le due parti in Medio Oriente.<\/p>\n\n\n\n<p>\"Il nostro obiettivo principale\" \u00e8 la de-escalation\", Biden sostiene il \"diritto legittimo di Israele di difendere se stesso e il suo popolo\" e allo stesso tempo condanna gli \"attacchi missilistici in corso da parte di Hamas e di altri gruppi terroristici, anche contro Gerusalemme\". Cos\u00ec la portavoce della Casa Bianca, Jen Psaki, sulla posizione del presidente Joe Biden in relazione al conflitto in corso fra Israele e palestinesi. L'amministrazione Biden \"continuer\u00e0 anche a sostenere una soluzione a due Stati al conflitto israelo-palestinese\", \"\u00e8 l'unico modo per garantire la pace giusta e duratura che due popoli hanno lottato per raggiungere\".<\/p>\n\n\n\n<p>Dopo la temporanea chiusura a causa del massiccio lancio di razzi su Tel Aviv, sono ripresi i voli sull'aeroporto internazionale Ben Gurion. Lo riportano i media israeliani. In precedenza il traffico aereo era stato sospeso, con i voli dirottati su Cipro.<\/p>\n\n\n\n<p>Da parte palestinese ci sono almeno 28 morti (anche \"10 bambini\", secondo le autorit\u00e0 di Gaza) e quasi 200 feriti, tra cui importanti comandanti delle fazioni armate palestinesi. In Israele - protetto dal sistema di intercettazione anti-missili Iron Dome - si contano invece tre&nbsp;vittime: due donne colpite da un razzo che ha centrato un edificio ad Ashkelon e un'altra a causa di un razzo su Holon, a Sud di Tel Aviv. I feriti sono molte decine, mentre l'intera popolazione del sud di Israele \u00e8 costretta nei rifugi. Un palestinese \u00e8 stato inoltre ucciso e un altro ferito in Cisgiordania dai colpi dei militari israeliani. Entrambi sono membri dei servizi di sicurezza palestinesi.<\/p>\n\n\n\n<p>Le sirene antiaeree hanno risuonato anche a Tel Aviv, obiettivo di una raffica di razzi lanciati dalla Striscia di Gaza. I sistemi di difesa anti-missile israeliani si sono attivati. Hamas ha dichiarato di aver lanciato un totale di 130 razzi, il suo attacco pi\u00f9 intenso finora, in risposta alla distruzione da parte di Israele di un grattacielo a Gaza City.&nbsp;Un razzo ha colpito la citt\u00e0 di Holon, a sud di Tel Aviv, uccidendo una donna e ferendo diverse persone. Lo hanno riferito fonti sanitarie citate dal Times of Israel.<\/p>\n\n\n\n<p>Dopo una giornata di escalation, Benjamin Netanyahu ha annunciato di aver deciso insieme all'apparato militare di \"accrescere ancora di pi\u00f9 la potenza e il ritmo degli attacchi\" di quella che \u00e8 stata chiamata Operazione Guardiani delle Mura.\"Hamas - ha minacciato il premier israeliano - ricever\u00e0 un colpo che non si aspetta\". Per questo sono stati richiamati 5mila riservisti e schierati a ridosso del confine con Gaza la Brigata Golani e i tank della 7\/a Brigata corazzata. \"Tutti i comandi - ha incalzato il capo di stato maggiore Aviv Kochavi - devono prepararsi ad un conflitto pi\u00f9 esteso senza limiti di tempo\".<\/p>\n\n\n\n<p>Nella Striscia \u00e8 tornata l'atmosfera cupa delle guerre del 2012 e del 2014, mentre Hamas e la Jihad hanno esaltato la loro Operazione Spada di Gerusalemme - con un chiaro riferimento agli scontri sulla Spianata delle Moschee - che ha visto la cittadina costiera di Ashdod colpita da una gragnuola di 40 razzi Grad. Su Ashkelon poi Hamas ha rivendicato il tiro dei muovi missili Sijeel, in grado a suo dire di evitare l'intercettamento dell'Iron Dome: \"\u00c8 una risposta - ha spiegato Hammed a-Rakeb, un dirigente di Hamas - ad attacchi lanciati in precedenza da Israele contro appartamenti dove si trovavano comandanti militari\". Non a caso, visto che come ammesso dallo stesso Netanyahu e da Kochavi Israele vuole colpire innanzi tutto l'elite di comando dei bracci militari delle fazioni palestinesi. Tra questi \u00e8 stato ucciso Iyad Fathi Faik Sharir, comandante delle unit\u00e0 anticarro di Hamas.<\/p>\n\n\n\n<p>Appare remota al momento una possibile tregua, mediata dall'Egitto: Israele ha seccamente smentito che sia questa l'ora. \"Scopo dell'operazione in corso - ha precisato il ministro della Difesa Benny Gantz - \u00e8 colpire Hamas duramente, indebolirla e farle rimpiangere la sua decisione di lanciare i razzi. Ogni bomba ha un indirizzo. Continueremo nelle prossime ore e giorni\". Nell'ultimo attacco sulla Striscia, lo Stato ebraico ha usato 80 velivoli e tra questi alcuni F-35.<\/p>\n\n\n\n<p>Commentatori e analisti prevedono che non finir\u00e0 presto: i fatti di Gerusalemme sono diventati il catalizzatore di una guerra che negli anni scorsi era stata pi\u00f9 volte sfiorata. Quei fatti hanno avuto un'altra conseguenza pesante per Israele: l'aperta insofferenza di una parte della societ\u00e0 arabo-israeliana. Incidenti gravi sono avvenuti in molte cittadine a popolazione mista. Soprattutto a Lod, dove dimostranti arabi hanno attaccato residenti ebrei in alcuni rioni della citt\u00e0. Due dimostranti sono stati feriti da colpi di arma da fuoco e uno di essi \u00e8 deceduto poco dopo. Secondo i media, a sparare \u00e8 stato un ebreo che temeva il linciaggio da parte dei manifestanti che avevano gi\u00e0 attaccato un commissariato di polizia, un museo e un collegio rabbinico. Scontri si sono verificati anche a Ramle e di nuovo a Lod. \"Gli arabi israeliani - ha attaccato Netanyahu - si sono comportati in maniera selvaggia e non accettiamo questo comportamento da scalmanati\". Anche il presidente Reuven Rivlin ha trattato con durezza il capo delle Comunit\u00e0 arabe ammonendo che \"ebrei e arabi di Israele non devono diventare ostaggio dei terroristi assassini di Hamas e Jihad\". Difficile che in questa situazione i ripetuti appelli della comunit\u00e0 internazionale alla de-escalation possano trovare ascolto.<\/p>\n\n\n\n<p>Per gli abitanti di Gaza vigilia fra le bombe della festa dell'Id el-Fitr, che da gioved\u00ec concluder\u00e0 il Ramadan. Come in passato si sono affollati anche oggi nei mercati per gli ultimi acquisti di cibi speciali, di leccornie e abiti nuovi per i bambini. Ma l'atmosfera \u00e8 gravida di preoccupazione. Da ogni bancarella spuntano radio e televisioni accese che trasmettono in diretta gli ultimi aggiornamenti. Gli echi dei combattimenti sono peraltro perfettamente udibili anche senza apparecchiature speciali. In cielo volteggiano con insistenza i droni militari di Israele, e di quando in quando si sentono anche i fragorosi lanci di razzi sparati verso lo Stato ebraico dalle milizie locali.<\/p>\n\n\n\n<p>Agli adulti basta guardarsi negli occhi per tornare con il pensiero ad un altro sofferto Ramadan, quello del 2014, dell'operazione 'Margine Protettivo', per ricordare le vittime di allora. In molti quelle ferite si sono oggi riaperte, i traumi mai affrontati clinicamente si sono ripresentati. Secondo gli psicologi, ancora oggi essi provocano sofferenze estese, ad esempio per quanto riguarda le violenze familiari.<\/p>\n\n\n\n<p>E fra le bancarelle, nella coreografia colorata e vivace del mercato ortofrutticolo, gli animi si accendono. La domanda del giorno \u00e8 se fosse necessario per Hamas tornare a sfidare la macchina bellica di Israele, dopo le tre dolorose campagne degli ultimi anni. Molti sostengono che in effetti non era possibile restare insensibili al grido di dolore giunto dai fedeli islamici travolti dalla polizia israeliana sulla Spianata delle Moschee di Gerusalemme nel Lailyat al-Khader, la notte del destino. \"S\u00ec - replicano altri -, ma la risposta poteva essere diversa. Ad esempio con una lotta popolare contro la occupazione. Quel tipo di lotta - argomentano - porta frutti&nbsp;politici. I missili invece portano solo distruzione\".<\/p>\n\n\n\n<p>Passeggiando per il centro di Gaza si nota un forte contrasto fra gli addobbi per la festa imminente ed il clima di mestizia dopo che nelle prime fasi del conflitto (le milizie lo hanno chiamato 'Spada di Gerusalemme') un'intera famiglia \u00e8 stata distrutta ieri da un'esplosione a Beit Hanun, nel nord della Striscia. E mentre passano i primi cortei funebri, la guerra si manifesta in tutta la sua crudezza nelle stesse strade di Gaza City. Nel rione residenziale di Rimal un appartamento in un grande condominio \u00e8 devastato da un razzo israeliano. In seguito si apprender\u00e0 che all'interno c'erano tre responsabili militari della Jihad islamica, rimasti uccisi. E un'ora dopo nel rione popolare di Sajaya, a est di Gaza, un'automobile in transito \u00e8 centrata da un altro razzo. La strada in quel momento \u00e8 affollata. Si contano sette feriti, fra i passeggeri (di identit\u00e0 ignota) e i curiosi, che erano nelle immediate vicinanze. Festa e morte: proprio come nel Ramadan del 2014.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 12 Magg 2021 &#8211; Divampa la guerra tra Israele e Hamas, con lo Stato ebraico deciso a proseguire &#8220;senza limiti di tempo&#8221; un conflitto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":206415,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/206414"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=206414"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/206414\/revisions"}],"predecessor-version":[{"id":206416,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/206414\/revisions\/206416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/206415"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=206414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=206414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=206414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}