{"id":206399,"date":"2021-05-11T17:47:38","date_gmt":"2021-05-11T15:47:38","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=206399"},"modified":"2021-05-11T17:47:39","modified_gmt":"2021-05-11T15:47:39","slug":"coronavirus-in-italia-6-946-nuovi-casi-con-286-428-tamponi-e-251-vittime","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/05\/11\/coronavirus-in-italia-6-946-nuovi-casi-con-286-428-tamponi-e-251-vittime\/","title":{"rendered":"Coronavirus in Italia: 6.946 nuovi casi con 286.428 tamponi e 251 vittime."},"content":{"rendered":"\n<p>Roma, 11 Magg 2021 - La situazione in Italia della pandemia, con i dati del ministero della salute.\u00a0Oggi si registrano 6.946 nuovi casi con 286.428 tamponi e 251 vittime. Ieri\u00a05.080 casi con 130mila tamponi (indice al 3,9%) e 198 morti.<\/p>\n\n\n\n<p>In calo di 9.811 casi gli attualmente positivi in Italia, che complessivamente sono 363.859. Aumentano di&nbsp;16.503&nbsp;i dimessi e guariti nelle ultime 24 ore; il dato nazionale \u00e8&nbsp;3.636.089. I deceduti sono&nbsp;123.282&nbsp;in Italia e i casi totali&nbsp;4.123.230.<\/p>\n\n\n\n<p>Sono 1.109 i tamponi risultati positivi al coronavirus su 16.351 tamponi molecolari analizzati ieri in Campania. Nel bollettino odierno diffuso dall'unit\u00e0 di crisi della Regione Campania, aggiornato alla scorsa mezzanotte, sono inseriti 29 nuovi decessi, 18 dei quali avvenuti nelle ultime 48 ore e 11 in precedenza, ma registrati ieri. Sono 6.719 i decessi registrati in Campania dall'inizio della pandemia da Covid-19. I nuovi guariti sono 2.390, il totale dei guariti \u00e8 316.423. In Campania sono 111 i pazienti Covid ricoverati in terapia intensiva, 1.353 i pazienti Covid ricoverati nei reparti di degenza.<\/p>\n\n\n\n<p>In Lombardia si registrano 788 nuovi contagi da ieri.<\/p>\n\n\n\n<p>Il presidente della Regione Puglia, Michele Emiliano sulla base delle informazioni del direttore del dipartimento Promozione della Salute Vito Montanaro, informa che oggi in Puglia, sono stati registrati 11.692 test per l'infezione da Covid-19 coronavirus e sono stati registrati 684 casi positivi. Sono stati registrati 24 decessi. Dall'inizio dell'emergenza sono stati effettuati 2.333.975 test. 194.784 sono i pazienti guariti. 42.682 sono i casi attualmente positivi. Il totale dei casi positivi Covid in Puglia \u00e8 di 243.618.<\/p>\n\n\n\n<p>\"Oggi su oltre 13.301 mila tamponi nel Lazio (+2251) e oltre 21 mila antigenici per un totale di quasi 25 mila test, si registrano 635 nuovi casi positivi (-45) (oggi numero pi\u00f9 basso di positivi negli ultimi sette mesi. Forte frenata nei contagi), 40 i decessi (+23). E +1.230 i guariti. Diminuiscono i casi, forte calo delle terapie intensive e calo dei ricoverati. Il rapporto tra positivi e tamponi \u00e8 a 4.7%, ma se consideriamo anche gli antigenici la percentuale scende al 2.4%. I casi a Roma citt\u00e0 sono a quota 406\". A dirlo l'assessore alla Sanit\u00e0 e l'Integrazione Sociosanitaria della Regione Lazio, Alessio D'Amato, al termine della videoconferenza della task-force regionale per il Covid-19 con i direttori generali delle Asl e Aziende ospedaliere, Policlinici universitari e l'ospedale Pediatrico Bambino Ges\u00f9.<\/p>\n\n\n\n<p>Oggi l'Unit\u00e0 di Crisi della Regione Piemonte ha comunicato 529 nuovi casi di persone risultate positive al Covid-19 (di cui 68 dopo test antigenico), pari al 2,7% di 19.905 tamponi eseguiti, di cui 10.959 antigenici. Dei 529 nuovi casi, gli asintomatici sono 250 (47,3%). Il totale dei casi positivi diventa quindi 356.888. I ricoverati in terapia intensiva sono 148 (-13 rispetto a ieri); i ricoverati non in terapia intensiva sono 1.658 (-22 rispetto a ieri). Le persone in isolamento domiciliare sono 10.880. Purtroppo si registrano anche 12 decessi.<\/p>\n\n\n\n<p>Contagi in calo in Emilia-Romagna, dove si registrano 456 nuovi contagi, su un totale di 25.380 tamponi eseguiti nelle ultime 24 ore. Per quanto riguarda le persone guarite, sono 2.945 in pi\u00f9 rispetto a ieri. Purtroppo, si registrano 12 nuovi decessi. In totale, dall'inizio dell'epidemia i decessi in regione sono stati 13.031. Tendenza al miglioramento anche nelle corsie ospedaliere: i pazienti ricoverati in terapia intensiva sono 186 (-1 rispetto a ieri), 1.294 quelli negli altri reparti Covid (-63).<\/p>\n\n\n\n<p>I dati del bollettino del Covid confermano la frenata della curva del virus nella in Veneto. Nelle ultime 24 ore ci sono stati 417 contagi, che portano il totale degli infetti dell'inizio dell'epidemia a 418.144, e 17 vittime, per un numero complessivo di 11.442. Si tratta di dati - dopo i 247 positivi di ieri - che non si registravano dal periodo precedente la seconda ondata. In calo progressivo anche i dati ospedalieri. I posti letto occupati da pazienti Covid sono oggi 1.158 (-13), dei quali 1.010 (-8) nei normali reparti medici, e 148 (-5) nelle terapie intensive. I soggetti attualmente positivi sono 18.278 (-758).<\/p>\n\n\n\n<p>In Toscana sono 234.097 i casi di positivit\u00e0 al coronavirus, 367 in pi\u00f9 rispetto a ieri. I guariti sono 211.216. Oggi sono stati eseguiti 9.906 tamponi molecolari e 12.007 tamponi antigenici rapidi. Gli attualmente positivi sono oggi 16.458. I ricoverati sono 1.263 (48 in meno rispetto a ieri), di cui 195 in terapia intensiva (10 in meno). Oggi si registrano 21 nuovi decessi: 14 uomini e 7 donne con un'et\u00e0 media di 80,7 anni. Questi i dati - accertati alle ore 12 di oggi sulla base delle richieste della Protezione Civile Nazionale - relativi all'andamento dell'epidemia in regione.<\/p>\n\n\n\n<p>Sono 237 in pi\u00f9, rispetto a ieri, le persone risultate positive al coronavirus in Calabria su 3.241 tamponi eseguiti. In Calabria finora sono stati sottoposti a test 747.367 soggetti per un totale di 810.139 tamponi eseguiti. Le persone risultate positive al coronavirus sono 63.355, quelle negative 684.012. Lo rende noto la Regione nel bollettino quotidiano dei dati relativi al Covid: dall'inizio dell'emergenza i decessi sono 1.092 (+8 rispetto a ieri), mentre i guariti sono 49.000 (+495 rispetto a ieri).<\/p>\n\n\n\n<p>Sono altri 72 i decessi di persone positive al coronavirus registrati in Liguria, secondo l'ultimo bollettino diffuso dalla Regione: tre di questi risalgono ad aprile. Sale a 4.252 il numero delle vittime da inizio emergenza. I pazienti Covid ricoverati nei nosocomi liguri sono 421,18 in meno di ieri. Di questi, 47 sono in terapia intensiva. Il report registra 128 nuovi positivi, a fronte di 4.224 tamponi molecolari effettuati nelle ultime 24 ore, ai quali si aggiungono altri 2.466 tamponi antigenici rapidi. Sul fronte vaccini, dei 772.800 consegnati, ne sono stati somministrati 728.815, ovvero il 94%.<\/p>\n\n\n\n<p>Salgono a 55.765 i casi di positivit\u00e0 al Covid-19 complessivamente accertati in Sardegna dall'inizio dell'emergenza: nell'ultimo aggiornamento dell'Unit\u00e0 di crisi regionale sono stati rilevati 83 nuovi contagi. In totale sono stati eseguiti 1.224.781 tamponi, di cui 5.776 nelle ultime 24 ore, per un tasso di positivit\u00e0 dell'1,4%.&nbsp;Si registrano anche quattro decessi (1.422 in tutto).&nbsp;Sono, invece, 274 (-14) le persone attualmente ricoverate in ospedale in reparti non intensivi, 40 (-1) i pazienti in terapia intensiva. Le persone in isolamento domiciliare sono 14.916 e i guariti sono complessivamente 39.113 (+324).<\/p>\n\n\n\n<p>In Abruzzo dall'inizio dell'emergenza sono complessivamente 72649 i casi positivi al Covid 19 registrati. Rispetto a ieri si registrano 79 nuovi casi. Il bilancio dei pazienti deceduti registra 9 nuovi casi e sale a 2447. Dei casi odierni, 2 sono riferiti a decessi avvenuti nei giorni scorsi e comunicati solo oggi dalle Asl. Nel numero dei casi positivi sono compresi anche 62531 dimessi\/guariti (+251 rispetto a ieri). Gli attualmente positivi in Abruzzo (calcolati sottraendo al totale dei positivi, il numero dei dimessi\/guariti e dei deceduti) sono 7671 (-181 rispetto a ieri)<\/p>\n\n\n\n<p>Oggi in Friuli Venezia Giulia su un totale di 5.946 test sono state riscontrate 70 positivit\u00e0 al Covid 19, pari all'1,17%. Nel dettaglio, dall'analisi di 3.499 tamponi molecolari sono stati rilevati 50 nuovi contagi con una percentuale di positivit\u00e0 dell'1,43%. Sono inoltre 2.447 i test rapidi antigenici realizzati, dai quali sono stati rilevati 20 casi (0,82%). Sono stati registrati 2 decessi. I ricoveri nelle terapie intensive sono 20 (-2), negli altri reparti sono 136 (-11). Lo comunica in una nota il vicegovernatore del Fvg con delega alla Salute, Riccardo Riccardi. I decessi complessivamente ammontano a 3.746. I totalmente guariti sono 90.645, i clinicamente guariti 5.564, mentre le persone in isolamento sono 6.082. Dall'inizio della pandemia in Friuli Venezia Giulia sono risultate positive complessivamente 106.193 persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 11 Magg 2021 &#8211; La situazione in Italia della pandemia, con i dati del ministero della salute.\u00a0Oggi si registrano 6.946 nuovi casi con 286.428&#8230;<\/p>\n","protected":false},"author":2,"featured_media":206199,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/206399"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=206399"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/206399\/revisions"}],"predecessor-version":[{"id":206400,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/206399\/revisions\/206400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/206199"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=206399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=206399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=206399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}