{"id":205620,"date":"2021-04-24T10:20:29","date_gmt":"2021-04-24T08:20:29","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=205620"},"modified":"2021-04-24T10:20:30","modified_gmt":"2021-04-24T08:20:30","slug":"piano-di-recupero-predisposto-da-draghi-allesame-del-cdm-convocato-alle-10","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/04\/24\/piano-di-recupero-predisposto-da-draghi-allesame-del-cdm-convocato-alle-10\/","title":{"rendered":"Piano di recupero, predisposto da Draghi all&#8217;esame del Cdm convocato alle 10."},"content":{"rendered":"\n<p>Roma, 24 Apr 2021 - Il Consiglio dei ministri chiamato a discutere il piano di recupero (Recovery Plan) \u00e8 stato convocato alle ore 10. Lo rende noto la presidenza del Consiglio.<\/p>\n\n\n\n<p>Il piano nazionale di ripresa da 221 miliardi arriva in consiglio dei ministri per un primo esame, poi il passaggio in Parlamento la settimana prossima prima dell'approvazione definitiva.<\/p>\n\n\n\n<p>Mario Draghi porta in Consiglio dei ministri un Piano nazionale di ripresa e resilienza da 221,5 miliardi totali, di cui 191,5 riferibili al fondo di recupero e 30 miliardi per finanziare le opere \"extra piano\". La spinta stimata alla crescita \u00e8 di 3 punti di Pil nel 2026.<\/p>\n\n\n\n<p>L'obiettivo \u00e8 non solo \"riparare i danni della pandemia\" ma affrontare anche \"debolezze strutturali\" dell'economia italiana. Il grosso del piano \u00e8 definito, con 135 linee di investimento. E l'impianto \"non cambier\u00e0\", sottolineano dal governo, di fronte alla mole di richieste che emerge in queste ore dai partiti.<\/p>\n\n\n\n<p>Un piano in 318 pagine con l'indicazione di obiettivi, missioni, priorit\u00e0 trasversali e riforme che lo accompagneranno: \u00e8 la bozza del piano di recupero taliano che dovrebbe arrivare oggi per un primo esame sul tavolo del Cdm.<\/p>\n\n\n\n<p>Il Piano \"comprende un ambizioso progetto di riforme\" con \"quattro importanti riforme di contesto \u2013 Pubblica Amministrazione, giustizia, semplificazione della legislazione e promozione della concorrenza\". Ci sono poi la \"modernizzazione del mercato del lavoro; il rafforzamento della concorrenza nel mercato dei prodotti e dei servizi\" e la riforma del fisco, anche in chiave ambientale.<\/p>\n\n\n\n<p>\"Il Pnrr \u00e8 parte di una pi\u00f9 ampia e ambiziosa strategia per l'ammodernamento del Paese. Il governo intende aggiornare e perfezionare le strategie nazionali in tema di sviluppo e mobilit\u00e0 sostenibile; ambiente e clima; idrogeno; automotive; filiera della salute. L'Italia deve combinare immaginazione e creativit\u00e0 a capacit\u00e0 progettuale e concretezza. Il governo vuole vincere questa sfida e consegnare alle prossime generazioni un Paese pi\u00f9 moderno, all'interno di un'Europa pi\u00f9 forte e solidale\". Lo scrive Mario Draghi nell'introduzione alPnrr, nella bozza in ingresso in Cdm su cui Il Foglio ha fatto oggi un ampio servizio.<\/p>\n\n\n\n<p>L'impatto sul Pil del Piano nazionale di ripresa e resilienza&nbsp;legato al piano sar\u00e0 nel 2026 \"di almeno 3,6 per cento pi\u00f9 alto rispetto all'andamento tendenziale\". Lo si legge nella premessa a firma di Mario Draghi alla bozza del Pnrr, in cui si specifica che l'effetto sull'occupazione sar\u00e0 di quasi 3 punti percentuali.<\/p>\n\n\n\n<p>\"La supervisione politica del piano \u00e8 affidata a un comitato istituito presso la Presidenza del Consiglio&nbsp;a cui partecipano i ministri competenti\". Lo scrive Mario Draghi nella premessa del bozza del Pnrr, illustrando la governance. C'\u00e8 \"una struttura di coordinamento centrale presso il ministero dell'Economia\" che \"supervisiona l'attuazione del piano ed \u00e8 responsabile dell'invio delle richieste di pagamento alla Commissione Ue\". La affiancano una struttura di valutazione e una di controllo. Le amministrazioni sono responsabili di singoli investimenti e riforme. Il governo costituir\u00e0 task force locali per aiutare le amministrazioni.<\/p>\n\n\n\n<p>Il nuovo Recovery Plan vede confermata la struttura in sei missioni e 16 componenti. Per Digitalizzazione, innovazione, competitivit\u00e0 e cultura&nbsp;sono previsti 42,55 miliardi (38,25 per nuovi progetti), per Rivoluzione verde e transizione ecologica&nbsp;57 (34,6), per Infrastrutture per mobilit\u00e0 sostenibile 25,33 (14,13), per Istruzione e ricerca 31,88 (24,1), per Inclusione e coesione 19,12, per Salute 15,63 (12,65). Cifre che portano al totale di 191,5 miliardi.<\/p>\n\n\n\n<p>Tra i fondi finanziati con le risorse Ue, salta l'intervento da circa 5 miliardi a sostegno dell'operazione cashback per favorire i pagamenti digitali. Trovano invece conferme le principali linee di intervento rispetto al vecchio piano. Come gli incentivi fiscali del piano Transizione 4.0 con 18,5 miliardi e la banda ultra larga che viene ulteriormente ampliata e portata a 5,3 miliardi di cui 4 per progetti nuovi.<\/p>\n\n\n\n<p>Nessun obbligo di rendiconto alla&nbsp;Commissione europea e scadenze pi\u00f9 lunghe, rispetto al 2026&nbsp;dell'orizzonte temporale del piano di recupero. \u00c8 questa una delle&nbsp;differenze tra il piano di investimenti del governo attraverso il&nbsp;fondo complementare al Pnrr e il Piano nazionale di ripresa e&nbsp;resilienza, indicata in una sintesi sulla bozza del piano di recupero.<\/p>\n\n\n\n<p>Due riforme strutturali - giustizia e&nbsp;Pubblica amministrazione - per realizzare le sei missioni in cui si&nbsp;articola il piano di recupero messo a punto dal governo italiano. Sul&nbsp;fronte della giustizia, in particolare, si mira a intervenire sulla&nbsp;\"bassa efficienza\" che passa dall'eccessiva durata dei processi e dal&nbsp;\"forte peso degli arretrati giudiziari\". Tra le \"riforme abilitanti\"&nbsp;da realizzare, \"le semplificazioni per la concessione di permessi e&nbsp;autorizzazioni\" nonch\u00e9 \"interventi sul codice degli appalti\". Tra le&nbsp;riforme \"settoriali specifiche\" vengono poi indicate \"nuove regole per&nbsp;la produzione di rinnovabili\" e \"interventi sul contratto di&nbsp;programma&nbsp;per le Ferrovie\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 24 Apr 2021 &#8211; Il Consiglio dei ministri chiamato a discutere il piano di recupero (Recovery Plan) \u00e8 stato convocato alle ore 10. Lo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":202278,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/205620"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=205620"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/205620\/revisions"}],"predecessor-version":[{"id":205621,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/205620\/revisions\/205621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/202278"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=205620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=205620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=205620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}