{"id":204989,"date":"2021-04-10T17:50:42","date_gmt":"2021-04-10T15:50:42","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=204989"},"modified":"2021-04-10T17:50:44","modified_gmt":"2021-04-10T15:50:44","slug":"coronavirus-in-italia-nelle-ultime-24-ore-sono-stati-registrati-17-567-nuovi-casi-con-320-892-tamponi-e-344-morti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/04\/10\/coronavirus-in-italia-nelle-ultime-24-ore-sono-stati-registrati-17-567-nuovi-casi-con-320-892-tamponi-e-344-morti\/","title":{"rendered":"Coronavirus: in Italia nelle ultime 24 ore sono stati registrati 17.567 nuovi casi con 320.892 tamponi e 344 morti."},"content":{"rendered":"\n<p>Roma, 10 Apr 2021 - I dati di oggi del ministero della Salute.\u00a0Oggi si registrano 17.567 nuovi casi con 320.892 tamponi e 344 vittime.\u00a0Ieri i casi erano stati 18.938, 460 le vittime e 362.973 i tamponi (tasso al 5,2%).<\/p>\n\n\n\n<p>I positivi attuali in Italia sono 533.085, in calo di 3.276 rispetto a ieri.&nbsp;Tra dimessi e guariti si contano 3.107.069 casi, c'\u00e8 un incremento di&nbsp;20.483 persone in confronto a ieri. Il bilancio delle vittime sale a&nbsp;113.923 da inizio pandemia e i casi totali sono&nbsp;3.754.077.<\/p>\n\n\n\n<p>La Lombardia \u00e8 la Regione dove si registrano pi\u00f9 casi, oggi sono 2.974 in pi\u00f9 rispetto a 24 ore fa. Segue la Campania con 2.069 casi.<\/p>\n\n\n\n<p>Nelle ultime 24 ore in Puglia sono stati registrati 13.461 test per l'infezione da Covid-19 coronavirus e sono stati rilevati 1.804 casi positivi, il 13,4% dei test (ieri era del 12,54%). Sono stati registrati 31 decessi (ieri erano stati 48). Dall'inizio dell'emergenza sono stati effettuati 1.991.105 test. 152.439 sono i pazienti guariti. 51.558 sono i casi attualmente positivi. Il totale dei casi positivi Covid in Puglia \u00e8 di 209.171, mentre le vittime dall'inizio dell'epidemia sono 5174,<\/p>\n\n\n\n<p>I nuovi contagi in Emilia-Romagna sono stati 1.525 nelle ultime 24 ore, mentre i morti sono stati 33. Aumentano i guariti e diminuiscono i ricoveri. Dall'inizio dell'epidemia da coronavirus, in regione si sono registrati 349.822 casi di positivit\u00e0. I tamponi eseguiti nelle ultime 24 ore sono stati 28.829 e la percentuale dei nuovi positivi sul numero di tamponi fatti da ieri \u00e8 del 5,3%. Sono alcuni dei dati forniti dal bollettino della Regione. I morti sono stati 33. In totale, dall'inizio dell'epidemia i decessi in regione sono stati 12.340.<\/p>\n\n\n\n<p>\"Oggi su oltre 18 mila tamponi nel Lazio (-474) e oltre 18 mila antigenici per un totale di oltre 37 mila test, si registrano 1.463 positivi (+100), 35 decessi (-12) e +980 guariti. Aumentano i casi e le terapie intensive, mentre diminuiscono i decessi e i ricoveri\". Cos\u00ec l'assessore regionale alla Sanit\u00e0, Alessio D'Amato. \"Il rapporto tra positivi e tamponi \u00e8 a 8%, ma se consideriamo anche gli antigenici la percentuale \u00e8 al 4% - aggiunge -. I casi a Roma citt\u00e0 sono a quota 700\".<\/p>\n\n\n\n<p>Piemonte Sono 22 i decessi di persone positive al test del Covid-19 comunicati dall'Unit\u00e0 di Crisi della Regione Piemonte, il totale \u00e8 ora di 10.647 deceduti risultati positivi al virus. Oggi l'Unit\u00e0 di Crisi della Regione Piemonte ha comunicato 1.267 nuovi casi di persone risultate positive al Covid-19 (di cui 124 dopo test antigenico), pari al 4,4% dei 28.927 tamponi eseguiti, di cui 19.183 antigenici. Dei 1.267 nuovi casi, gli asintomatici sono 534 (42,1%). 142 screening, 821 contatti di caso, 304 con indagine in corso; per ambito: 12 RSA\/Strutture Socio-Assistenziali, 85 scolastico, 1.170 popolazione generale. Il totale dei casi positivi diventa quindi 329.232. I restanti 2.407 sono in fase di elaborazione e attribuzione territoriale. I ricoverati in terapia intensiva sono 324 (- 5 rispetto a ieri). I ricoverati non in terapia intensiva sono 3.633 (- 73 rispetto a ieri). Le persone in isolamento domiciliare sono 24.716. I tamponi diagnostici finora processati sono 3.978.062 (+28.927 rispetto a ieri), di cui 1.406.015 risultati negativi.<\/p>\n\n\n\n<p>In Toscana sono 1.177 i nuovi casi di coronavirus rispetto a ieri (1.135 confermati con tampone molecolare e 42 da test rapido antigenico). I guariti crescono dello 0,8% e raggiungono quota 174.442 (83,9% dei casi totali). Secondo i dati - accertati alle ore 12 di oggi sulla base delle richieste della Protezione Civile Nazionale - relativi all'andamento dell'epidemia in regione. Oggi sono stati eseguiti 15.128 tamponi molecolari e 10.562 tamponi antigenici rapidi, di questi il 4,6% \u00e8 risultato positivo. Sono invece 8.968 i soggetti testati oggi (con tampone antigenico e\/o molecolare, escludendo i tamponi di controllo), di cui il 13,1% \u00e8 risultato positivo. Gli attualmente positivi sono oggi 27.912, -0,9% rispetto a ieri. I ricoverati sono 1.974 (14 in meno rispetto a ieri), di cui 286 in terapia intensiva (2 in pi\u00f9). Oggi si registrano 28 nuovi decessi: 13 uomini e 15 donne con un'et\u00e0 media di 79,4 anni.<\/p>\n\n\n\n<p>Leggera risalita rispetto a ieri della curva dei contagi da Coronavirus in Veneto: il bollettino regionale segnala 1.054 casi in pi\u00f9, con il totale a 394.336 da inizio pandemia. Si registrano anche 14 decessi, per un totale di 10.913 vittime. Continua la discesa delle persone attualmente positive, stamani 32.535, 383 in meno rispetto a ieri. Nei reparti ospedalieri scendono (-12) i ricoverati in area non critica, oggi 1.874, mentre risalgono (+2) quelli in terapia intensiva, con 310 posti occupati.<\/p>\n\n\n\n<p>Nel bollettino quotidiano Covid-19 della Regione Calabria sono 477 i nuovi positivi mentre si registrano altri 7 decessi.&nbsp;Non si arresta la crescita dei ricoveri da Covid in Calabria. Nelle ultime 24 ore ci sono stati 7 nuovi ingressi in area medica (472) con un tasso di occupazione dei posti letto che sale al 50%, 10 punti in pi\u00f9 della soglia di saturazione. Calano di uno, invece, i ricoverati in terapia intensiva (38) con un tasso di occupazione del 25%, 5 punti sotto il livello critico. Anche i nuovi positivi si mantengono su livelli alti (477) con un rapporto tamponi-positivi del 13,18%. Sette le vittime (in totale 897). Gli isolati a domicilio crescono di 356 (11.899) e 108 sono i nuovi guariti (37.782). I casi attivi salgono dai 12.047 di ieri ai 12.409 di oggi.<\/p>\n\n\n\n<p>In Sardegna aumentano i nuovi casi di Covid (+425), soprattutto nell'area metropolitana di Cagliari, i ricoveri in ospedale e le persone in isolamento domiciliare, in una giornata in cui l'ultimo aggiornamento dell'Unit\u00e0 di crisi regionale segnala anche altri due morti: sale cos\u00ec a 1.261 il numero delle vittime dall'inizio della pandemia nell'isola, mentre quello complessivo dei casi raggiunge quota 48.740. Le persone in isolamento domiciliare sono salite a 16.416, numeri simili a quelli dell'inverno scorso, mentre i ricoverati sono 323 in reparti non intensivi (+2) e 55 (+5) nelle terapie intensive. In totale sono stati eseguiti 1.063.256 tamponi, per un incremento complessivo di 5.804 test rispetto al dato precedente. I guariti sono 30.673 (+78), mentre le persone dichiarate guarite clinicamente sono 12. In Liguria 410 nuovi casi e 21 decessi Sono 410 i positivi al Covid-19 registrati nelle ultime 24 ore in Liguria, a fronte di 4.597 tamponi molecolari e 2.924 tamponi antigenici rapidi processati. I deceduti ammontano a 3.971, 21 in pi\u00f9 nelle ultime 24 ore. \u00c8 quanto emerge dal bollettino della Regione Liguria.<\/p>\n\n\n\n<p>In Friuli Venezia Giulia oggi su 6.505 tamponi molecolari sono stati rilevati 308 nuovi contagi con una percentuale di positivit\u00e0 del 4,73%. Sono inoltre 1.166 i test rapidi antigenici realizzati, dai quali sono stati rilevati 84 casi (7,20%). I decessi registrati sono 9, a cui se ne aggiungono 3 pregressi; i ricoveri nelle terapie scendono a 75, cos\u00ec come quelli negli altri reparti che calano a 516. Lo rende noto il vicegovernatore con delega alla Salute, Riccardo Riccardi. I decessi complessivamente ammontano a 3.494. I totalmente guariti sono 81.646, i clinicamente guariti 4.639, mentre le persone in isolamento scendono a 10.831. Dall'inizio della pandemia in Friuli Venezia Giulia sono risultate positive complessivamente 101.201 persone.<\/p>\n\n\n\n<p>Sono stati 152 i nuovi positivi al Covid registrati in Umbria nell'ultimo giorno a fronte di 311 guariti. Lo riporta il sito della Regione, dal quale emergono anche altri quattro morti. Ancora in calo gli attualmente positivi, ora 4.107, 163 in meno di venerd\u00ec.&nbsp; Sono stati analizzati 2.933 tamponi e 3.185 test antigenici. Il tasso di positivit\u00e0 \u00e8 del 2,48 per cento sul totale (ieri 3,24) e del 5,1 per cento sui soli molecolari (ieri 6,9).&nbsp;Sostanzialmente stabile il quadro dei ricoverati negli ospedali, 328, uno in meno di ieri, 43 dei quali (dato stabile) nelle terapie intensive.<\/p>\n\n\n\n<p>Altri 2 decessi da Covid-19 in Trentino secondo il rapporto quotidiano dell'Azienda provinciale per i servizi sanitari che d\u00e0 conto anche di 42 nuovi casi positivi al molecolare e 65 all'antigenico, mentre le vaccinazioni hanno superato ormai quota 115.000. Nel dettaglio, ieri sono stati analizzati 1.682 tamponi molecolari (1.213 all'Ospedale Santa Chiara e 469 alla Fem) che tra l'altro hanno confermato anche 28 positivit\u00e0 intercettate nei giorni scorsi dai test rapidi. Gli antigenici notificati all'Azienda sanitaria sono invece 1.245.<\/p>\n\n\n\n<p>In Alto Adige sono 87 i nuovi casi di Covid-19 emersi nella giornata di ieri su 10.442 tamponi processati. Una persona \u00e8 deceduta nelle ultime 24 ore per aver contratto il coronavirus. Il totale di vittime in provincia di Bolzano \u00e8 di 1.150. Le nuove positivit\u00e0 sono 53 su 950 tamponi molecolari esaminati e 34 su 9.492 test antigenici effettuati. Su 207.078 persone sottoposte a tampone molecolare, 46.172 sono risultate positive. Le persone con almeno un test antigenico positivo sono 24.877. La situazione negli ospedali altoatesini \u00e8 stabile: 76 sono i pazienti Covid ricoverati nei normali reparti (+4 rispetto a ieri), 23 quelli in terapia intensiva (-1 rispetto a ieri), 45 quelli ricoverati nelle strutture private convenzionate e 51 quelli in isolamento nelle due strutture appositamente allestite.<\/p>\n\n\n\n<p>Sono 78 i nuovi casi positivi registrati in Valle d'Aosta nelle ultime 24 ore. I casi attuali nella regione sono 1142, di questi 65 ricoverati e 12 in terapia intensiva. Nelle ultime 24 ore non viene segnalato nessun decesso. Il totale resta a 436 dall'inizio della pandemia in Valle d'Aosta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 10 Apr 2021 &#8211; I dati di oggi del ministero della Salute.\u00a0Oggi si registrano 17.567 nuovi casi con 320.892 tamponi e 344 vittime.\u00a0Ieri i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":204493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/204989"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=204989"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/204989\/revisions"}],"predecessor-version":[{"id":204990,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/204989\/revisions\/204990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/204493"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=204989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=204989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=204989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}