{"id":204845,"date":"2021-04-07T18:05:18","date_gmt":"2021-04-07T16:05:18","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=204845"},"modified":"2021-04-07T18:05:22","modified_gmt":"2021-04-07T16:05:22","slug":"coronavirus-in-italia-sono-stati-registrati-13-708-nuovi-casi-con-339-939-tamponi-e-ancora-una-infinita-di-vittime-627-vittime-in-sole-24-ore-e-lirresponsabile-salvini-vorrebbe-riaprire-tu","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/04\/07\/coronavirus-in-italia-sono-stati-registrati-13-708-nuovi-casi-con-339-939-tamponi-e-ancora-una-infinita-di-vittime-627-vittime-in-sole-24-ore-e-lirresponsabile-salvini-vorrebbe-riaprire-tu\/","title":{"rendered":"Coronavirus: in Italia sono stati registrati 13.708 nuovi casi con 339.939 tamponi e ancora una infinit\u00e0 di vittime: 627 vittime in sole 24 ore. E l\u2019irresponsabile Salvini vorrebbe riaprire tutto in queste condizioni."},"content":{"rendered":"\n<p>Roma, 7 Apr 2021 - I dati di oggi sulla pandemia in Italia, forniti dal Ministero della Salute.\u00a0Oggi si registrano 13.708 nuovi casi con 339.939 tamponi e 627 vittime.\u00a0Il tasso di positivit\u00e0 scende al 4% Ieri 7.767 casi con 112.962 tamponi (tasso al 6.9%) e 421 vittime.<\/p>\n\n\n\n<p>Gli attualmente positivi sono&nbsp;547.837 - in calo di&nbsp;7.868 casi rispetto a ieri - 514.838 dei quali si trovano in isolamento domiciliare,&nbsp;29.316 sono ricoverati con sintomi. In terapia intensiva sono ricoverate 3.683 persone: 276 gli ingressi nelle ultime 24 ore.&nbsp;Tra dimessi e guariti si contano 3.040.182 casi, c'\u00e8 un incremento di&nbsp;20.927 rispetto a 24 ore fa. Il bilancio totale delle vittime \u00e8 di&nbsp;112.374 da inizio pandemia. Il totale dei casi di contagiati dal Covid-19 in Italia \u00e8 di&nbsp;3.700.393.<\/p>\n\n\n\n<p>In Lombardia si registrano 2.569 nuovi contagi.<\/p>\n\n\n\n<p>Oggi l'Unit\u00e0 di crisi della Regione Piemonte ha comunicato 1.464 nuovi casi di persone risultate positive al Covid-19 (di cui 194 dopo test antigenico), pari al 6,1% dei 24.097 tamponi eseguiti, di cui 13.153 antigenici. Dei 1.464 nuovi casi, gli asintomatici sono 612 (41,8%). I ricoverati in terapia intensiva sono 357 (- 13 rispetto a ieri). I ricoverati non in terapia intensiva sono 3.889 (+7 rispetto a ieri). Le persone in isolamento domiciliare sono 27.276.&nbsp;Sono 79 i decessi di persone positive al test del Covid-19 comunicati dall'Unit\u00e0 di Crisi della Regione Piemonte, di cui 2 verificatisi oggi. I pazienti guariti sono complessivamente 282.424 (+2.651 rispetto a ieri).<\/p>\n\n\n\n<p>Sono 1.358 i nuovi positivi registrati in Campania su 14.520 tamponi molecolari effettuati. I casi sono divisi in 842 asintomatici e 516 sintomatici. A darne notizia l'Unit\u00e0 di crisi della Regione Campania che segnala anche l'effettuazione di 1.550 tamponi antigenici. Nel report sono indicati anche 66 decessi, 34 quelli nelle ultime 48 ore, e 2.087 guarigioni. Da inizio pandemia il numero dei deceduti si aggiorna quindi a 5.653, quello dei guariti a 252.199. Sul fronte dei posti letto da segnalare un calo dei degenti nelle terapie intensive: ieri erano 160 oggi 149. La disponibilit\u00e0 resta ferma a 656. Su 3.160 posti letto di degenza disponibili, tra Covid e offerta privata, ad esserne occupati sono 1.606, tre pi\u00f9 di ieri.<\/p>\n\n\n\n<p>In Veneto nel bollettino regionale. Il presidente Luca Zaia ha tuttavia attribuito il dato a un ritardo nella comunicazione dei dati negli ultimi giorni. Il totale dei morti dall'inizio della pandemia \u00e8 di 10.873. I nuovi casi registrati da ieri sono 1.111, con il totale a 391.053. Scendono gli attuali positivi, che sono 35.537 (-1.449). Prosegue la crescita dei dati clinici, con 1.972 ricoverati nei reparti non critici (+3) e 323 nelle terapie intensive (+8).<\/p>\n\n\n\n<p>Oggi su oltre 13 mila tamponi nel Lazio (+5.989) e oltre 23 mila antigenici per un totale di oltre 37 mila test, si registrano 1.081 casi positivi (-39), 47&nbsp;i decessi (+4) e +1.801 i guariti. Diminuiscono i casi e le terapie intensive, mentre aumentano i ricoveri e i decessi. Il rapporto tra positivi e tamponi \u00e8 a 8%, ma se consideriamo anche gli antigenici la percentuale \u00e8 al 2%. I casi a Roma citt\u00e0 sono a quota 500. Oggi aperte le prenotazioni per gli anni 65 e 64 (ovvero i nati nel 1956 e 1957). Tutto si sta svolgendo regolarmente e sono gi\u00e0 oltre 35 mila le prenotazioni effettuate. Primi segnali di discesa dei casi, oggi in calo rispetto a ieri (-39) e soprattutto rispetto a mercoled\u00ec della scorsa settimana (-719) e si riducono i tassi di occupazione delle terapie intensive.<\/p>\n\n\n\n<p>In Toscana sono 204.347 i casi di positivit\u00e0 al Coronavirus, 937 in pi\u00f9 rispetto a ieri (918 confermati con tampone molecolare e 19 da test rapido antigenico). I guariti raggiungono quota 170.444 (83,4% dei casi totali). Oggi sono stati eseguiti 11.971 tamponi molecolari e 15.298 tamponi antigenici rapidi. Gli attualmente positivi sono oggi 28.352. I ricoverati sono 1.999, di cui 275 in terapia intensiva (4 in meno). Oggi si registrano 41 nuovi decessi.<\/p>\n\n\n\n<p>Dall'inizio dell'epidemia di Coronavirus, in Emilia-Romagna si sono registrati 345.753 casi di positivit\u00e0, 576 in pi\u00f9 rispetto a ieri, su un totale di 31.860 tamponi eseguiti nelle ultime 24 ore. Purtroppo, si registrano 57 nuovi decessi. In totale, dall'inizio dell'epidemia i decessi in regione sono stati 12.246. In Calabria 292 nuovi casi e 8 decessi In Calabria ad oggi sono stati sottoposti a test 646.152 soggetti per un totale di 687.923 tamponi eseguiti. Le persone risultate positive al Coronavirus sono 49.596 (+292 rispetto a ieri), quelle negative 596.556. Sono questi i dati giornalieri relativi all'epidemia da Covid-19 comunicati dal dipartimento Tutela della Salute, che fanno registrare +2 terapie intensive, +337 guariti\/dimessi e altri 8 decessi.<\/p>\n\n\n\n<p>Scende il numero dei casi di Covid-19 in Friuli Venezia Giulia ma resta alto il dato sui decessi. Oggi si contano 166 nuovi contagi su 4.306 tamponi molecolari e 120 su 2.960 test rapidi antigenici realizzati. I decessi registrati sono 22, i ricoveri nelle terapie intensive scendono a 79, quelli in altri reparti sono 584, in isolamento si trovano 12.299 persone. A comunicare i dati il vicegovernatore con delega alla Salute, Riccardo Riccardi. Superata quota 100 mila contagi in regione dall'inizio della pandemia, 100.016. Le morti da Covid-19 ammontano a 3.424. I totalmente guariti sono 79.305, i clinicamente guariti 4.32.<\/p>\n\n\n\n<p>&nbsp;Sono 263 i nuovi casi di Coronavirus in Sardegna, 6.599 dei test in pi\u00f9 eseguiti, con un tasso di positivit\u00e0 di poco inferiore al 4%. Nelle ultime 24 ore si sono registrati 5 decessi. I pazienti attualmente ricoverati in ospedale sono 294 (-3), mentre restano 47 quelli in terapia intensiva. Le persone in isolamento domiciliare sono 15.649, 117 quelle in pi\u00f9 guarite. Dei 47.630 casi positivi complessivamente accertati, 12.121 (+76) sono stati rilevati nella Citt\u00e0 Metropolitana di Cagliari, 7.309 (+30) nel Sud Sardegna, 4.081 (+38) a Oristano, 9.375 (+48) a Nuoro, 14.744 (+71) a Sassari<\/p>\n\n\n\n<p>Aumentano i contagi da Coronavirus oggi in Abruzzo con 219 positivi in pi\u00f9, ieri erano appena 47. Il bilancio dei deceduti ne registra altre 13 vittime da Covid 19 (una in meno rispetto a ieri), nelle ultime ore, sale a 2.200 il loro numero. Gli attualmente positivi sono 10.397, 174 in meno rispetto a 24 ore fa. Il tasso di positivit\u00e0 \u00e8 pari a 2.5 per cento, ieri era al 3,2 per cento. Sono 66.878 i contagiati registrati dall'inizio dell'emergenza sanitaria. Tra i positivi sono compresi anche 54.281 guariti (379 in pi\u00f9 rispetto a ieri). Dall'inizio della pandemia sono stati eseguiti complessivamente 916.707 tamponi molecolari (5.277 in pi\u00f9 rispetto a ieri) e 363.953 test antigenici (3.299 rispetto a ieri). I posti letto occupati in area medica per malati Covid sono 592 (11 in meno rispetto a ieri). Nelle terapie intensive sono ricoverate 72 persone (2 in pi\u00f9 rispetto a ieri, con 6 nuovi ricoveri e 4 dimissioni). Altre 9.733 persone (165 in meno rispetto a 24 ore fa) sono in isolamento domiciliare con sorveglianza attiva da parte delle Asl.<\/p>\n\n\n\n<p>Altri 5 decessi per coronavirus in Trentino, secondo il bollettino odierno dell'Azienda provinciale per i servizi sanitari che riporta 103 nuovi casi di contagio. Nel dettaglio, 1.092 tamponi molecolari hanno individuato 38 nuovi casi positivi e confermato 68 positivit\u00e0 intercettate nei giorni scorsi dai test rapidi. Dai 1.215 tamponi rapidi antigenici notificati ieri all'Azienda sanitaria sono emersi invece 65 nuovi casi positivi. &nbsp;Negli ospedali i pazienti ricoverati sono 214, di cui 48 in rianimazione (5 in meno rispetto a ieri). Nella giornata di ieri sono stati registrati 11 nuovi ricoveri, ma le dimissioni sono state esattamente il doppio (22). Le nuove guarigioni sono 232. Degli oltre 107.000 vaccini finora somministrati, 35.616 si riferiscono a seconde dosi, 48.065 alle somministrazioni a favore di ultra ottantenni e 15.195 riferite alla fascia 70-79 anni.<\/p>\n\n\n\n<p>Nelle ultime 24 ore in Valle d'Aosta sono stati rilevati 61 nuovi casi positivi al Covid-19 a fronte di 407 persone sottoposte a tampone. Ci sono stati due decessi, un uomo e una donna. Continua anche a crescere il numero di pazienti ricoverati all'ospedale Parini: sono 72, di cui 13 in terapia intensiva. Il totale dei contagiati sale a 1.173, 24 in meno di ieri. E' quanto si legge nel bollettino della Regione sulla base dei dati forniti dall'Usl. I guariti sono 83.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 7 Apr 2021 &#8211; I dati di oggi sulla pandemia in Italia, forniti dal Ministero della Salute.\u00a0Oggi si registrano 13.708 nuovi casi con 339.939&#8230;<\/p>\n","protected":false},"author":2,"featured_media":204396,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/204845"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=204845"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/204845\/revisions"}],"predecessor-version":[{"id":204846,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/204845\/revisions\/204846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/204396"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=204845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=204845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=204845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}