{"id":201905,"date":"2021-02-05T10:17:05","date_gmt":"2021-02-05T09:17:05","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201905"},"modified":"2021-02-05T10:17:07","modified_gmt":"2021-02-05T09:17:07","slug":"guardia-di-finanza-cagliari-sequestrati-oltre-3-000-ricci-di-mare-paracentrotus-lividus-immessi-illegalmente-sul-mercato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/02\/05\/guardia-di-finanza-cagliari-sequestrati-oltre-3-000-ricci-di-mare-paracentrotus-lividus-immessi-illegalmente-sul-mercato\/","title":{"rendered":"Guardia di Finanza Cagliari: sequestrati oltre 3.000 ricci di mare (Paracentrotus Lividus) immessi illegalmente sul mercato."},"content":{"rendered":"\n<p>Cagliari, 5 Gen 2021 - Nell\u2019ambito di un\u2019articolata attivit\u00e0 di servizio finalizzata alla verifica del rispetto della normativa in materia di etichettatura e tracciabilit\u00e0 dei prodotti derivanti dalla pesca, nonch\u00e9 della salute dei consumatori, i finanzieri della Stazione Navale Cagliar hanno sequestrato, lungo il litorale Poetto, nei comuni di Cagliari e di Quartu Sant\u2019Elena, oltre 3.000 ricci di mare (Paracentrotus Lividus) messi in vendita da pescatori abusivi.<\/p>\n\n\n\n<p>Dai controlli effettuati alle attivit\u00e0 illecite, \u00e8 emerso la totale assenza sia dei documenti commerciali obbligatori che dell\u2019etichettatura attestanti la rintracciabilit\u00e0 e tracciabilit\u00e0 dei prodotti ittici. Il primo \u00e8 obbligatorio ai fini fiscali mentre il secondo \u00e8 rilasciato da un Centro di Spedizione abilitato. Quest\u2019ultimo, \u00e8 la vera \u201ccarta d\u2019identit\u00e0\u201d che dimostra il percorso compiuto dal pescato, a partire dal momento della cattura fino al consumo finale. Quindi vista l\u2019illecita provenienza, le Fiamme Gialle hanno sottoposto a sequestrato amministrativo dei ricci, ovvero sei grandi ceste, equivalenti ad oltre 3.000 esemplari che, ancora vivi, venivano immediatamente rigettati nelle acque del Golfo di Cagliari.<\/p>\n\n\n\n<p>In seguito, nei confronti dei tre responsabili sono stati sanzionati per le violazioni alla normativa nazionale ricettrice dei Regolamenti Comunitari in materia di pesca che, per le specifiche violazioni, sono previste multe comprese tra i 750 ei 4.500 euro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2021\/02\/FOTO2_ROAN_CA_SEQ_RICCI.jpg\" alt=\"\" class=\"wp-image-201907\" width=\"732\" height=\"941\" srcset=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2021\/02\/FOTO2_ROAN_CA_SEQ_RICCI.jpg 600w, https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2021\/02\/FOTO2_ROAN_CA_SEQ_RICCI-233x300.jpg 233w\" sizes=\"(max-width: 732px) 100vw, 732px\" \/><\/figure>\n\n\n\n<p>L\u2019attivit\u00e0 posta in essere - sottolinea il Col. Alessandro Bucci, Comandante del Reparto Operativo Aeronavale di Cagliari \u2013 \u00e8 il risultato del dinamismo operativo degli uomini della Guardia di Finanza in Sardegna, sia in mare che sul territorio. Occorre innanzitutto tutelare la salute pubblica e, contestualmente, difendere gli onesti operatori che, con fatica, investono nelle loro piccole aziende, pagando regolarmente le tasse.<\/p>\n\n\n\n<p>Le Fiamme Gialle del comparto aeronavale oltre a svolgere le attivit\u00e0 d\u2019istituto in materia di polizia economico-finanziaria, sono impegnate a proteggere il delicato ecosistema marino, oggi pi\u00f9 delicato che mai, costantemente devastato dai pescatori abusivi e senza scrupoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 5 Gen 2021 &#8211; Nell\u2019ambito di un\u2019articolata attivit\u00e0 di servizio finalizzata alla verifica del rispetto della normativa in materia di etichettatura e tracciabilit\u00e0 dei&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201906,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201905"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201905"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201905\/revisions"}],"predecessor-version":[{"id":201908,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201905\/revisions\/201908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/201906"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}