{"id":201598,"date":"2021-01-30T10:01:01","date_gmt":"2021-01-30T09:01:01","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201598"},"modified":"2021-01-30T10:01:02","modified_gmt":"2021-01-30T09:01:02","slug":"un-27enne-di-san-giovanni-suergiu-deferito-alla-g-dai-carabinieri-della-stazione-di-gesico-per-aver-emesso-un-assegno-non-coperto","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/30\/un-27enne-di-san-giovanni-suergiu-deferito-alla-g-dai-carabinieri-della-stazione-di-gesico-per-aver-emesso-un-assegno-non-coperto\/","title":{"rendered":"Un 27enne di San Giovanni Suergiu deferito all\u2019A.G. dai carabinieri della Stazione di Gesico per aver emesso un assegno non coperto."},"content":{"rendered":"\n<p>Gesico (Ca), 30 Gen 2021 - Ieri a Gesico i carabinieri della locale Stazione, a conclusione di un\u2019attivit\u00e0 d\u2019indagine originata dalla querela presentata presso la vicina Stazione di Suelli il 28 ottobre 2020 da un 55enne di Barumini, hanno deferito in stato di libert\u00e0 alla Procura della Repubblica presso il Tribunale di Cagliari un 27enne di San Giovanni Suergiu, commerciante, con precedenti denunce a carico.<\/p>\n\n\n\n<p>I militari hanno ricostruito i vari passaggi della vicenda intercorsa fra i due protagonisti. Il denunciato il 2 ottobre scorso aveva venduto una Fiat Multipla al compratore per 750 euro, con contestuale scrittura privata. Successivamente l\u2019acquirente ha chiesto a Ferruccio un\u2019auto pi\u00f9 economica e quest\u2019ultimo, con l\u2019impegno di sostituirla con un\u2019altra meno costosa, si \u00e8 ripreso l\u2019auto gi\u00e0 venduta, lasciando al compratore un assegno bancario di 500 euro a titolo di garanzia, rendendosi poi irreperibile.<\/p>\n\n\n\n<p>Quindi la vittima, per limitare i danni, ha deciso quindi di versare l\u2019assegno per l\u2019incasso presso il Banco di Sardegna di Mandas, dove ha appreso, suo malgrado, che il titolo di credito era scoperto e non incassabile. In sostanza aveva speso 750 euro per non avere nulla in cambio.<\/p>\n\n\n\n<p>Per il disoccupato quella cifra \u00e8 assolutamente significativa ed \u00e8 verosimile che il commerciante dovr\u00e0 ora in qualche modo rimediare al danno, visto quanto documentato dai carabinieri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gesico (Ca), 30 Gen 2021 &#8211; Ieri a Gesico i carabinieri della locale Stazione, a conclusione di un\u2019attivit\u00e0 d\u2019indagine originata dalla querela presentata presso la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201599,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201598"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201598"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201598\/revisions"}],"predecessor-version":[{"id":201600,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201598\/revisions\/201600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/201599"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}