{"id":201538,"date":"2021-01-29T09:30:30","date_gmt":"2021-01-29T08:30:30","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201538"},"modified":"2021-01-29T09:30:36","modified_gmt":"2021-01-29T08:30:36","slug":"arresto-dagli-agenti-del-commissariato-di-p-s-di-olbia-un-37enne-olbiese-per-violenza-o-minaccia-resistenza-e-oltraggio-a-un-pubblico-ufficiale","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/29\/arresto-dagli-agenti-del-commissariato-di-p-s-di-olbia-un-37enne-olbiese-per-violenza-o-minaccia-resistenza-e-oltraggio-a-un-pubblico-ufficiale\/","title":{"rendered":"Arresto dagli agenti del Commissariato di P.S. di Olbia un 37enne olbiese, per violenza o minaccia, resistenza e oltraggio a un pubblico ufficiale."},"content":{"rendered":"\n<p>Olbia, 29 Gen 2021 - Nei giorni scorsi, personale della Polizia di Stato del Commissariato di Olbia ha arrestato un 37enne olbiese, per violenza o minaccia, resistenza e oltraggio a un pubblico ufficiale.<\/p>\n\n\n\n<p>Gli agenti a seguito di una chiamata giunta sulla linea \u201c113\u201d, sono intervenuti presso un esercizio pubblico presente in noto centro commerciale sito nella centralissima via Aldo Moro.<\/p>\n\n\n\n<p>Una volta arrivati sul posto, gli avventori del bar situato all\u2019interno del supermercato, impauriti, hanno indicato ai poliziotti, un giovane il quale in evidente stato di alterazione alcolica, creava disturbo a tutti i presenti e in particolare alla giovane barista.<\/p>\n\n\n\n<p>L\u2019uomo alla vista del personale della Polizia si \u00e8 scagliato violentemente contro di loro insultandoli, minacciandoli, cercando in ogni modo di arrivare al contatto fisico con calci e pugni.<\/p>\n\n\n\n<p>Nell\u2019occasione, gli agenti, per scongiurare il coinvolgimento degli altri presenti, contro i quali l\u2019esagitato si era pi\u00f9 colte scagliato, hanno bloccato ed immobilizzato l\u2019individuo.<\/p>\n\n\n\n<p>Il 37enne, che in passato si era gi\u00e0 reso protagonista per diversi episodi simili, \u00e8 stato dichiarato in arresto e quindi accompagnato in Commissariato e messo a disposizione dell\u2019Autorit\u00e0 Giudiziaria.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olbia, 29 Gen 2021 &#8211; Nei giorni scorsi, personale della Polizia di Stato del Commissariato di Olbia ha arrestato un 37enne olbiese, per violenza o&#8230;<\/p>\n","protected":false},"author":2,"featured_media":173629,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201538"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201538"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201538\/revisions"}],"predecessor-version":[{"id":201539,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201538\/revisions\/201539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/173629"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}