{"id":201469,"date":"2021-01-28T11:38:43","date_gmt":"2021-01-28T10:38:43","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201469"},"modified":"2021-01-28T11:38:45","modified_gmt":"2021-01-28T10:38:45","slug":"gli-agenti-della-squadra-mobile-di-sassari-eseguono-due-ordinanze-di-custodia-cautelare-in-carcere-nei-confronti-di-due-giovani-ladri","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/28\/gli-agenti-della-squadra-mobile-di-sassari-eseguono-due-ordinanze-di-custodia-cautelare-in-carcere-nei-confronti-di-due-giovani-ladri\/","title":{"rendered":"Gli agenti della Squadra Mobile di Sassari eseguono due ordinanze di custodia cautelare in carcere nei confronti di due giovani ladri."},"content":{"rendered":"\n<p>Sassari, 28 Gen 2021 \u2013 Il personale della Polizia di Stato della Questura di Sassari ha eseguito nelle scorse giornate, due ordinanze di custodia cautelare in carcere nei confronti di due giovani, un 21enne e un 28enne, responsabili di una serie di furti in citt\u00e0, ai danni di alcuni esercizi pubblici.<\/p>\n\n\n\n<p>In particolare il titolare di una farmacia, all\u2019inizio dell\u2019anno, aveva subito un furto all\u2019interno del suo esercizio, dove era stata sottratta una modesta somma di denaro. Ma grazie all\u2019impianto di videosorveglianza presente nella farmacia erano stati acquisiti importanti elementi investigativi.<\/p>\n\n\n\n<p>Analogamente, verso met\u00e0 mese, gli stessi fatti sono accaduti in un\u2019altra farmacia cittadina, ove le telecamere di sicurezza avevano registrato due ladri che s\u2019impossessavano di un cellulare e del denaro contenuto nella cassa. E anche qui grazie a tutto il materiale raccolto, il personale della Squadra Mobile della Questura di Sassari \u00e8 riuscito a risalire all\u2019identit\u00e0 degli autori, peraltro gi\u00e0 responsabili di fatti analoghi in passato, nonch\u00e9 il mezzo da loro utilizzato.<\/p>\n\n\n\n<p>Le indagini successive hanno permesso di localizzare l\u2019autovettura in questione, all\u2019interno della quale sono state rinvenute due borsette, vari attrezzi da scasso, i documenti di uno dei due sospettati e svariati gioielli, poi restituiti alla proprietaria che fatta intervenire in questura li aveva riconosciuti come suoi. Pertanto, gli agenti della Squadra Mobile, raccolti tutti gli indizi e trasmessa una informativa all\u2019Autorit\u00e0 Giudiziaria, hanno ottenuto l\u2019emissione, a carico dei due pluripregiudicati, definiti quali \u201cla banda delle Farmacie\u201d, di due provvedimenti di custodia cautelare in carcere, che sono stati gi\u00e0 eseguiti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sassari, 28 Gen 2021 \u2013 Il personale della Polizia di Stato della Questura di Sassari ha eseguito nelle scorse giornate, due ordinanze di custodia cautelare&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201470,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201469"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201469"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201469\/revisions"}],"predecessor-version":[{"id":201471,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201469\/revisions\/201471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/201470"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}