{"id":201444,"date":"2021-01-27T18:13:18","date_gmt":"2021-01-27T17:13:18","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201444"},"modified":"2021-01-27T18:13:20","modified_gmt":"2021-01-27T17:13:20","slug":"arriva-il-carcere-per-due-stranieri-residenti-a-sorso-nel-sassarese","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/27\/arriva-il-carcere-per-due-stranieri-residenti-a-sorso-nel-sassarese\/","title":{"rendered":"Arriva il carcere per due stranieri residenti a Sorso nel sassarese."},"content":{"rendered":"\n<p>Sorso (SS), 27 Gen 2021 - Questa mattina, i carabinieri della Stazione di Sorso, hanno dato esecuzione ad un decreto emesso dall\u2019ufficio di sorveglianza di Sassari nei confronti di un bosniaco di 45 anni, residente nel centro del sassarese, per un cumulo di pena per il compimento di reati di furto e ricettazione commessi dal condannato nelle province di Sassari e Cagliari tra l\u2019anno 2015 e l\u2019anno 2019.<\/p>\n\n\n\n<p>Dopo le formalit\u00e0 di rito, l\u2019uomo \u00e8 stato associato presso la casa circondariale di Sassari \u2013 Bancali.<\/p>\n\n\n\n<p>Nella stessa mattinata i carabinieri della stessa Stazione del paese, hanno dato esecuzione ad un altro decreto emesso dalla procura della repubblica presso il tribunale ordinario di Sassari \u2013 ufficio esecuzioni penali, nei confronti di un bracciante agricolo di origine rumena, 27enne, a seguito di una sentenza di condanna definitiva per vari reati contro il patrimonio, la persona ed in materia di armi, commessi dal condannato nel 2017 proprio nel paese di sorso.<\/p>\n\n\n\n<p>Anche lui \u00e8 stato associato presso la casa circondariale di Sassari \u2013 Bancali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorso (SS), 27 Gen 2021 &#8211; Questa mattina, i carabinieri della Stazione di Sorso, hanno dato esecuzione ad un decreto emesso dall\u2019ufficio di sorveglianza di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":179102,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201444"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201444"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201444\/revisions"}],"predecessor-version":[{"id":201445,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201444\/revisions\/201445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/179102"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}