{"id":201388,"date":"2021-01-27T09:31:06","date_gmt":"2021-01-27T08:31:06","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201388"},"modified":"2021-01-27T09:31:07","modified_gmt":"2021-01-27T08:31:07","slug":"una-donna-di-35-anni-di-assemini-deferito-in-stato-di-liberta-dai-carabinieri-della-stazione-di-assemini-per-guida-in-stato-di-ebbrezza","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/27\/una-donna-di-35-anni-di-assemini-deferito-in-stato-di-liberta-dai-carabinieri-della-stazione-di-assemini-per-guida-in-stato-di-ebbrezza\/","title":{"rendered":"Una donna di 35 anni di Assemini deferito in stato di libert\u00e0 dai carabinieri della Stazione di Assemini per guida in stato di ebbrezza."},"content":{"rendered":"\n<p>Assemini (Ca), 27 Gen 2021 - Questa mattina alle ore 02:00 circa, i carabinieri della Stazione di Assemini, al termine di alcuni accertamenti, hanno deferito in stato di libert\u00e0 per guida in stato di ebbrezza alcolica, una 35enne impiegata del luogo, incensurata.<\/p>\n\n\n\n<p>La donna, alle ore 00:50 circa, in via Coghe, \u00e8 stata fermata per un controllo mentre era alla guida della sua auto e subito dopo sottoposta a esame etilometrico che ha poi ha evidenziato un tasso alcolemico pari a 1,58 g\/l (primo accertamento) e 1,51 g\/l (secondo accertamento), livello triplo rispetto al massimo consentito.<\/p>\n\n\n\n<p>Quindi alla giovane donna \u00e8 stata ritirata la patente ed il veicolo \u00e8 stato sottoposto a sequestro amministrativo. Contestualmente le \u00e8 stata sanzionata per 400 euro, non avendo fornito valide giustificazioni circa propria presenza in loco, in orario vietato dalla normativa per il contenimento della pandemia in corso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assemini (Ca), 27 Gen 2021 &#8211; Questa mattina alle ore 02:00 circa, i carabinieri della Stazione di Assemini, al termine di alcuni accertamenti, hanno deferito&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201094,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201388"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201388"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201388\/revisions"}],"predecessor-version":[{"id":201389,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201388\/revisions\/201389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/201094"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}