{"id":201309,"date":"2021-01-26T09:50:53","date_gmt":"2021-01-26T08:50:53","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201309"},"modified":"2021-01-26T09:50:55","modified_gmt":"2021-01-26T08:50:55","slug":"un-operaio-di-ortacesus-denunciato-dai-carabinieri-della-compagnai-di-dolianova-per-inosservanza-di-un-provvedimento-della-g","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/26\/un-operaio-di-ortacesus-denunciato-dai-carabinieri-della-compagnai-di-dolianova-per-inosservanza-di-un-provvedimento-della-g\/","title":{"rendered":"Un operaio di Ortacesus denunciato dai carabinieri della compagnai di Dolianova per inosservanza di un provvedimento dell\u2019A.G."},"content":{"rendered":"\n<p>Dolianova (Ca), 26 Gen 2021 \u2013 Ieri i carabinieri della Stazione di San al termine di alcuni accertamenti hanno deferito in stato di libert\u00e0 alla Procura della Repubblica presso il Tribunale di Cagliari, per violazione di sigilli e inosservanza di un provvedimento dell\u2019autorit\u00e0 un 57enne operaio di Ortacesus.<\/p>\n\n\n\n<p>L\u2019uomo era stato fermato per un controllo a Ortacesus il 12 gennaio scorso mentre era alla guida della sua auto. In seguito dopo alcune verifiche si \u00e8 scoperto che la vettura che conduceva risultava essere stata posta sotto sequestro amministrativo da personale del Radiomobile della Compagnia di Dolianova, il 14 giugno 2019, per violazione del codice della strada. In pratica l\u2019uomo girava senza assicurazione e senza revisione. E a seguito di tale constatazione l\u2019autovettura \u00e8 stata posta nuovamente sotto sequestro amministrativo dai carabinieri e affidata a una depositeria giudiziaria convenzionata ai fini dell\u2019alienazione, mentre la patente di guida dell\u2019indisciplinato automobilista \u00e8 stata ritirata per la successiva revoca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dolianova (Ca), 26 Gen 2021 \u2013 Ieri i carabinieri della Stazione di San al termine di alcuni accertamenti hanno deferito in stato di libert\u00e0 alla&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201251,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201309"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201309"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201309\/revisions"}],"predecessor-version":[{"id":201310,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201309\/revisions\/201310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/201251"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}