{"id":201253,"date":"2021-01-25T11:45:19","date_gmt":"2021-01-25T10:45:19","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=201253"},"modified":"2021-01-25T11:45:20","modified_gmt":"2021-01-25T10:45:20","slug":"comune-di-cagliari-diritto-allo-studio-2019-emessi-i-mandati-di-pagamento-relativi-ai-bonifici-respinti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/25\/comune-di-cagliari-diritto-allo-studio-2019-emessi-i-mandati-di-pagamento-relativi-ai-bonifici-respinti\/","title":{"rendered":"Comune di Cagliari &#8211; Diritto allo Studio 2019: emessi i mandati di pagamento relativi ai bonifici respinti."},"content":{"rendered":"\n<p>Cagliari, 25 Gen 2021 - Sono stati emessi i mandati di pagamento relativi all'elenco dei bonifici respinti (pubblicato lo scorso 17 novembre 2020) per i contributi \u201cDiritto allo Studio 2019\u201d (Borse di Studio regionali Anno Scolastico 2018\/2019 e Buono Libri Anno Scolastico 2019\/2020).<\/p>\n\n\n\n<p>La modalit\u00e0 di pagamento \u00e8 quella richiesta dagli utenti in seguito alla pubblicazione dell'elenco dei bonifici precedentemente respinti.<\/p>\n\n\n\n<p>Per chi non avesse modificato la modalit\u00e0 di pagamento, \u00e8 stata disposto, d'ufficio, il pagamento per contanti presso uno degli sportelli del Banco di Sardegna.<\/p>\n\n\n\n<p>L'elenco, aggiornato dopo la notifica da parte del Banco di Sardegna di un altro bonifico respinto e pubblicato in allegato alla Determinazione n.8563 del 22\/12\/2020, \u00e8 composto da 44 reintroiti.<\/p>\n\n\n\n<p>Per il rispetto della privacy di chi ha fatto domanda di contributo, l'elenco non indica i nominativi degli utenti che vengono indicati in base al numero di protocollo dell'istanza presentata.<\/p>\n\n\n\n<p>Per ulteriori informazioni \u00e8 possibile contattare il Servizio Pubblica Istruzione inviando una mail all'indirizzo:<a href=\"javascript:webmail.View.mailto(%7bmailto:'pubblicaistruzione@comune.cagliari.it.',%20subject:%20''%7d)\">&nbsp;pubblicaistruzione@comune.cagliari.it.&nbsp;<\/a>\u00c8 disponibile anche il numero di telefono 070\/6776436 al quale, per\u00f2, non potranno rispondere gli operatori che si trovano in telelavoro. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 25 Gen 2021 &#8211; Sono stati emessi i mandati di pagamento relativi all&#8217;elenco dei bonifici respinti (pubblicato lo scorso 17 novembre 2020) per i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":132553,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201253"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=201253"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201253\/revisions"}],"predecessor-version":[{"id":201254,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/201253\/revisions\/201254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/132553"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=201253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=201253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=201253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}