{"id":200659,"date":"2021-01-12T16:23:07","date_gmt":"2021-01-12T15:23:07","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=200659"},"modified":"2021-01-12T16:23:08","modified_gmt":"2021-01-12T15:23:08","slug":"vaccinati-tutti-i-dipendenti-dellaou-di-sassari-in-una-settimana-si-sono-chiuse-le-somministrazioni-per-tutto-il-personale-aziendale-e-oggi-quelle-per-i-lavoratori-delle-ditte-esterne-che-la","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2021\/01\/12\/vaccinati-tutti-i-dipendenti-dellaou-di-sassari-in-una-settimana-si-sono-chiuse-le-somministrazioni-per-tutto-il-personale-aziendale-e-oggi-quelle-per-i-lavoratori-delle-ditte-esterne-che-la\/","title":{"rendered":"Vaccinati tutti i dipendenti dell\u2019Aou di Sassari: in una settimana si sono chiuse le somministrazioni per tutto il personale aziendale e oggi quelle per i lavoratori delle ditte esterne che lavorano in ospedale."},"content":{"rendered":"\n<p>Sassari 12 Gen 2021 \u2013 Si \u00e8 conclusa domenica la somministrazione della prima dose di vaccino al personale dipendente dell'Azienda ospedaliero universitaria di Sassari. Oggi, invece, si \u00e8 chiusa quella dei dipendenti delle ditte esterne che lavorano nelle strutture ospedaliere cittadine. A questi si aggiungono anche i medici specializzandi, gi\u00e0 vaccinati nei giorni scorsi, per un totale di oltre 3.600 persone.\u00a0<\/p>\n\n\n\n<p>La campagna di vaccinazione contro il Covid-19 \u00e8 iniziata in Aou il 4 gennaio scorso con la somministrazione del vaccino ai primi 140&nbsp;medici, infermieri, operatori socio sanitari dei reparti Covid dell'Azienda.<\/p>\n\n\n\n<p>Nell'arco di sette giorni, si \u00e8 conclusa la vaccinazione di tutti i dipendenti che hanno dato l\u2019adesione, che rappresenta il 99 per cento del totale.<\/p>\n\n\n\n<p>Le quattro equipe vaccinali, formate da un medico, due infermieri e un ausiliare hanno lavorato spedite, vaccinando una media di 400 persone al giorno, con punte che hanno superato anche i 500 operatori.&nbsp;<\/p>\n\n\n\n<p>\u00abSi tratta di un risultato importante \u2013&nbsp;commenta il commissario straordinario dell\u2019Aou di Sassari Antonio Spano&nbsp;\u2013 la vaccinazione era attesa da molti, con grande ansia. La risposta dei nostri operatori, ma anche dei nostri fornitori che lavorano all'interno dei nostri ospedali, \u00e8 stata elevatissima. Un gesto importante che mette in luce la volont\u00e0 di voler uscire da una situazione e un forte senso di responsabilit\u00e0.<\/p>\n\n\n\n<p>\u00abAbbiamo mantenuto gli impegni presi con la Regione Sardegna \u2013&nbsp;prosegue il commissario&nbsp;\u2013 di effettuare la vaccinazione, di tutto il personale dipendente e delle ditte esterne, nel minor tempo possibile.&nbsp;Ecco perch\u00e9 il nostro ringraziamento va al personale sanitario e amministrativo che si \u00e8 impegnato per il raggiungimento di questo obiettivo.&nbsp;Adesso replicheremo il sistema adottato per la somministrazione della seconda dose.<\/p>\n\n\n\n<p>In questa fase, secondo il commissario, la parola d'ordine \u00e8 non abbassare la guardia. \u00abSiamo ancora lontani dal poterci dire fuori da questo grande problema. La strada, tuttavia, \u00e8 quella corretta e, assieme alle buone prassi sull\u2019uso della mascherina, dei dispositivi di protezione e del distanziamento, garantir\u00e0 in tempi non troppo lunghi il risultato che tutti ci aspettiamo: tornare a una vita normale\u00bb,&nbsp;chiude Antonio Spano.&nbsp;<\/p>\n\n\n\n<p>La seconda fase inizier\u00e0 il&nbsp;21 gennaio, quando si comincer\u00e0 a somministrare la seconda dose del vaccino ai primi dieci operatori vaccinati il 31 dicembre quindi dal 25 gennaio tutti gli altri.<\/p>\n\n\n\n<p>In totale l'Aou di Sassari ha ricevuto, in tre consegne distinte, 7 confezioni da 195 flaconi per un totale di 1365, pari a 8.190 dosi utili per le due somministrazioni. 200 flaconi sono stati prestati all\u2019Ats Sardegna per le esigenze di vaccinazione.&nbsp;<\/p>\n\n\n\n<p>\u00abIl risultato ottenuto \u00e8 rilevante -&nbsp;affermano il dottor Antonello Serra direttore della Sorveglianza sanitaria e il professor Paolo Castiglia direttore di Igiene e controllo delle infezioni ospedaliere che hanno coordinato la campagna di vaccinazione&nbsp;- questo anche grazie all'investimento fatto dall'Azienda in termini di risorse umane impegnate. In una sola settimana siamo riusciti a vaccinare oltre 3.600 persone.<\/p>\n\n\n\n<p>\u00ab\u00c8 stato attivato un ambulatorio di vaccinazione protetta che ha permesso di somministrare il vaccino anche a soggetti che avevano patologie di rilievo. Una struttura complessa che ha visto attivare un laboratorio per la preparazione delle dosi, 4 ambulatori vaccinali e un centro di immissione dati collegato con il sistema regionale\u00bb, concludono.&nbsp; Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sassari 12 Gen 2021 \u2013 Si \u00e8 conclusa domenica la somministrazione della prima dose di vaccino al personale dipendente dell&#8217;Azienda ospedaliero universitaria di Sassari. Oggi,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200223,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/200659"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=200659"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/200659\/revisions"}],"predecessor-version":[{"id":200660,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/200659\/revisions\/200660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/200223"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=200659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=200659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=200659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}